{"id":251040,"date":"2025-11-05T11:50:00","date_gmt":"2025-11-05T10:50:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=251040"},"modified":"2025-11-05T12:01:42","modified_gmt":"2025-11-05T11:01:42","slug":"sventato-furto-di-rame-in-azienda","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/11\/05\/sventato-furto-di-rame-in-azienda\/","title":{"rendered":"SVENTATO FURTO DI RAME IN AZIENDA"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"584\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/11\/carabinieri-bandoliera-5-1024x584.jpg\" alt=\"\" class=\"wp-image-251043\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/11\/carabinieri-bandoliera-5-1024x584.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/11\/carabinieri-bandoliera-5-300x171.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/11\/carabinieri-bandoliera-5-768x438.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/11\/carabinieri-bandoliera-5.jpg 1217w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>(f.f.)_____________<\/p>\n\n\n\n<p>Nuovo episodio legato al traffico di rame nel Salento, ma questa volta il colpo \u00e8 stato bloccato prima che potesse essere portato a termine. Nella tarda serata del 3 novembre, un giovane di 22 anni originario di Casarano \u00e8 stato denunciato dai carabinieri dopo essere stato sorpreso con materiale in rame sottratto da una ditta situata nella zona industriale di Surano.<\/p>\n\n\n\n<p>Il tentativo di furto \u00e8 avvenuto all&#8217;interno dell\u2019azienda Elica Ferramenta, lungo la statale 275. L\u2019allarme \u00e8 scattato quando la centrale operativa dell\u2019istituto di vigilanza Cosmopol ha rilevato un\u2019anomalia e inviato una pattuglia sul posto. Il vigilante, giunto in pochi minuti, ha immediatamente constatato il danneggiamento di vari pozzetti esterni e l\u2019effrazione di una finestra dei locali interni.<\/p>\n\n\n\n<p>Poco prima dell\u2019ispezione, la guardia aveva notato un\u2019auto con i fari spenti ferma sul retro dell\u2019azienda, poi allontanatasi, fatto che ha subito insospettito l\u2019addetto alla sicurezza. Tornato a controllare l\u2019area, il vigilante ha ritrovato la stessa vettura parcheggiata a ridosso della struttura, con il conducente intento a caricare cavi e componenti in rame, parte dei quali erano gi\u00e0 stati deposti anche su una carriola nei pressi dell\u2019edificio.<\/p>\n\n\n\n<p>A quel punto, sono stati allertati i carabinieri della compagnia di Maglie, intervenuti rapidamente per bloccare l\u2019uomo e procedere all\u2019identificazione. Il 22enne, incensurato, non \u00e8 stato arrestato ma \u00e8 stato denunciato per ricettazione, non essendo stato colto materialmente nell\u2019atto di effrazione, ma trovato in possesso della refurtiva e di materiale compatibile con il furto.<\/p>\n\n\n\n<p>Il rame recuperato \u00e8 stato sequestrato e riconsegnato all\u2019azienda, mentre sono in corso ulteriori accertamenti per individuare eventuali complici e collegamenti con altre razzie avvenute negli ultimi mesi nel territorio, dove il furto di cavi e componenti in metallo prezioso continua a rappresentare un danno economico costante per imprese e infrastrutture.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/11\/05\/sventato-furto-di-rame-in-azienda\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/11\/05\/sventato-furto-di-rame-in-azienda\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(f.f.)_____________ Nuovo episodio legato al traffico di rame nel Salento, ma questa volta il colpo \u00e8 stato bloccato prima che potesse essere portato a termine. Nella tarda serata del 3 novembre, un giovane di 22 anni originario di Casarano \u00e8 stato denunciato dai carabinieri dopo essere stato sorpreso con materiale in rame sottratto da una [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":251043,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/251040"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=251040"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/251040\/revisions"}],"predecessor-version":[{"id":251051,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/251040\/revisions\/251051"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/251043"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=251040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=251040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=251040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}