{"id":251100,"date":"2025-11-06T12:17:25","date_gmt":"2025-11-06T11:17:25","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=251100"},"modified":"2025-11-11T13:16:47","modified_gmt":"2025-11-11T12:16:47","slug":"quarta-caffe-vi-invita-a-lecce-in-piazza-palio-all-agro-ge-pak","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/11\/06\/quarta-caffe-vi-invita-a-lecce-in-piazza-palio-all-agro-ge-pak\/","title":{"rendered":"QUARTA CAFFE&#8217; VI INVITA A LECCE IN PIAZZA PALIO ALL&#8217; AGRO.GE.PA.CIOK"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"960\" height=\"639\" class=\"wp-image-251101\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/11\/BannerNews_Agrogepaciok25_960x639px_IT.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/11\/BannerNews_Agrogepaciok25_960x639px_IT.jpg 960w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/11\/BannerNews_Agrogepaciok25_960x639px_IT-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/11\/BannerNews_Agrogepaciok25_960x639px_IT-768x511.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/p>\n\n\n\n<p><strong>AGRO.GE.PA.CIOK 2025<\/strong><\/p>\n\n\n\n<p>Scopri le ultime tendenze dell\u2019arte del caff\u00e8 dall\u20198 al 12 novembre a Lecce Fiere, Piazza Palio.<\/p>\n\n\n\n<p>Dal <strong>8 al 12 novembre 2025<\/strong>, Quarta Caff\u00e8 ritorna con entusiasmo ad <strong>AGRO.GE.PA.CIOK<\/strong>, il Salone nazionale dell\u2019arte dolciaria, cioccolateria, gelateria e dell\u2019artigianato agroalimentare, che si terr\u00e0 presso <strong>Lecce Fiere<\/strong>, Piazza Palio.<\/p>\n\n\n\n<p>Durante questi cinque giorni, l\u2019azienda sar\u00e0 lieta di presentare al pubblico le sue esclusive miscele, emblema della qualit\u00e0 e dell\u2019innovazione che caratterizzano Quarta Caff\u00e8. Utilizziamo le pi\u00f9 pregiate qualit\u00e0 di caff\u00e8, garantendo una freschezza impareggiabile grazie alla <strong>tostatura separata<\/strong>, senza l\u2019uso del sottovuoto.<\/p>\n\n\n\n<p>Oltre alle degustazioni, i visitatori potranno scoprire le ultime tendenze nell\u2019arte del caff\u00e8. Saranno presenti dimostrazioni di <strong>Latte Art<\/strong>, per perfezionare la preparazione di un espresso ideale.<\/p>\n\n\n\n<p><strong>Quarta Caff\u00e8<\/strong>, leader di settore con un forte legame al territorio salentino, \u00e8 orgogliosa di poter condividere ancora una volta la propria esperienza e passione con clienti e appassionati di caff\u00e8 in questa edizione 2025 di <strong>AGRO.GE.PA.CIOK.<\/strong><\/p>\n\n\n\n<p><strong>Vi aspettiamo in fiera presso AREA B \u2013 STAND 92\/93\/120\/121.<\/strong><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/11\/06\/quarta-caffe-vi-invita-a-lecce-in-piazza-palio-all-agro-ge-pak\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/11\/06\/quarta-caffe-vi-invita-a-lecce-in-piazza-palio-all-agro-ge-pak\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>AGRO.GE.PA.CIOK 2025 Scopri le ultime tendenze dell\u2019arte del caff\u00e8 dall\u20198 al 12 novembre a Lecce Fiere, Piazza Palio. Dal 8 al 12 novembre 2025, Quarta Caff\u00e8 ritorna con entusiasmo ad AGRO.GE.PA.CIOK, il Salone nazionale dell\u2019arte dolciaria, cioccolateria, gelateria e dell\u2019artigianato agroalimentare, che si terr\u00e0 presso Lecce Fiere, Piazza Palio. Durante questi cinque giorni, l\u2019azienda sar\u00e0 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":251101,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69,75],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/251100"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=251100"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/251100\/revisions"}],"predecessor-version":[{"id":251109,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/251100\/revisions\/251109"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/251101"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=251100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=251100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=251100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}