{"id":251163,"date":"2025-11-07T09:44:00","date_gmt":"2025-11-07T08:44:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=251163"},"modified":"2025-11-07T10:58:49","modified_gmt":"2025-11-07T09:58:49","slug":"brindisi-scoperti-altri-32-furbetti-del-reddito-di-cittadinanza","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/11\/07\/brindisi-scoperti-altri-32-furbetti-del-reddito-di-cittadinanza\/","title":{"rendered":"BRINDISI, SCOPERTI ALTRI 32  FURBETTI DEL REDDITO DI CITTADINANZA"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"700\" height=\"465\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/11\/Guardia-di-Finanza-Brindisi.jpg\" alt=\"\" class=\"wp-image-251164\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/11\/Guardia-di-Finanza-Brindisi.jpg 700w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/11\/Guardia-di-Finanza-Brindisi-300x199.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/figure>\n\n\n\n<p>(f.f.)__________<\/p>\n\n\n\n<p>I finanzieri della Compagnia di Ostuni hanno individuato 32 cittadini residenti nei comuni di Ostuni, Carovigno, Ceglie Messapica e San Vito dei Normanni che, secondo quanto emerso dalle indagini, avrebbero percepito il reddito di cittadinanza senza averne i requisiti previsti. L\u2019ammontare complessivo delle somme indebitamente incassate supera i 370 mila euro.<\/p>\n\n\n\n<p>Le verifiche, condotte sulla base dei dati forniti dal Nucleo Speciale Spesa Pubblica e Repressione Frodi Comunitarie della Guardia di Finanza di Roma e dall\u2019INPS, hanno permesso di individuare diverse irregolarit\u00e0. In molti casi i beneficiari avrebbero omesso di dichiarare familiari conviventi, precedenti giudiziari o cambiamenti nella situazione lavorativa, elementi che avrebbero comportato la perdita del diritto al sussidio.<\/p>\n\n\n\n<p>Tutti i soggetti coinvolti sono stati denunciati alla Procura della Repubblica di Brindisi e segnalati all\u2019INPS, che provveder\u00e0 alla revoca del beneficio, al recupero delle somme indebitamente percepite e al blocco di ulteriori erogazioni.<\/p>\n\n\n\n<p>Tra i casi pi\u00f9 eclatanti, quello di una coppia che aveva falsamente dichiarato di vivere separata, riuscendo cos\u00ec a ottenere due redditi di cittadinanza per un totale di 36 mila euro.<\/p>\n\n\n\n<p>L\u2019attivit\u00e0 della Guardia di Finanza, svolta in stretta collaborazione con l\u2019INPS, rientra nel pi\u00f9 ampio piano di contrasto alle frodi ai danni dello Stato, volto a tutelare le risorse pubbliche e garantire che i sostegni economici siano destinati a chi ne ha realmente bisogno.<\/p>\n\n\n\n<p>I controlli continueranno anche nei prossimi mesi per prevenire e reprimere nuovi episodi di irregolarit\u00e0. Resta fermo il principio di presunzione d\u2019innocenza fino a eventuale condanna definitiva.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/11\/07\/brindisi-scoperti-altri-32-furbetti-del-reddito-di-cittadinanza\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/11\/07\/brindisi-scoperti-altri-32-furbetti-del-reddito-di-cittadinanza\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(f.f.)__________ I finanzieri della Compagnia di Ostuni hanno individuato 32 cittadini residenti nei comuni di Ostuni, Carovigno, Ceglie Messapica e San Vito dei Normanni che, secondo quanto emerso dalle indagini, avrebbero percepito il reddito di cittadinanza senza averne i requisiti previsti. L\u2019ammontare complessivo delle somme indebitamente incassate supera i 370 mila euro. Le verifiche, condotte [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":251164,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/251163"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=251163"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/251163\/revisions"}],"predecessor-version":[{"id":251173,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/251163\/revisions\/251173"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/251164"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=251163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=251163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=251163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}