{"id":251312,"date":"2025-11-10T12:10:00","date_gmt":"2025-11-10T11:10:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=251312"},"modified":"2025-11-11T15:25:39","modified_gmt":"2025-11-11T14:25:39","slug":"galatina-smaltimento-illecito-di-rifiuti-scoperto-e-sanzionato","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/11\/10\/galatina-smaltimento-illecito-di-rifiuti-scoperto-e-sanzionato\/","title":{"rendered":"GALATINA, SMALTIMENTO ILLECITO DI RIFIUTI SCOPERTO E SANZIONATO"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"690\" height=\"397\" class=\"wp-image-225936\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/01\/galatina-polizia-commissariato.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/01\/galatina-polizia-commissariato.jpg 690w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/01\/galatina-polizia-commissariato-300x173.jpg 300w\" sizes=\"(max-width: 690px) 100vw, 690px\" \/><\/p>\n\n\n\n<p>(f.f.)____________<\/p>\n\n\n\n<p>Stavano abbandonando scarti di materiale edile nelle campagne del territorio quando sono stati colti in flagrante dagli agenti del Commissariato di Polizia di Stato di Galatina. Protagonisti dell\u2019episodio, avvenuto a fine settembre, due uomini sorpresi a bordo di una Fiat Panda mentre svuotavano grossi contenitori pieni di detriti e residui di lavori di costruzione.<\/p>\n\n\n\n<p>Gli agenti, impegnati in un normale servizio di controllo del territorio, hanno notato la scena e si sono immediatamente avvicinati, fermando i due sul posto. Invitati a ripristinare l\u2019area, i responsabili hanno dovuto raccogliere il materiale gi\u00e0 disperso sul terreno e provvedere successivamente al corretto smaltimento, documentandone l\u2019avvenuta esecuzione presso gli uffici di polizia.<\/p>\n\n\n\n<p>Nella giornata odierna, al momento della consegna della ricevuta di smaltimento, \u00e8 scattata la sanzione amministrativa per il principale responsabile, un 68enne proprietario dell\u2019auto e del materiale. In base alla normativa vigente in materia ambientale, all\u2019uomo \u00e8 stata comminata una multa di 4.500 euro, oltre alla sospensione della patente di guida per un periodo compreso tra quattro e sei mesi.<\/p>\n\n\n\n<p>L\u2019episodio conferma l\u2019impegno costante della Polizia di Stato nel contrastare le pratiche illegali di abbandono dei rifiuti e nel tutelare l\u2019ambiente rurale, spesso vittima di comportamenti irresponsabili che compromettono il territorio salentino.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/11\/10\/galatina-smaltimento-illecito-di-rifiuti-scoperto-e-sanzionato\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/11\/10\/galatina-smaltimento-illecito-di-rifiuti-scoperto-e-sanzionato\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(f.f.)____________ Stavano abbandonando scarti di materiale edile nelle campagne del territorio quando sono stati colti in flagrante dagli agenti del Commissariato di Polizia di Stato di Galatina. Protagonisti dell\u2019episodio, avvenuto a fine settembre, due uomini sorpresi a bordo di una Fiat Panda mentre svuotavano grossi contenitori pieni di detriti e residui di lavori di costruzione. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":225936,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/251312"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=251312"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/251312\/revisions"}],"predecessor-version":[{"id":251359,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/251312\/revisions\/251359"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/225936"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=251312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=251312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=251312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}