{"id":251318,"date":"2025-11-11T12:44:22","date_gmt":"2025-11-11T11:44:22","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=251318"},"modified":"2025-11-11T12:44:25","modified_gmt":"2025-11-11T11:44:25","slug":"anziano-si-perde-nel-bosco-di-carpignano-salvato-dai-carabinieri","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/11\/11\/anziano-si-perde-nel-bosco-di-carpignano-salvato-dai-carabinieri\/","title":{"rendered":"ANZIANO SI PERDE NEL BOSCO DI CARPIGNANO, SALVATO DAI CARABINIERI"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/11\/IMG-20251110-WA0007-768x1024.jpg\" alt=\"\" class=\"wp-image-251319\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/11\/IMG-20251110-WA0007-768x1024.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/11\/IMG-20251110-WA0007-225x300.jpg 225w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/11\/IMG-20251110-WA0007-1152x1536.jpg 1152w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/11\/IMG-20251110-WA0007.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p>(f.f.)____________<\/p>\n\n\n\n<p>Una mattinata di grande apprensione si \u00e8 fortunatamente conclusa con un lieto fine grazie alla prontezza e alla professionalit\u00e0 dei Carabinieri della Stazione di Soleto, intervenuti per soccorrere un uomo di 77 anni che si era smarrito in un\u2019area boschiva del territorio di Carpignano Salentino.<\/p>\n\n\n\n<p>L\u2019anziano, residente a Galatina, aveva deciso di addentrarsi da solo tra i sentieri della macchia salentina nelle prime ore del mattino. Dopo qualche tempo, per\u00f2, la fitta vegetazione e l\u2019assenza di punti di riferimento lo hanno disorientato, facendogli perdere completamente la via del ritorno. Resosi conto di trovarsi in difficolt\u00e0, l\u2019uomo ha avuto la lucidit\u00e0 di contattare il numero unico di emergenza 112, chiedendo aiuto.<\/p>\n\n\n\n<p>Fondamentale si \u00e8 rivelata la prontezza dell\u2019operatore della Centrale Operativa, che ha mantenuto costantemente il contatto telefonico con l\u2019anziano, riuscendo a tranquillizzarlo e a raccogliere preziose informazioni per individuare la zona in cui si trovava. Nel frattempo, una pattuglia dei Carabinieri di Soleto si \u00e8 immediatamente diretta verso l\u2019area indicata, iniziando le ricerche a piedi tra i sentieri e la vegetazione fitta.<\/p>\n\n\n\n<p>Dopo un\u2019intensa perlustrazione, i militari sono riusciti a individuare l\u2019uomo, visibilmente spaventato ma in buone condizioni fisiche. Dopo averlo rassicurato, lo hanno accompagnato fino al punto in cui aveva lasciato la propria automobile, consentendogli di riprendersi dallo spavento e di tornare finalmente a casa.<\/p>\n\n\n\n<p>L\u2019episodio dimostra ancora una volta l\u2019importanza del presidio costante dei Carabinieri sul territorio e la loro vicinanza concreta alla popolazione, in particolare agli anziani, spesso pi\u00f9 esposti a situazioni di rischio anche in contesti apparentemente ordinari. La tempestivit\u00e0 dell\u2019intervento e l\u2019attenzione umana mostrata dai militari hanno permesso di evitare che una semplice passeggiata si trasformasse in una tragedia, riaffermando il ruolo dell\u2019Arma come punto di riferimento essenziale per la sicurezza e la tutela dei cittadini.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/11\/11\/anziano-si-perde-nel-bosco-di-carpignano-salvato-dai-carabinieri\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/11\/11\/anziano-si-perde-nel-bosco-di-carpignano-salvato-dai-carabinieri\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(f.f.)____________ Una mattinata di grande apprensione si \u00e8 fortunatamente conclusa con un lieto fine grazie alla prontezza e alla professionalit\u00e0 dei Carabinieri della Stazione di Soleto, intervenuti per soccorrere un uomo di 77 anni che si era smarrito in un\u2019area boschiva del territorio di Carpignano Salentino. L\u2019anziano, residente a Galatina, aveva deciso di addentrarsi da [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":251319,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/251318"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=251318"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/251318\/revisions"}],"predecessor-version":[{"id":251331,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/251318\/revisions\/251331"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/251319"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=251318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=251318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=251318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}