{"id":2519,"date":"2012-07-03T09:53:33","date_gmt":"2012-07-03T09:53:33","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=2519"},"modified":"2012-07-03T10:17:47","modified_gmt":"2012-07-03T10:17:47","slug":"la-uil-nella-lotta-al-caporalato-agricolo-le-novita-il-commento-di-mauro-fioretti","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2012\/07\/03\/la-uil-nella-lotta-al-caporalato-agricolo-le-novita-il-commento-di-mauro-fioretti\/","title":{"rendered":"LA UIL NELLA LOTTA AL CAPORALATO AGRICOLO \u2013 LE NOVITA\u2019 \u2013 IL COMMENTO DI MAURO FIORETTI"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/07\/03\/la-uil-nella-lotta-al-caporalato-agricolo-le-novita-il-commento-di-mauro-fioretti\/ortofrutta1\/\" rel=\"attachment wp-att-2520\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/07\/ortofrutta1-300x225.jpg\" alt=\"\" title=\"ortofrutta1\" width=\"300\" height=\"225\" class=\"alignnone size-medium wp-image-2520\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/07\/ortofrutta1-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/07\/ortofrutta1.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>\u00c8 stato presentato e depositato ufficialmente venerd\u00ec scorso, nella sede della Prefettura di Lecce, il protocollo sulle operazioni di raccolta delle produzioni ortofrutticole siglato dai sindacati Uila Uil, Fai Cisl e Flai Cgil, insieme con le associazioni di categoria Cia, Coldiretti e Confagricoltura.<\/p>\n<p>Scopo del protocollo \u00e8 quello di creare una lista di aziende che si dichiarano disponibili ad assumere i lavoratori inseriti all\u2019interno delle liste di prenotazione gi\u00e0 istituite con apposita legge regionale e fare in modo, quindi, che ci sia una sorta di \u201crintracciabilit\u00e0\u201d del rapporto di lavoro e soprattutto un incontro diretto tra domanda e offerta, senza dannose ed illegali intermediazioni che portano al deprecabile fenomeno del caporalato agricolo, come testimoniano i recenti fatti di Boncuri.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201c<em>Parliamo di <span style=\"text-decoration: underline;\">uno strumento trasparente per il collocamento di braccianti italiani o stranieri\u201d<\/span><\/em> \u2013 ha spiegato a leccecronaca.it <strong>Mauro Fioretti<\/strong>, segretario provinciale Uila Uil, che ha cos\u00ec proseguito il suo commento \u2013 <em>\u201cE\u2019 anche il primo esperimento in tal senso a livello nazionale, quindi sicuramente perfettibile e suscettibile di modifiche. <span style=\"text-decoration: underline;\">L\u2019intento \u00e8 in sostanza quello di fare in modo che le aziende ci rappresentino le loro disponibilit\u00e0 in termini di manodopera, in modo da creare un punto d\u2019incontro diretto tra domanda e offerta<\/span>. Abbiamo inoltre avanzato una richiesta precisa, ossia che un istituto bancario possa costituire una sorta di cassa privilegiata monitorata per il pagamento delle prestazioni lavorative. In tal modo, infatti, si avr\u00e0 la certezza che i soldi vengano effettivamente incassati da chi svolge la prestazione lavorativa. Noi come parti sociali abbiamo fatto la nostra parte e ci abbiamo messo la faccia. Su questo dobbiamo lavorare per portare avanti un\u2019azione di lotta e di contrasto ai fenomeni di sfruttamento, soprattutto ora che \u00e8 gi\u00e0 cominciata una nuova stagione di raccolta nei nostri campi. Adesso ognuno svolga il proprio ruolo\u201d.<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2012\/07\/03\/la-uil-nella-lotta-al-caporalato-agricolo-le-novita-il-commento-di-mauro-fioretti\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/07\/03\/la-uil-nella-lotta-al-caporalato-agricolo-le-novita-il-commento-di-mauro-fioretti\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>\u00c8 stato presentato e depositato ufficialmente venerd\u00ec scorso, nella sede della Prefettura di Lecce, il protocollo sulle operazioni di raccolta delle produzioni ortofrutticole siglato dai sindacati Uila Uil, Fai Cisl e Flai Cgil, insieme con le associazioni di categoria Cia, Coldiretti e Confagricoltura. Scopo del protocollo \u00e8 quello di creare una lista di aziende che [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2520,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/2519"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=2519"}],"version-history":[{"count":7,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/2519\/revisions"}],"predecessor-version":[{"id":2527,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/2519\/revisions\/2527"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/2520"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=2519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=2519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=2519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}