{"id":25200,"date":"2014-03-04T09:31:18","date_gmt":"2014-03-04T09:31:18","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=25200"},"modified":"2014-03-04T09:33:07","modified_gmt":"2014-03-04T09:33:07","slug":"operazione-froth-sgominata-organizzazione-di-trafficanti-e-spacciatori-di-droga","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/03\/04\/operazione-froth-sgominata-organizzazione-di-trafficanti-e-spacciatori-di-droga\/","title":{"rendered":"\u201cOPERAZIONE FROTH\u201d: SGOMINATA ORGANIZZAZIONE DI TRAFFICANTI E SPACCIATORI DI DROGA"},"content":{"rendered":"<p>IN CORSO DI ESECUZIONE 29 PROVVEDIMENTI DI CATTURA<\/p>\n<p>Dalle prime ore di questa mattina, i Finanzieri della Compagnia di Lecce, coadiuvati dai colleghi di tutti i Reparti del Corpo della provincia, stanno eseguendo 29 ordinanze di custodia cautelare scaturite da un\u2019articolata indagine nei confronti di un\u2019associazione finalizzata al traffico illecito di sostanze stupefacenti.<\/p>\n<p>I dettagli dell\u2019operazione verranno forniti in occasione della conferenza stampa \u2013 presieduta dal Procuratore della Repubblica di Lecce, dott. Cataldo MOTTA \u2013 che si terr\u00e0 alle ore 11.00 odierne presso questo Comando Provinciale, in Piazzetta dei Peruzzi, 1.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/03\/04\/operazione-froth-sgominata-organizzazione-di-trafficanti-e-spacciatori-di-droga\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/03\/04\/operazione-froth-sgominata-organizzazione-di-trafficanti-e-spacciatori-di-droga\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>IN CORSO DI ESECUZIONE 29 PROVVEDIMENTI DI CATTURA Dalle prime ore di questa mattina, i Finanzieri della Compagnia di Lecce, coadiuvati dai colleghi di tutti i Reparti del Corpo della provincia, stanno eseguendo 29 ordinanze di custodia cautelare scaturite da un\u2019articolata indagine nei confronti di un\u2019associazione finalizzata al traffico illecito di sostanze stupefacenti. I dettagli [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15953,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/25200"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=25200"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/25200\/revisions"}],"predecessor-version":[{"id":25203,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/25200\/revisions\/25203"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/15953"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=25200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=25200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=25200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}