{"id":25292,"date":"2014-03-06T07:52:26","date_gmt":"2014-03-06T07:52:26","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=25292"},"modified":"2014-03-06T07:58:57","modified_gmt":"2014-03-06T07:58:57","slug":"gli-orrori-del-salento-2-giro-giro-tondo-con-opera-darte-di-tonio-leuci","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/03\/06\/gli-orrori-del-salento-2-giro-giro-tondo-con-opera-darte-di-tonio-leuci\/","title":{"rendered":"Gli orrori del Salento\/ 2  GIRO GIRO TONDO, CON \u201cOPERA D&#8217;ARTE\u201d  di Tonio Leuci"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/03\/Schermata-2014-03-06-a-08.55.58.png\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/03\/Schermata-2014-03-06-a-08.55.58-300x241.png\" alt=\"\" width=\"300\" height=\"241\" class=\"alignleft size-medium wp-image-25297\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/03\/Schermata-2014-03-06-a-08.55.58-300x241.png 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/03\/Schermata-2014-03-06-a-08.55.58.png 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Nel mio reportage sugli orrori che deturpano il nostro territorio, eccomi ad occuparmi delle rotatorie stradali con le loro \u201copere d&#8217;arte\u201d, oppure \u201cobbrobri\u201d, a seconda dei punti di vista, un fenomeno \u00e8 esploso qualche anno fa nel Nord e Centro Italia, per poi riguardare anche il Sud, in particolare la Puglia e il Salento.<\/p>\n<p>Le rotatorie oramai spuntano come funghi spesso con monumenti incorporati , facendo nascere qualche perplessit\u00e0 sulla loro effettiva utilit\u00e0 e sicurezza.<\/p>\n<p>Per molti esperti, le rotatorie sono un&#8217;agevolazione del traffico. C&#8217;\u00e8 da dire per\u00f2 che funzionano perfettamente in Francia, in Germania, in altri Paesi europei, dove di solito, imboccandole, gli automobilisti rallentano e agevolano il passaggio degli altri, con prudenza e galanteria, a differenza del nostro Paese, dove invece accade esattamente il contrario.<\/p>\n<p>E&#8217; storia di ogni giono e di ogni rotatoria: da noi, di solito si fa a gara a prendere velocit\u00e0, occupare le corsie di transito e negare il passaggio degli altri con prepotenza ed eoismo, tanto che da noi le rotatorie sono sempre causa di incomprensioni, mancate precedenze e incidenti, finendo per complicare cio\u00e8 che avrebbero dovuto risolvere, stante il basso livello di educazione civica che ci contraddistingue.<\/p>\n<p>Prendere da un&#8217;altra cultura e importare senza il minimo tentativo di approfondire \u00e8 sempre rischioso. Ma l&#8217; Italia non pu\u00f2 fare a meno di distinguersi per superficialit\u00e0, in fondo gli Italiani ne hanno fatto una scienza.<\/p>\n<p>&nbsp;<\/p>\n<p>Tralasciando le polemiche circa lo loro effettiva utilit\u00e0 o pericolosit\u00e0, vorrei fare qualche riflessione circa le \u201copere d&#8217;arte\u201d &#8211; se cos\u00ec possiamo chiamarle &#8211; che vengono collocate nelle rotatorie, dalle amministrazioni comunali. Come non pensare per esempio al colossale cavallo della ciclopica rotatoria di Cavallino? O\u00a0 alle sculture sulle rotatorie Nard\u00f2- Melissano che rappresentano un mollusco e una non meglio precisata figura, un misto tra un anatra e un cavalluccio marino?<\/p>\n<p>Mi domando: queste rotatorie &#8211; oltre a deturpare il paesaggio &#8211; quanto costano alla collettivit\u00e0? Quanti monumenti, quanti beni culturali e archeologici potrebbero essere salvati, mentre sono abbandonati all&#8217;incuria e al degrado?\u00a0In ogni citt\u00e0 d&#8217;Italia pezzi importanti del nostro passato storico e artistico vanno in rovina. E gli scavi archeologici sono aperti e richiusi perch\u00e9 non ci sono i soldi per gestirli.\u00a0Uno sperpero di fondi europei, per commissionare gli orrori delle rotatorie.<\/p>\n<p>Andrea Paltrinieri \u00e8 un sociologo emiliano che d\u00e0 la seguente spiegazione del fenomeno: <em>\u201cLe rotatorie hanno da tempo scalzato le piazze come\u00a0<\/em>location\u00a0<em>ideale per queste opere d&#8217; arte, per questi \u201cmonumenti\u201d.<\/em>\u00a0<em>Accanto ai luoghi cambiano per\u00f2 anche i temi.<\/em>\u00a0<em>Non pi\u00f9 personaggi della storia nazionale. Non pi\u00f9 eventi eroici o tragici della citt\u00e0. Non pi\u00f9 rappresentazioni di ideali astratti o virt\u00f9 civiche (qualunque esse siano). Ma i prodotti del territorio. Quei prodotti che hanno contribuito a determinare il benessere economico della popolazione residente o che,<\/em><\/p>\n<p><em>\u00a0anche solo, segnano un tratto dell&#8217;identit\u00e0 che si vuole affermare (spesso recuperandola dal passato) per il territorio. Opere d&#8217;arte, dunque, che sono chiamate non tanto ad elevare lo spirito, ma a fungere da operatori del marketing territoriale\u201d.<\/em><\/p>\n<p><strong>Tonio Leuci ( 2 \u2013 continua )<\/strong><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/03\/06\/gli-orrori-del-salento-2-giro-giro-tondo-con-opera-darte-di-tonio-leuci\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/03\/06\/gli-orrori-del-salento-2-giro-giro-tondo-con-opera-darte-di-tonio-leuci\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Nel mio reportage sugli orrori che deturpano il nostro territorio, eccomi ad occuparmi delle rotatorie stradali con le loro \u201copere d&#8217;arte\u201d, oppure \u201cobbrobri\u201d, a seconda dei punti di vista, un fenomeno \u00e8 esploso qualche anno fa nel Nord e Centro Italia, per poi riguardare anche il Sud, in particolare la Puglia e il Salento. Le [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":25297,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/25292"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=25292"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/25292\/revisions"}],"predecessor-version":[{"id":25295,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/25292\/revisions\/25295"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/25297"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=25292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=25292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=25292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}