{"id":25442,"date":"2014-03-10T15:34:53","date_gmt":"2014-03-10T15:34:53","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=25442"},"modified":"2014-03-10T15:35:34","modified_gmt":"2014-03-10T15:35:34","slug":"mostra-o-iniziativa-pubblicitaria-1994-2014-ventanni-un-soffio","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/03\/10\/mostra-o-iniziativa-pubblicitaria-1994-2014-ventanni-un-soffio\/","title":{"rendered":"MOSTRA O INIZIATIVA PUBBLICITARIA? 1994- 2014  \u201cVent\u2019anni, un soffio!\u201d"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><strong><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/03\/coop.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/03\/coop-230x300.jpg\" alt=\"\" width=\"230\" height=\"300\" class=\"alignleft size-medium wp-image-25444\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/03\/coop-230x300.jpg 230w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/03\/coop.jpg 300w\" sizes=\"(max-width: 230px) 100vw, 230px\" \/><\/a>Con il sostegno del comune di Lecce e di Surbo, il Centro Commerciale Mongolfiera Lecce ( l&#8217;Ipercoop di Surbo)\u00a0<\/strong><strong>il 14 marzo festeggia il suo\u00a0<em>20^ anniversario\u00a0<\/em><\/strong><strong>con una mostra fotografica unica nel suo genere.<br \/>\n<\/strong>Al via i festeggiamenti per il ventennale di attivit\u00e0 del Centro Commerciale Mongolfiera Lecce,\u00a0<strong>il primo centro commerciale\u00a0aperto in Puglia,\u00a0<\/strong>che ancora oggi rappresenta una delle pi\u00f9 solide realt\u00e0 del territorio: leader indiscusso, non solo per lo shopping, ma anche per le attivit\u00e0 e le iniziative che lo hanno legato al territorio salentino.<\/p>\n<p><strong>Nel 1994<\/strong>, infatti, grazie ad un&#8217;importante iniziativa di Coop Estense,<strong>\u00a0nasceva il Centro Salento<\/strong>, il centro commerciale dei salentini: un luogo commerciale che negli anni, con impegno e passione, ha saputo rappresentare un punto di riferimento e di aggregazione sociale. Ed \u00e8 per questo che il centro commerciale Mongolfiera, ha pensato di rendere omaggio alla sua terra celebrando questi 20 anni di storia, ripercorrendo avvenimenti ed emozioni che in questo lungo tempo lo hanno accompagnato.<\/p>\n<p>&#8220;Vent&#8217;anni, un soffio!&#8221;: \u00e8 il titolo della raccolta di immagini con cui il Centro Commerciale Mongolfiera Lecce vuole condividere con il territorio salentino un percorso virtuoso lungo due decadi, travagliate come poche. A partire dal 14 marzo, percorrendo i corridoi del centro commerciale, sar\u00e0 possibile scoprire questa suggestiva mostra fotografica che, in venti pannelli, ripercorre, anno dopo anno, gli avvenimenti che hanno scritto la\u00a0<strong>storia del mondo,<\/strong>\u00a0<strong>dal 1994 al 2014,\u00a0<\/strong>in parallelo con altrettanti<strong>\u00a0avvenimenti locali e dello stesso Centro Commerciale,\u00a0<\/strong>che delineano il percorso virtuoso di un territorio ed una citt\u00e0 particolarmente attivi nell\u2019ultimo ventennio.<\/p>\n<p><strong><em>\u00a0&#8220;Vent\u2019anni, un Soffio!\u00a0<\/em><\/strong><em>\u00e8 il miglior modo<\/em>\u00a0\u2013 spiega<strong>\u00a0il direttore del centro commerciale Davide Vitale<\/strong>\u00a0\u2013<em>per ringraziare i salentini e le istituzioni e, condividere con loro, la storia e l&#8217;impegno del centro commerciale in queste due decadi, caratterizzate da mutamenti politici, tecnologici e di costume che hanno interessato il mondo intero e parallelamente il Salento. Una terra viva e vitale che proprio in questi anni si \u00e8 affacciata alla ribalta internazionale, attraverso la cultura, l\u2019arte e il turismo<strong>&#8220;.<\/strong><\/em><\/p>\n<p>Venti anni di shopping e di emozioni: un&#8217;occasione per ringraziare tutti i clienti e coinvolgerli in\u00a0<strong>una grande festa, che entusiasmer\u00e0 grandi e piccini<\/strong>. E\u2019 infatti iniziato il<strong>\u00a0<\/strong><em>countdown\u00a0<\/em><em>per il taglio della\u00a0<strong>torta monumentale\u00a0<\/strong>che, con le tecniche pi\u00f9 evolute del cake design, ripercorrer\u00e0 questi anni di storia salentina.<\/em><strong>Venerd\u00ec 14 Marzo, dalle ore 17:00,<\/strong>\u00a0tanta allegria all\u2019interno del centro commerciale.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/03\/10\/mostra-o-iniziativa-pubblicitaria-1994-2014-ventanni-un-soffio\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/03\/10\/mostra-o-iniziativa-pubblicitaria-1994-2014-ventanni-un-soffio\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Con il sostegno del comune di Lecce e di Surbo, il Centro Commerciale Mongolfiera Lecce ( l&#8217;Ipercoop di Surbo)\u00a0il 14 marzo festeggia il suo\u00a020^ anniversario\u00a0con una mostra fotografica unica nel suo genere. Al via i festeggiamenti per il ventennale di attivit\u00e0 del Centro Commerciale Mongolfiera Lecce,\u00a0il primo centro commerciale\u00a0aperto in Puglia,\u00a0che ancora oggi rappresenta una [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":25444,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/25442"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=25442"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/25442\/revisions"}],"predecessor-version":[{"id":25446,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/25442\/revisions\/25446"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/25444"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=25442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=25442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=25442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}