{"id":254934,"date":"2026-02-05T12:27:00","date_gmt":"2026-02-05T11:27:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=254934"},"modified":"2026-02-05T13:46:50","modified_gmt":"2026-02-05T12:46:50","slug":"ladri-in-azione-al-liceo-banzi-scuole-leccesi-sotto-attacco","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2026\/02\/05\/ladri-in-azione-al-liceo-banzi-scuole-leccesi-sotto-attacco\/","title":{"rendered":"LADRI IN AZIONE AL LICEO BANZI, SCUOLE LECCESI SOTTO ATTACCO"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"600\" height=\"400\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2026\/02\/LICEO-BANZI.jpg\" alt=\"\" class=\"wp-image-254937\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2026\/02\/LICEO-BANZI.jpg 600w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2026\/02\/LICEO-BANZI-300x200.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p>(f.f.)_____________<\/p>\n\n\n\n<p>Nella scorsa notte il Liceo Scientifico \u201cBanzi\u201d di piazza Palio \u00e8 stato preso di mira da ignoti malviventi. I ladri, dopo essere entrati nell\u2019edificio, hanno forzato e aperto i distributori automatici presenti, appropriandosi del denaro contenuto all\u2019interno.<\/p>\n\n\n\n<p>Sul luogo dell\u2019accaduto sono intervenuti i carabinieri per effettuare tutti i rilievi del caso. Fortunatamente, al momento non sono stati segnalati danni alle strutture o alle aule dell\u2019istituto.<\/p>\n\n\n\n<p>L\u2019episodio si inserisce in un contesto preoccupante di continui atti contro le scuole cittadine. Solo la notte precedente, infatti, il Liceo \u201cEnrico Fermi\u201d di via Merine ha subito un raid vandalico con gravi conseguenze: aule devastate, corridoi in disordine, arredi danneggiati, fotocopiatrici fuori uso e distributori automatici manomessi.<\/p>\n\n\n\n<p>Le forze dell\u2019ordine hanno avviato le indagini per identificare i responsabili, mentre la comunit\u00e0 scolastica resta in apprensione per la sicurezza dei propri istituti.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2026\/02\/05\/ladri-in-azione-al-liceo-banzi-scuole-leccesi-sotto-attacco\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2026\/02\/05\/ladri-in-azione-al-liceo-banzi-scuole-leccesi-sotto-attacco\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(f.f.)_____________ Nella scorsa notte il Liceo Scientifico \u201cBanzi\u201d di piazza Palio \u00e8 stato preso di mira da ignoti malviventi. I ladri, dopo essere entrati nell\u2019edificio, hanno forzato e aperto i distributori automatici presenti, appropriandosi del denaro contenuto all\u2019interno. Sul luogo dell\u2019accaduto sono intervenuti i carabinieri per effettuare tutti i rilievi del caso. Fortunatamente, al momento [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":254937,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/254934"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=254934"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/254934\/revisions"}],"predecessor-version":[{"id":254938,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/254934\/revisions\/254938"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/254937"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=254934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=254934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=254934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}