{"id":255101,"date":"2026-02-08T12:29:58","date_gmt":"2026-02-08T11:29:58","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=255101"},"modified":"2026-02-08T12:35:06","modified_gmt":"2026-02-08T11:35:06","slug":"brindisi-poliziotto-fuori-servizio-ritrova-il-furgone-rubato-dei-bambini-della-valtur-new-basket","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2026\/02\/08\/brindisi-poliziotto-fuori-servizio-ritrova-il-furgone-rubato-dei-bambini-della-valtur-new-basket\/","title":{"rendered":"BRINDISI, POLIZIOTTO FUORI SERVIZIO RITROVA IL FURGONE RUBATO DEI BAMBINI DELLA VALTUR NEW BASKET"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"780\" height=\"470\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2026\/02\/Controlli-straordinari-a-Lecce-della-Polizia-di-Stato-nel-centro-cittadino-780x470-2.jpg\" alt=\"\" class=\"wp-image-255102\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2026\/02\/Controlli-straordinari-a-Lecce-della-Polizia-di-Stato-nel-centro-cittadino-780x470-2.jpg 780w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2026\/02\/Controlli-straordinari-a-Lecce-della-Polizia-di-Stato-nel-centro-cittadino-780x470-2-300x181.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2026\/02\/Controlli-straordinari-a-Lecce-della-Polizia-di-Stato-nel-centro-cittadino-780x470-2-768x463.jpg 768w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/><\/figure>\n\n\n\n<p>(f.f.)______________<\/p>\n\n\n\n<p>Una vicenda a lieto fine per i giovani atleti della Valtur New Basket Brindisi, grazie alla prontezza di un poliziotto fuori servizio della Questura di Brindisi. Nella notte scorsa, intorno alle 00:40, l\u2019operatore, rientrando a casa a Lecce dopo il turno in Sala Operativa, ha notato un furgone con i loghi della squadra parcheggiato in una posizione defilata lungo la strada. Il veicolo gli ha subito ricordato la segnalazione di un furto avvenuto pochi giorni prima, quando ignoti avevano sottratto il mezzo utilizzato per trasportare i bambini e i giovani atleti che frequentano l\u2019impianto di Contrada Masseriola.<\/p>\n\n\n\n<p>Senza perdere tempo, il poliziotto ha contattato la Sala Operativa della Questura di Brindisi e il suo Dirigente, avvicinandosi al furgone e verificando che si trattava proprio del mezzo rubato, trovato aperto. Sono stati immediatamente allertati sia il titolare del veicolo sia la Sala Operativa della Questura di Lecce, che ha inviato una pattuglia sul posto. Il poliziotto ha vigilato sul furgone fino all\u2019arrivo degli agenti, impedendo che qualcuno potesse avvicinarsi.<\/p>\n\n\n\n<p>Grazie al coordinamento tra le forze di Polizia di Brindisi e Lecce e all\u2019applicazione dei protocolli operativi del Ministero dell\u2019Interno, il furgone \u00e8 stato recuperato e riconsegnato ai bambini della Valtur New Basket, pronto per tornare in uso. L\u2019intervento tempestivo e l\u2019intraprendenza dell\u2019agente hanno permesso di trasformare un possibile episodio problematico in un lieto fine, dimostrando la professionalit\u00e0 e la collaborazione tra le diverse articolazioni delle Questure coinvolte.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2026\/02\/08\/brindisi-poliziotto-fuori-servizio-ritrova-il-furgone-rubato-dei-bambini-della-valtur-new-basket\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2026\/02\/08\/brindisi-poliziotto-fuori-servizio-ritrova-il-furgone-rubato-dei-bambini-della-valtur-new-basket\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(f.f.)______________ Una vicenda a lieto fine per i giovani atleti della Valtur New Basket Brindisi, grazie alla prontezza di un poliziotto fuori servizio della Questura di Brindisi. Nella notte scorsa, intorno alle 00:40, l\u2019operatore, rientrando a casa a Lecce dopo il turno in Sala Operativa, ha notato un furgone con i loghi della squadra parcheggiato [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":255102,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/255101"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=255101"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/255101\/revisions"}],"predecessor-version":[{"id":255104,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/255101\/revisions\/255104"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/255102"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=255101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=255101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=255101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}