{"id":255171,"date":"2026-02-11T12:07:07","date_gmt":"2026-02-11T11:07:07","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=255171"},"modified":"2026-02-11T12:17:25","modified_gmt":"2026-02-11T11:17:25","slug":"per-il-foro-boario-senza-parcheggi-per-due-settimane-pesanti-disagi","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2026\/02\/11\/per-il-foro-boario-senza-parcheggi-per-due-settimane-pesanti-disagi\/","title":{"rendered":"PER IL  FORO BOARIO SENZA PARCHEGGI PER DUE SETTIMANE PESANTI DISAGI"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"800\" height=\"482\" class=\"wp-image-255172\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2026\/02\/parcheggio-foro-boario.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2026\/02\/parcheggio-foro-boario.jpg 800w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2026\/02\/parcheggio-foro-boario-300x181.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2026\/02\/parcheggio-foro-boario-768x463.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>Riceviamo e volentieri pubblichiamo _____________<\/p>\n\n\n\n<p><strong>ARRIVA IL CIRCO.<\/strong> <strong>E SE DOVETE LAVORARE ATTACCATEVI AL\u2026 FILOBUS!<\/strong><\/p>\n\n\n\n<p>Arriva il circo al Foro Boario. E per chi debba recarsi in Tribunale, Giudice di Pace, Corte d\u2019Appello civile o da Equitalia si pu\u00f2 attaccare al\u2026 filobus!<\/p>\n\n\n\n<p>Forse l\u2019Amministrazione Comunale ha dimenticato che il parcheggio del Foro Boario \u00e8 il parcheggio di interscambio pi\u00f9 usato di Lecce, che esso potrebbe perfino servire per intercettare il traffico di coloro che vengono da Brindisi per evitare di intasare il centro di Lecce.<\/p>\n\n\n\n<p>E invece\u2026<\/p>\n\n\n\n<p>Invece ci piazzano il Circo e per 13 giorni tolgono parcheggi. Con buona pace degli utenti che per avventura dovessero recarsi nelle aule di giustizia o da Equitalia in quei giorni.<\/p>\n\n\n\n<p>E con buona pace pure del quartiere di Santa Rosa, gi\u00e0 sottoposto tutte le mattine ad un grandissimo stress automobilistico proprio a causa della grande presenza di soggetti coinvolti in quei servizi, e che con il venir meno dei posti auto occupati dal circo si trover\u00e0 in ancora maggiore difficolt\u00e0.<\/p>\n\n\n\n<p>Sar\u00e0 perch\u00e9 c\u2019\u00e8 il sole oltre le nuvole, ma ogni tanto sembra che l\u2019Amministrazione comunale ci viva, sopra le nuvole, e non si renda conto delle conseguenze delle sue azioni in materia di traffico.<\/p>\n\n\n\n<p>Eppure, basterebbe, prima di prendere decisioni del genere, scendere dalle nuvole e farsi una passeggiata nelle zone coinvolte da queste decisioni e rendersi conto dell\u2019assurdit\u00e0 di esse. Sarebbe bastato fare un salto un giorno qualunque di qualsiasi settimana prima di questa per capire che la mattina nella zona del Foro Boario non si parcheggia regolarmente per la grande massa di automobilisti presenti in zona. O sarebbe bastato vedere le multe elevate dalla Polizia locale e dagli ausiliari del traffico: il risultato non sarebbe cambiato di molto.<\/p>\n\n\n\n<p>Sarebbe infatti bastato questo per capire che, tra i parcheggi di interscambio della citt\u00e0, quello di Settelacquare \u00e8 molto meno utilizzato, e che quindi mettere l\u00ec il circo avrebbe creato meno problemi.<\/p>\n\n\n\n<p>Invece, come al solito l\u2019improvvisazione e la poca conoscenza delle dinamiche della citt\u00e0 porta l\u2019Amministrazione a trascurare le situazioni e a creare disagi anche l\u00e0 dove non se ne sentiva assolutamente la necessit\u00e0.<\/p>\n\n\n\n<p>Ormai il danno \u00e8 fatto, non si pu\u00f2 tornare indietro, ma si auspica che per il futuro si tenga in maggiore considerazione la vivibilit\u00e0 della citt\u00e0. Intanto, attacchiamoci al\u2026 filobus, questo mezzo mitologico che non ha risolto alcun problema di viabilit\u00e0 e che addirittura il Comune vuole ampliare contro la volont\u00e0 di una grossa fetta di cittadini, non solo quelli che hanno firmato per il referendum.&nbsp; Volont\u00e0 che l\u2019Amministrazione ha paura di ascoltare.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2026\/02\/11\/per-il-foro-boario-senza-parcheggi-per-due-settimane-pesanti-disagi\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2026\/02\/11\/per-il-foro-boario-senza-parcheggi-per-due-settimane-pesanti-disagi\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo _____________ ARRIVA IL CIRCO. E SE DOVETE LAVORARE ATTACCATEVI AL\u2026 FILOBUS! Arriva il circo al Foro Boario. E per chi debba recarsi in Tribunale, Giudice di Pace, Corte d\u2019Appello civile o da Equitalia si pu\u00f2 attaccare al\u2026 filobus! Forse l\u2019Amministrazione Comunale ha dimenticato che il parcheggio del Foro Boario \u00e8 il [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":255172,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/255171"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=255171"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/255171\/revisions"}],"predecessor-version":[{"id":255173,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/255171\/revisions\/255173"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/255172"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=255171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=255171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=255171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}