{"id":25534,"date":"2014-03-12T08:34:31","date_gmt":"2014-03-12T08:34:31","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=25534"},"modified":"2014-03-12T08:34:32","modified_gmt":"2014-03-12T08:34:32","slug":"arrestato-dai-carabinieri-spacciatore-di-eroina-di-galatina","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/03\/12\/arrestato-dai-carabinieri-spacciatore-di-eroina-di-galatina\/","title":{"rendered":"ARRESTATO DAI CARABINIERI SPACCIATORE DI EROINA DI GALATINA"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><strong><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/03\/DSCN1434.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/03\/DSCN1434-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" class=\"alignleft size-medium wp-image-25535\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/03\/DSCN1434-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/03\/DSCN1434.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Galatina.\u00a0<\/strong>I militari della Stazione di Galatina hanno nel pomeriggio odierna tratto in arresto, in flagranza di reato, BALDARI Leonello, classe 1977 di Galatina, con l\u2019accusa di spaccio di sostanze stupefacenti.<\/p>\n<p>I Carabinieri avevano notato il BALDARI, gi\u00e0 noto alle Forze di Polizia per precedenti specifici, continuare ad ospitare nelle sue abitazioni numerosi tossicodipendenti della zona.<\/p>\n<p>All\u2019ennesimo viavai di ragazzi, i militari della Stazione hanno deciso di intervenire nell\u2019abitazione. All\u2019interno, sdraiato sul letto, con sull\u2019addome una dose di eroina aperta in corso di consumo, vi era il BALDARI, con accanto il tossicodipendente. In mano, il BALDARI aveva cinque dosi di eroina che stava consegnando.<\/p>\n<p>La successiva perquisizione domiciliare ha invece permesso di rinvenire altre ventuno dosi di eroina, per complessivi 16.5 grammi, in un tubo per medicinali posto sotto le coperte del letto nonch\u00e9 materiale per il confezionamento, un bilancino di precisione e la somma di \u20ac 635, ritenuta dagli inquirenti frutto dell\u2019attivit\u00e0 di spaccio.<\/p>\n<p>Il BALDARI, posto in stato di arresto, su disposizione del P.M. di turno Dott.ssa BUFFELLI, \u00e8 stato tradotto nella sua abitazione, in regime di arresti domiciliari.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/03\/12\/arrestato-dai-carabinieri-spacciatore-di-eroina-di-galatina\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/03\/12\/arrestato-dai-carabinieri-spacciatore-di-eroina-di-galatina\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Galatina.\u00a0I militari della Stazione di Galatina hanno nel pomeriggio odierna tratto in arresto, in flagranza di reato, BALDARI Leonello, classe 1977 di Galatina, con l\u2019accusa di spaccio di sostanze stupefacenti. I Carabinieri avevano notato il BALDARI, gi\u00e0 noto alle Forze di Polizia per precedenti specifici, continuare ad ospitare nelle sue abitazioni numerosi tossicodipendenti della zona. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":25535,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/25534"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=25534"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/25534\/revisions"}],"predecessor-version":[{"id":25536,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/25534\/revisions\/25536"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/25535"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=25534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=25534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=25534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}