{"id":25578,"date":"2014-03-13T07:41:21","date_gmt":"2014-03-13T07:41:21","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=25578"},"modified":"2014-03-13T07:41:21","modified_gmt":"2014-03-13T07:41:21","slug":"21-rally-citta-di-casarano","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/03\/13\/21-rally-citta-di-casarano\/","title":{"rendered":"21\u00b0 RALLY CITTA&#8217; DI CASARANO"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/03\/13.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/03\/13-300x199.jpg\" alt=\"\" width=\"300\" height=\"199\" class=\"alignleft size-medium wp-image-25579\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/03\/13-300x199.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/03\/13.jpg 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Entra ufficialmente nel vivo, la 21^ edizione del Rally Citt\u00e0 di Casarano, in programma, con una veste in parte rinnovata e nuovi stimoli agonistici, per il 12 e 13 aprile 2014. Lo fa con l\u2019apertura delle iscrizioni, periodo che proseguir\u00e0 sino a domenica 6 aprile.<br \/>\nLa gara oltre ad inaugurare la stagione rallystica in terra di Puglia, vestir\u00e0 anche\u00a0 i panni di\u00a0 appuntamento di apertura sia\u00a0 del nuovo Trofeo ACI-CSAI Rally Nazionali\u00a0 5^ zona a coefficiente 1,5, sia del Trofeo Peugeot Competition di zona.<\/p>\n<p>Allegato a questa mail, il Comunicato Stampa di riferimento accompagnato da una foto free-copyright per usi giornalistici,\u00a0 che ritrae in azione l\u2019equipaggio composto da Fernando Primiceri e Martino Rosato, coppia classificatasi nel 2013 su Peugeot 207 Super2000 al secondo posto assoluto.<\/p>\n<p>La foto \u00e8 per gentile concessione di Leonardo D\u2019Angelo (gradita firma info:\u00a0<a href=\"http:\/\/www.leonardodangelo.com\/\">www.leonardodangelo.com<\/a>).<\/p>\n<p>Nel ringraziarVi ancora una volta per la Vostra preziosa collaborazione, Vi invitiamo come sempre a prendere visione del comunicato e a darne diffusione.<\/p>\n<p>Cogliamo anche\u00a0 l&#8217;occasione per ricordarVi che se avete domande specifiche sull\u2019argomento o desiderate ulteriori approfondimenti, potete inviarci le vostre domande rispondendo a questa e-mail o contattandoci telefonicamente.<\/p>\n<p>A tutti Voi Buon lavoro e un buon proseguimento di serata.<\/p>\n<p>&nbsp;<\/p>\n<p>Grazie.<\/p>\n<p>Alessandro Rizzo.<\/p>\n<h1>Ufficio Stampa Rally Citt\u00e0 di Casarano<\/h1>\n<p><strong>Alessandro Rizzo<\/strong><\/p>\n<p><strong>Tel. (+39) 328.9327457 \u2013 (+39) 329.7780609<\/strong><\/p>\n<p><strong>E mail: rizzorally@tiscali.it<\/strong><\/p>\n<div><strong><br \/>\n<\/strong><\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/03\/13\/21-rally-citta-di-casarano\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/03\/13\/21-rally-citta-di-casarano\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Entra ufficialmente nel vivo, la 21^ edizione del Rally Citt\u00e0 di Casarano, in programma, con una veste in parte rinnovata e nuovi stimoli agonistici, per il 12 e 13 aprile 2014. Lo fa con l\u2019apertura delle iscrizioni, periodo che proseguir\u00e0 sino a domenica 6 aprile. La gara oltre ad inaugurare la stagione rallystica in terra [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":25579,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/25578"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=25578"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/25578\/revisions"}],"predecessor-version":[{"id":25580,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/25578\/revisions\/25580"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/25579"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=25578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=25578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=25578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}