{"id":25586,"date":"2014-03-13T09:20:16","date_gmt":"2014-03-13T09:20:16","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=25586"},"modified":"2014-03-13T09:20:16","modified_gmt":"2014-03-13T09:20:16","slug":"via-duca-degli-abruzzi-incontro-con-il-questore","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/03\/13\/via-duca-degli-abruzzi-incontro-con-il-questore\/","title":{"rendered":"VIA DUCA DEGLI ABRUZZI, INCONTRO CON IL QUESTORE"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\">Si \u00e8 svolto questa mattina, nella sede della Questura di Lecce, l\u2019incontro richiesto dagli assessori Comunali <strong>Andrea Guido<\/strong> e <strong>Luca Pasqualini<\/strong> con il <strong>Questore Antonio Maiorano<\/strong>, in merito alle problematiche esistenti in via Duca degli Abruzzi.<\/p>\n<p>Dalla riunione di oggi \u00e8 emersa la necessit\u00e0 di prevedere un piano strategico a lungo termine da condividere con i diversi portatori di interessi. Controlli e pattugliamenti riprenderanno ad essere pi\u00f9 insistenti dalla prossima settimana ma la soluzione, secondo quanto \u00e8 emerso dalla riunione, \u00e8 da rintracciarsi in una serie di interventi complementari da realizzarsi in maniera sincronizzata su diversi livelli.<\/p>\n<p><em>\u201cIn realt\u00e0 \u2013 <\/em>ha affermato il questore <strong>Antonio Maiorano<\/strong><em> \u2013 le problematiche di ordine pubblico e sicurezza sono da addebitarsi unicamente al comportamento di pochi elementi, recidivi, emarginati e spesso indigenti, vecchie conoscenze delle forze dell\u2019ordine, i quali ormai, con le dovute eccezioni, non temono pi\u00f9 neanche l\u2019arresto in quanto nulla hanno da perdere. In questi casi forse, pi\u00f9 che un\u2019azione repressiva, sarebbe pi\u00f9 opportuno l\u2019intervento dei servizi sociali perch\u00e9 forniscano loro un aiuto ed una seconda occasione. Un pattugliamento quotidiano o la presenza fissa degli uomini in divisa funzionerebbero senza dubbio come ottimo deterrente, ma non risolverebbero il problema alla radice. Occorre invece una condivisione di mezzi e obiettivi su pi\u00f9 livelli\u201d.<\/em><\/p>\n<p>Numerose le azioni previste per cercare di individuare una soluzione definitiva al problema: provvedimenti dell\u2019Amministrazione Comunale per <strong>limitare la distribuzione delle bevande alcoliche in alcuni orari e in particolari periodi dell\u2019anno<\/strong>, <strong>controlli in divisa e in borghese<\/strong> da parte di tutte le forze dell\u2019ordine, <strong>implementazione dell\u2019illuminazione pubblica e del servizio di videosorveglianza<\/strong>, <strong>maggior attenzione da parte delle ditte affidatarie del servizio di igiene urbana<\/strong> sull\u2019area, <strong>coinvolgimento dei servizi sociali del Comune e dell\u2019Asl, dei residenti<\/strong> di via Duca degli Abruzzi, i quali devono partecipare e condividere ogni livello del piano e, infine, <strong>coinvolgimento diretto dei rappresentanti delle comunit\u00e0 straniere<\/strong> che sono solite frequentare l\u2019area.<\/p>\n<p>Nelle scorse settimane il Comitato Popolare per la salvaguardia e la tutela dell\u2019assetto e il decoro urbano di via Duca degli Abruzzi aveva trasmesso un corposo dossier sul degrado socio ambientale della stessa via. Secondo quanto riportato nel documento, firmato da numerosi residenti e titolari di attivit\u00e0 commerciali, il degrado che caratterizza l\u2019area urbana in questione ha ormai carattere di permanenza e quelli che un tempo potevano essere considerati degli episodi circoscritti e ricorrenti oggi rientrano invece nella \u201cnormalit\u00e0\u201d. Risse e violenze perpetrate da individui di ogni etnia e nazionalit\u00e0, abuso di alcool e stupefacenti, atti vandalici, molestie nei confronti di passanti e residenti, espletamento di bisogni fisiologici a cielo aperto e negli androni e nei portoni delle abitazioni sembrano essere all\u2019ordine del giorno.<\/p>\n<p><em>\u201cIn seguito al ricevimento del dossier da parte del Comitato per la salvaguardia e la tutela dell\u2019assetto e il decoro urbano di via Duca degli Abruzzi, ma, soprattutto, dopo l\u2019ultima rissa scoppiata lo scorso 15 gennaio, di concerto con il mio collega Luca Pasqualini \u2013 <\/em>ha commentato l\u2019assessore <strong>Andrea Guido<\/strong><em> &#8211; ho deciso di scrivere al Questore di Lecce per fissare un incontro. Dopo la riunione di questa mattina sono ancora pi\u00f9 convinto che per risolvere la questione occorre una strategia unica che deve coinvolgere, oltre alle forze dell\u2019ordine e gli uffici ai quali sovrintendiamo io e l\u2019assessore Pasqualini, il settore dei Servizi Sociali e gli stessi cittadini residenti di Via Duca degli Abruzzi\u201d.<\/em><\/p>\n<p><em>\u201cProveremo questa strategia complessa \u2013 <\/em>ha confermato l\u2019assessore <strong>Luca Pasqualini<\/strong> \u2013 <em>che, secondo le previsioni, potrebbe avere efficacia per ogni singolo aspetto che concorre a generare il degrado della strada in questione, ma in ogni caso, chieder\u00f2 al Comandante della Polizia Locale, Donato Zacheo &#8211; che gi\u00e0 si \u00e8 speso enormemente nel tentativo di risolvere la questione con tutti i mezzi di cui dispone &#8211; di riprendere pattugliamenti e controlli secondo un calendario preciso gi\u00e0 dalla prossima settimana. Sono convinto che le strategie emerse dalla riunione odierna possano rappresentare una soluzione al problema; se ci\u00f2 non dovesse avvenire, come ultima spiaggia, e di questo ne ho gi\u00e0 discusso con l\u2019assessore Guido, sono disposto a chiedere la riunione di un Comitato per l\u2019Ordine e la Sicurezza Pubblica\u201d.<\/em><\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/03\/13\/via-duca-degli-abruzzi-incontro-con-il-questore\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/03\/13\/via-duca-degli-abruzzi-incontro-con-il-questore\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Si \u00e8 svolto questa mattina, nella sede della Questura di Lecce, l\u2019incontro richiesto dagli assessori Comunali Andrea Guido e Luca Pasqualini con il Questore Antonio Maiorano, in merito alle problematiche esistenti in via Duca degli Abruzzi. Dalla riunione di oggi \u00e8 emersa la necessit\u00e0 di prevedere un piano strategico a lungo termine da condividere con [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/25586"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=25586"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/25586\/revisions"}],"predecessor-version":[{"id":25588,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/25586\/revisions\/25588"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=25586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=25586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=25586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}