{"id":25593,"date":"2014-03-13T11:23:46","date_gmt":"2014-03-13T11:23:46","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=25593"},"modified":"2014-03-13T13:05:35","modified_gmt":"2014-03-13T13:05:35","slug":"scoperta-impresa-di-giardinaggio-evasore-totale","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/03\/13\/scoperta-impresa-di-giardinaggio-evasore-totale\/","title":{"rendered":"SCOPERTA IMPRESA DI GIARDINAGGIO  EVASORE TOTALE"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><em><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/03\/coltivatore.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/03\/coltivatore-300x291.jpg\" alt=\"\" width=\"300\" height=\"291\" class=\"alignleft size-medium wp-image-25596\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/03\/coltivatore-300x291.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/03\/coltivatore-1024x993.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/03\/coltivatore.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>SOTTRATTI ALL\u2019ERARIO RICAVI PER<\/em><em> 486 MILA EURO\u00a0<\/em><em>E I.V.A. PER 110 MILA EURO.<br \/>\n<\/em>La Compagnia della Guardia di Finanza di Lecce ha eseguito una verifica fiscale nei confronti di una ditta individuale che esercita l\u2019attivit\u00e0 di sistemazione di parchi e giardini, scoprendo l\u2019omessa dichiarazione di ricavi per circa 486 mila Euro, I.V.A. per circa 110 mila Euro, ritenute IRPEF per 15 mila euro, ritenute previdenziali ed assistenziali INPS per 26 mila euro e contributi e premi INAIL per 5 mila euro.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019attivit\u00e0 ispettiva, che ha interessato l\u2019arco temporale dal 2009 al 2013, ha consentito di rilevare che l\u2019impresa individuale, avvalendosi anche di un lavoratore \u201cin nero\u201d, pur emettendo le fatture fiscali ai clienti, negli anni 2009 e 2010 ha presentato le dichiarazioni fiscali in maniera infedele, mentre nei periodi d\u2019imposta 2011 e 2012 ha omesso di presentare tali dichiarazioni in materia di Imposte sui redditi, I.V.A. e IRAP, sottraendosi, pertanto, al pagamento delle relative imposte.<\/p>\n<p>&nbsp;<\/p>\n<p>Anche in questo caso, l\u2019azienda sottoposta a controllo ha assunto la veste di \u201cevasore totale\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019imprenditore \u00e8 stato denunciato alla locale Autorit\u00e0 Giudiziaria in ordine al reato previsto e punito dall\u2019 art. 10 del D.Lgs. nr. 74\/2000 (Occultamento o distruzione di documenti contabili).<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/03\/13\/scoperta-impresa-di-giardinaggio-evasore-totale\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/03\/13\/scoperta-impresa-di-giardinaggio-evasore-totale\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>SOTTRATTI ALL\u2019ERARIO RICAVI PER 486 MILA EURO\u00a0E I.V.A. PER 110 MILA EURO. La Compagnia della Guardia di Finanza di Lecce ha eseguito una verifica fiscale nei confronti di una ditta individuale che esercita l\u2019attivit\u00e0 di sistemazione di parchi e giardini, scoprendo l\u2019omessa dichiarazione di ricavi per circa 486 mila Euro, I.V.A. per circa 110 mila [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":25596,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/25593"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=25593"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/25593\/revisions"}],"predecessor-version":[{"id":25595,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/25593\/revisions\/25595"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/25596"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=25593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=25593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=25593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}