{"id":256923,"date":"2026-03-20T00:05:00","date_gmt":"2026-03-19T23:05:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=256923"},"modified":"2026-03-19T15:40:58","modified_gmt":"2026-03-19T14:40:58","slug":"i-canti-di-passione-nella-grecia-salentina-da-sabato-21-marzo-a-mercoledi-1-aprile-il-programma-completo-degli-appuntamenti","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2026\/03\/20\/i-canti-di-passione-nella-grecia-salentina-da-sabato-21-marzo-a-mercoledi-1-aprile-il-programma-completo-degli-appuntamenti\/","title":{"rendered":"I &#8220;Canti di passione&#8221; NELLA GRECI&#8217;A SALENTINA DA SABATO 21 MARZO A MERCOLEDI&#8217; 1 APRILE. IL PROGRAMMA COMPLETO DEGLI APPUNTAMENTI"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1920\" height=\"1440\" class=\"wp-image-256924\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2026\/03\/provi.jpeg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2026\/03\/provi.jpeg 1920w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2026\/03\/provi-300x225.jpeg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2026\/03\/provi-1024x768.jpeg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2026\/03\/provi-768x576.jpeg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2026\/03\/provi-1536x1152.jpeg 1536w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2026\/03\/provi-400x300.jpeg 400w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/p>\n\n\n\n<p>Comunicazione istituzionale della Provincia di Lecce _______________<\/p>\n\n\n\n<p>E&#8217; stata presentata nella sala stampa di Palazzo Adorno a\u00a0<strong>Lecce<\/strong> l\u2019edizione 2026 dei\u00a0<strong>\u201cCanti di Passione &#8211; Ce Custi o Gaddho na Cantalisi\u201d<\/strong>, alla presenza del presidente della Provincia di Lecce\u00a0<strong>Fabio Tarantino<\/strong>, del presidente dell\u2019Unione dei Comuni della Grec\u00eca Salentina\u00a0<strong>Roberto Casaluci<\/strong>, della presidente dell\u2019Istituto Diego Carpitella\u00a0<strong>Valentina Avantaggiato<\/strong>, di\u00a0<strong>Graziano Vantaggiato<\/strong>\u00a0per la Fondazione Notte della Taranta, del direttore artistico di Canti di Passione\u00a0<strong>Antonio Melegari<\/strong>.<\/p>\n\n\n\n<p><strong>Dodici giorni<\/strong>&nbsp;di eventi,&nbsp;<strong>quindici appuntamenti<\/strong>&nbsp;e oltre&nbsp;<strong>trecentocinquanta artisti<\/strong>&nbsp;coinvolti. Sono questi i numeri della rassegna promossa dall\u2019<strong>Unione dei Comuni della Grec\u00eca Salentina,&nbsp;<\/strong>con la partecipazione dell\u2019<strong>Istituto Diego Carpitella&nbsp;<\/strong>e con i partner&nbsp;<strong>Fondazione La Notte della Taranta e Provincia di Lecc<\/strong><strong>e, che ha concesso il suo patrocinio<\/strong>.<\/p>\n\n\n\n<p>Diretta artisticamente da\u00a0<strong>Antonio Melegari<\/strong>, l\u2019edizione 2026, in programma\u00a0<strong>dal 21 marzo al 1\u00b0 aprile<\/strong>, propone delle novit\u00e0. Infatti, oltre ai canti, verranno promossi ancora di pi\u00f9 i luoghi e i sapori tradizionali delle comunit\u00e0 ospitanti: previsti itinerari nei borghi prima dei concerti a cura di guide turistiche e spazio ai \u201csapori\u201d con un men\u00f9 dedicato in convenzione nei paesi della Grec\u00eca Salentina.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>\u201cCanti di Passione\u201d<\/strong>, che coinvolge i dodici comuni della\u00a0<strong>Grec\u00eca Salentina<\/strong>\u00a0con delle tappe speciali a\u00a0<strong>Lecce\u00a0<\/strong>ed\u00a0<strong>Alessano<\/strong>, \u00e8 una\u00a0<strong>rassegna di canti devozionali<\/strong>, che ha inizio nella\u00a0<strong>settimana che precede la Domenica delle Palme<\/strong>\u00a0e si diffonde nei principali luoghi sacri del territorio, una vera e propria isola linguistica ellenofona del Salento. Qui, la narrazione della vita e della morte di Cristo, raggiunge una delle espressioni pi\u00f9 alte attraverso la poesia popolare grika, che si concretizza con canti, musica e gestualit\u00e0 capaci di emozionare e di creare un pathos unico. Tutto questo bagaglio ha resistito al passare del tempo e, ogni anno, si celebra nei piccoli borghi di questa terra, tra gli storici palazzi e i sagrati delle chiese, tra le piazze e gli antichi conventi che accolgono le tradizionali esibizioni di\u00a0<strong>bande musicali<\/strong>,\u00a0<strong>compagnie di cantori<\/strong>,\u00a0<strong>confraternite<\/strong>,\u00a0<strong>ragazzi delle scuole<\/strong>,\u00a0<strong>formazioni musicali<\/strong>\u00a0impegnate nello studio e la ricerca dei testi e delle musiche della Settimana Santa.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>\u201cI Canti di Passione della Grecia Salentina\u201d, ha detto il presidente della Provincia di Lecce\u00a0<strong>Fabio Tarantino,\u00a0<\/strong>\u201crappresentano uno dei patrimoni immateriali pi\u00f9 autentici e profondi del nostro territorio, espressione viva di una tradizione che affonda le sue radici nella storia, nella spiritualit\u00e0 e nell\u2019identit\u00e0 delle nostre comunit\u00e0. Si tratta di un\u2019eredit\u00e0 preziosa, tramandata di generazione in generazione, che conserva intatto il legame tra fede, lingua e cultura popolare, rendendo unico il panorama culturale salentino. In questi canti si ritrova il senso pi\u00f9 genuino della partecipazione collettiva, della devozione e della memoria condivisa: un patrimonio che non \u00e8 soltanto testimonianza del passato, ma anche strumento vivo di coesione sociale e di dialogo tra le generazioni. La Provincia di Lecce riconosce il valore inestimabile di queste tradizioni, che contribuiscono a rafforzare il senso di appartenenza e a promuovere l\u2019identit\u00e0 culturale del nostro territorio, anche oltre i confini locali. Per questo motivo, riteniamo fondamentale continuare a valorizzare tutte le iniziative volte alla tutela e alla diffusione dei Canti di Passione della Grecia Salentina, affinch\u00e9 possano essere conosciuti, apprezzati e trasmessi alle future generazioni. Investire nella salvaguardia del nostro patrimonio culturale significa investire nel futuro della nostra comunit\u00e0, nella sua capacit\u00e0 di riconoscersi nelle proprie radici e di presentarsi al mondo con una voce autentica e distintiva\u201d.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>\u201cI Canti di Passione rappresentano una delle espressioni pi\u00f9 autentiche della tradizione popolare della Grec\u00eca Salentina\u201d, ha sottolineato\u00a0<strong>Roberto Casaluci<\/strong>, presidente dell\u2019Unione dei Comuni, \u201ce continuano a vivere grazie a un impegno condiviso che, da anni, vede amministrazioni, associazioni e cantori lavorare insieme in modo sinergico. \u00c8 proprio attraverso questa rete consolidata che si rinnova e si valorizza l\u2019identit\u00e0 storica ed ellenofona dell\u2019area grika, in un dialogo continuo tra memoria e innovazione. In questa prospettiva, l\u2019Unione dei Comuni della Grec\u00eca Salentina guarda al futuro con un obiettivo chiaro: costruire un progetto capace non solo di trasmettere alle nuove generazioni il valore di questo patrimonio culturale, ma anche di attrarre un pubblico sempre pi\u00f9 ampio, oltre i confini locali, generando interesse e ricadute diffuse sul territorio\u201d.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>\u201cLa rassegna traccia la sua linea guida\u201d ha dichiarato il direttore artistico\u00a0<strong>Antonio Melegari, \u201c<\/strong>sin dall\u2019inizio per dare voce alle squadre di cantori che andavano, e vanno tuttora, di notte in giro tra le case a cantare la Passione di Cristo e soprattutto per portare avanti \u201cI Passiuna tu Christ\u00f9\u201d, considerata una delle forme pi\u00f9 antiche di teatro popolare, perch\u00e9 oltre al canto ad accompagnare le oltre sessanta strofe c\u2019\u00e8 anche tanta gestualit\u00e0 e mimica. Tra le molteplici forme di espressione musicale italiane della devozione popolare, i repertori dei Canti di Passione della Grecia Salentina, occupano un posto di assoluto rilievo\u201d.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Ecco il&nbsp;<strong>calendario completo<\/strong>&nbsp;della rassegna:<\/p>\n\n\n\n<p><strong>Sabato 21 marzo<\/strong><\/p>\n\n\n\n<p><strong>STERNATIA&nbsp;<\/strong>dalla chiesa di San Vito alla chiesa di Maria Ss. Assunta, ore 19:00<\/p>\n\n\n\n<p>\u2013 Confraternita di Minori<\/p>\n\n\n\n<p>\u2013 Famiglia De Prezzo in Lu Lazzarenu<\/p>\n\n\n\n<p>\u2013 Roberto Licci con Salvatore Cotardo, Angelo Urso, Emanuele Licci<\/p>\n\n\n\n<p>\u2013 Ast\u00e8ria di Giorgio Filieri<\/p>\n\n\n\n<p><strong>Domenica 22 marzo<\/strong><\/p>\n\n\n\n<p><strong>SOGLIANO CAVOUR&nbsp;<\/strong>Sagrato della chiesa Madre di San Lorenzo Martire, ore 11:00<\/p>\n\n\n\n<p>\u2013 Confraternita di Minori<\/p>\n\n\n\n<p>\u2013 Compagnia Gioacchino De Filippo<\/p>\n\n\n\n<p>\u2013 Primitivo trad (Canti dell\u2019area tarantina)<\/p>\n\n\n\n<p><strong>Luned\u00ec 23 marzo<\/strong><\/p>\n\n\n\n<p><strong>SOLETO&nbsp;<\/strong>dal centro storico alla chiesa Madre Maria Ss. Assunta, ore 19:30<\/p>\n\n\n\n<p>\u2013 Pierluigi Mele<\/p>\n\n\n\n<p>\u2013 Banda della Grec\u00eca Salentina<\/p>\n\n\n\n<p>\u2013 Compagnia Arakne Mediterranea<\/p>\n\n\n\n<p>\u2013 Faraualla<\/p>\n\n\n\n<p><strong>Marted\u00ec 24 marzo<\/strong><\/p>\n\n\n\n<p><strong>CORIGLIANO D\u2019OTRANTO&nbsp;<\/strong>dal Castello de\u2019 Monti alla chiesa Madre San Nicola Vescovo, ore 19:30<\/p>\n\n\n\n<p>\u2013 Concerto bandistico citt\u00e0 di Racale \u201cPompilio Librando\u201d diretto dal M\u00b0 Fulvio Palese<\/p>\n\n\n\n<p>\u2013 Argal\u00eco<\/p>\n\n\n\n<p>\u2013 Giovanni Amati e Matteo Scatigna (Valle d\u2019Itria)<\/p>\n\n\n\n<p><strong>Mercoled\u00ec 25 marzo<\/strong><\/p>\n\n\n\n<p><strong>MELPIGNANO&nbsp;<\/strong>Dal centro storico alla chiesa di San Giorgio Martire, ore 19:00<\/p>\n\n\n\n<p>\u2013 Estratto video della rassegna Passione e resurrezione (Calimera 1983)<\/p>\n\n\n\n<p><em>Archivio Luigi Chiriatti<\/em>&nbsp;\u2013 Centro Documentazione Musiche Popolari (Melpignano)<\/p>\n\n\n\n<p>\u2013 Banda della Grec\u00eca Salentina<\/p>\n\n\n\n<p>\u2013 Orchestra e Coro I.C.S. di Corigliano d\u2019Ot.\/Melpignano\/Castrignano de\u2019 Greci<\/p>\n\n\n\n<p>coordinati dai maestri Franco Bovio, Loredana Cal\u00f2, Stefano Schirosi, Ovidio Venturoso; Ref. Coro ins. Natalia Villani e con gli esperti Giovanni Campa e Salvatore Cotardo<\/p>\n\n\n\n<p>\u2013 Giovanni Palma, Luigi Marra e Ilaria Costantino<\/p>\n\n\n\n<p>\u2013 Redi Hasa e Fabrizio Saccomano<\/p>\n\n\n\n<p><strong>Gioved\u00ec 26 marzo<\/strong><\/p>\n\n\n\n<p><strong>CALIMERA&nbsp;<\/strong>Chiesa Madre, ore 19:30<\/p>\n\n\n\n<p>\u2013 Mattia e Vittorio Chittano con Giancarlo Paglialunga<\/p>\n\n\n\n<p>\u2013 Giusy Zangari e Coro Femminile VivArte<\/p>\n\n\n\n<p>\u2013 Cantori della Bottega del Teatro di Zollino<\/p>\n\n\n\n<p><strong>Venerd\u00ec 27 marzo<\/strong><\/p>\n\n\n\n<p><strong>LECCE&nbsp;<\/strong>dalla chiesa Greca alla chiesa di San Giovanni Evangelista, ore 17:00<\/p>\n\n\n\n<p>\u2013 Ast\u00e8ria di Giorgio Filieri<\/p>\n\n\n\n<p>\u2013 Compagnia de Lu Santu Lazzaru<\/p>\n\n\n\n<p><strong>Venerd\u00ec 27 marzo<\/strong><\/p>\n\n\n\n<p><strong>CASTRIGNANO DEI GRECI&nbsp;<\/strong>dal Palazzo de Gualtieris alla chiesa Maria Ss. Annunziata<\/p>\n\n\n\n<p>ore 17:30<\/p>\n\n\n\n<p>\u2013 Laboratorio di studi<\/p>\n\n\n\n<p>Cantare il sacro: testo e performance dei canti di questua nel periodo pasquale.<\/p>\n\n\n\n<p>Saluti di Roberto Casaluci (Presidente Unione dei Comuni della Grec\u00eca Salentina).<\/p>\n\n\n\n<p>Introduce e coordina Francesco G. Giannachi (UniSalento)<\/p>\n\n\n\n<p>Intervengono: Francesco Aventaggiato (UniSalento); Antonello Ricci (\u201cSapienza\u201d Universit\u00e0 di<\/p>\n\n\n\n<p>Roma).<\/p>\n\n\n\n<p>ore 19:30<\/p>\n\n\n\n<p>\u2013 Confraternite di Vico del Gargano<\/p>\n\n\n\n<p>\u2013 Compagnia Fiore Maggiulli<\/p>\n\n\n\n<p>\u2013 Passi\u00f9na a cura dell\u2019Orchestra Popolare La Notte della Taranta<\/p>\n\n\n\n<p>\u2013 Ast\u00e8ria di Giorgio Filieri<\/p>\n\n\n\n<p><strong>Sabato 28 marzo<\/strong><\/p>\n\n\n\n<p><strong>CUTROFIANO<\/strong><\/p>\n\n\n\n<p>Ore 10:00 Lu Santu Lazzaru tra le scuole<\/p>\n\n\n\n<p>Ore 19:30 Sagrato della Chiesa Madre<\/p>\n\n\n\n<p>36^ RASSEGNA SANTU LAZZARU<\/p>\n\n\n\n<p>Antonio Castrignan\u00f2, Luigi Marra, Giovanni Palma, Ilaria Costantino, Arakne Mediterranea, Compagnia di Salvino, Famiglia Cavalera, Michela Sicuro, Compagnia Giuseppe Lisi, Compagnia Paiano, Cantori della Bottega del Teatro di Zollino, Compagnia Melegari-Stefanizzi, Lina Bandello, Famiglia Giagnotti, Compagnia Fiore Maggiulli, Famiglia Zimba<\/p>\n\n\n\n<p>Coro dell\u2019I.C.S. \u201cDon Bosco\u201d Sogliano C.\/Cutrofiano coordinati da Mattia Manco<\/p>\n\n\n\n<p>Dalle ore 22:00<\/p>\n\n\n\n<p>Lu Santu Lazzaru tra le case con le Compagnie di Cutrofiano<\/p>\n\n\n\n<p><strong>Domenica 29 marzo<\/strong><\/p>\n\n\n\n<p><strong>MARTANO&nbsp;<\/strong>Piazza Assunta, dalle ore 9:30<\/p>\n\n\n\n<p>\u2013 Banda di Sogliano Cavour<\/p>\n\n\n\n<p>\u2013 Famiglia Giagnotti<\/p>\n\n\n\n<p>\u2013 Cantori di Martano<\/p>\n\n\n\n<p>\u2013 Trio a Modo (Lazio)<\/p>\n\n\n\n<p><strong>ZOLLINO&nbsp;<\/strong>Sagrato della Chiesa SS. Pietro e Paolo Apostoli, ore 11:30<\/p>\n\n\n\n<p>\u2013 Cantori di Galatina<\/p>\n\n\n\n<p>\u2013 Cantori della Bottega del Teatro di Zollino<\/p>\n\n\n\n<p><strong>Luned\u00ec 30 marzo<\/strong><\/p>\n\n\n\n<p><strong>CARPIGNANO&nbsp;<\/strong>Cripta di Santa Cristina, ore 18:00<\/p>\n\n\n\n<p>\u2013 Kantal\u00ecsomo \u2013 Le voci della Passione a cura dell\u2019Orchestra Popolare La Notte della Taranta<\/p>\n\n\n\n<p><strong>SERRANO (fraz. di Carpignano<a href=\"http:\/\/s.no\/\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;S.no<\/a>)&nbsp;<\/strong>Chiesa San Giorgio Martire, ore 19:30<\/p>\n\n\n\n<p>\u2013 Compagnia Arakne Mediterranea<\/p>\n\n\n\n<p>\u2013 Antonio Castrignan\u00f2 e Luigi Marra con Giorgio Distante, Rocco Nigro e Giuseppe Spedicato<\/p>\n\n\n\n<p><strong>Marted\u00ec 31 marzo<\/strong><\/p>\n\n\n\n<p><strong>ALESSANO&nbsp;<\/strong>Convento dei Frati Minori Cappuccini, ore 19:30<\/p>\n\n\n\n<p>\u2013 Cantori di Alezio<\/p>\n\n\n\n<p>\u2013 Tis Klei di Ninfa Giannuzzi con Emanuele Licci e Giuseppe Spedicato<\/p>\n\n\n\n<p><strong>Mercoled\u00ec 1 aprile 2026<\/strong><\/p>\n\n\n\n<p><strong>MARTIGNANO<\/strong><em><strong>&nbsp;<\/strong><\/em><em>a cura della Coop. Soc. Open di Parco Palmieri in collaborazione con la Compagnia Arakne Mediterranea<\/em><\/p>\n\n\n\n<p>Dalle ore 9:00 alle 12:30 Per le vie e case del paese e presso la Scuola Primaria e Secondaria di Primo Grado con Arakne Mediterranea e i cantori di Martignano.<\/p>\n\n\n\n<p>Ore 19:30 &#8211; dal sagrato della chiesa S. Maria dei Martiri a Piazza Palmieri<\/p>\n\n\n\n<p>\u2013 Compagnia Arakne Mediterranea e i cantori di Martignano<\/p>\n\n\n\n<p>\u2013 Famiglia Giagnotti.<\/p>\n\n\n\n<p>\u2013 Anna Cinzia Villani e il coro di Losanna<\/p>\n\n\n\n<p>\u2013 Famiglia Greco<\/p>\n\n\n\n<p>\u2013 Rocco De Santis e Mattia Manco<\/p>\n\n\n\n<p>\u2013 Cantori della Bottega del Teatro di Zollino<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>ITINERARI TRA PIETRA, MEMORIA E SPIRITUALIT\u00c0<\/strong><\/p>\n\n\n\n<p>In occasione della rassegna&nbsp;<strong>CANTI DI PASSIONE \u2013&nbsp;<\/strong><em><strong>Ce custi o gaddho na cantal\u00ecsi<\/strong><\/em>, sono proposti percorsi tematici guidati nei borghi del Salento. Gli itinerari attraversano centri storici, chiese e luoghi simbolici legati ai riti della Settimana Santa, intrecciando architetture, devozione popolare e cultura&nbsp;<em>grica<\/em>&nbsp;in un\u2019esperienza immersiva che racconta l\u2019identit\u00e0 profonda del territorio. L\u2019Associazione Culturale&nbsp;<strong>In Punta di Tacco APS<\/strong>&nbsp;accompagna il pubblico alla scoperta dei \u201cBorghi della Passione\u201d, con un programma di visite guidate che segue di tappa in tappa il&nbsp;<strong>calendario dei canti<\/strong>, attraversando i luoghi che ospitano riti e tradizioni. Le visite, condotte in italiano da guide abilitate dalla regione Puglia, sono a&nbsp;<strong>PARTECIPAZIONE GRATUITA con prenotazione obbligatoria<\/strong>&nbsp;(nome e cognome) via WhatsApp al numero 3780677478 entro le 24 ore prima dell\u2019evento.<\/p>\n\n\n\n<p>Ecco tutte le tappe:<\/p>\n\n\n\n<p><strong>STERNATIA<\/strong><\/p>\n\n\n\n<p><em>Ore 17.30<\/em><\/p>\n\n\n\n<p>Dalla Chiesa di San Vito alla Chiesa Madre, un cammino tra frantoi ipogei, palazzi storici e piazze simbolo della cultura&nbsp;<em>grica<\/em>&nbsp;e della vita comunitaria.<\/p>\n\n\n\n<p>\u2013 Frantoio Ipogeo<\/p>\n\n\n\n<p>\u2013Palazzo Granafei<\/p>\n\n\n\n<p>\u2013 Porta Fil\u00eca<\/p>\n\n\n\n<p>\u2013 Piazza Umberto I<\/p>\n\n\n\n<p>\u2013 Chiostro dei domenicani (sede del palazzo comunale)<\/p>\n\n\n\n<p>\u2013 Chiesa Maria Ss. Assunta<\/p>\n\n\n\n<p><strong>SOGLIANO CAVOUR<\/strong><\/p>\n\n\n\n<p><em>Ore 10.00<\/em><\/p>\n\n\n\n<p>Tra sagrati e architetture baronali, un percorso raccolto in Grec\u00eca, dove il canto dialoga con la pietra e la memoria religiosa del paese.<\/p>\n\n\n\n<p>\u2013 Palazzo baronale<\/p>\n\n\n\n<p>\u2013 Chiesa San Lorenzo<\/p>\n\n\n\n<p>\u2013 Chiesa di Maria Ss. Annunziata<\/p>\n\n\n\n<p><strong>SOLETO<\/strong><\/p>\n\n\n\n<p><em>Ore 18.00<\/em><\/p>\n\n\n\n<p>Un cammino di grande valore artistico tra porte, cappelle e la Guglia di Raimondello, simbolo di bellezza e spiritualit\u00e0.<\/p>\n\n\n\n<p>\u2013 Chiesa di Santo Stefano<\/p>\n\n\n\n<p>\u2013 Santuario Madonna delle Grazie<\/p>\n\n\n\n<p>\u2013 Casa di Mastteo Tafuri<\/p>\n\n\n\n<p>\u2013 Porta San Vito<\/p>\n\n\n\n<p>\u2013 Chiesa Maria Ss. dell\u2019Assunta e Guglia di Raimondello<\/p>\n\n\n\n<p><strong>CORIGLIANO D\u2019OTRANTO<\/strong><\/p>\n\n\n\n<p><em>Ore 18.00<\/em><\/p>\n\n\n\n<p>Porte, archi e castello guidano un itinerario nel centro fortificato della Grec\u00eca, dove sacro e storia si intrecciano.<\/p>\n\n\n\n<p>\u2013 Ca porta<\/p>\n\n\n\n<p>\u2013 Castello de\u2019 Monti<\/p>\n\n\n\n<p>\u2013 Arco Lucchetti<\/p>\n\n\n\n<p>\u2013 Torre dell\u2019orologio<\/p>\n\n\n\n<p>\u2013 Chiesa Madre<\/p>\n\n\n\n<p><strong>MELPIGNANO<\/strong><\/p>\n\n\n\n<p>a cura del Comune di Melpignano<\/p>\n\n\n\n<p><em>Ore 17.30<\/em><\/p>\n\n\n\n<p>Un\u2019originale visita guidata lungo il sentiero delle cappelle, alla scoperta degli antichi riti pasquali.<\/p>\n\n\n\n<p>\u2013 Piazza San Giorgio<\/p>\n\n\n\n<p>\u2013 Cappella di San Rocco<\/p>\n\n\n\n<p>\u2013 Cappella di San Michele Arcangelo<\/p>\n\n\n\n<p>\u2013 Cappella della Madonna di Costantinopoli<\/p>\n\n\n\n<p><strong>CALIMERA<\/strong><\/p>\n\n\n\n<p><em>Ore 18.00<\/em><\/p>\n\n\n\n<p>Un itinerario della memoria tra museo, cappelle e Chiesa Madre, che restituisce i gesti del mondo contadino e la tradizione&nbsp;<em>grica<\/em>&nbsp;ancora viva.<\/p>\n\n\n\n<p>\u2013 Casa-Museo della civilt\u00e0 contadina e della cultura&nbsp;<em>grica<\/em><\/p>\n\n\n\n<p>\u2013 Cappella del Crocifisso<\/p>\n\n\n\n<p>\u2013 Chiesa Madre<\/p>\n\n\n\n<p>\u2013 Chiesa di San Brizio<\/p>\n\n\n\n<p><strong>CASTRIGNANO DE\u2019 GRECI<\/strong><\/p>\n\n\n\n<p><em>Ore 17.00<\/em><\/p>\n\n\n\n<p>Dal palazzo storico alla chiesa madre, un itinerario in cui la cultura&nbsp;<em>grica<\/em>&nbsp;dialoga con il presente e l\u2019arte contemporanea.<\/p>\n\n\n\n<p>\u2013 Pozzelle<\/p>\n\n\n\n<p>\u2013 Palazzo De Gualtieris<\/p>\n\n\n\n<p>\u2013 Cripta Sant\u2019Onofrio<\/p>\n\n\n\n<p>\u2013 Chiesa Immacolata<\/p>\n\n\n\n<p>\u2013 Chiesa Madre<\/p>\n\n\n\n<p><strong>CUTROFIANO<\/strong><\/p>\n\n\n\n<p><em>Ore 18.00<\/em><\/p>\n\n\n\n<p>Un itinerario tra palazzi, chiese e luoghi dell\u2019artigianato, dove la devozione incontra la memoria del lavoro manuale.<\/p>\n\n\n\n<p>\u2013 Palazzo Filomarini (o Palazzo della Principessa)<\/p>\n\n\n\n<p>\u2013 Chiesa dell\u2019Immacolata<\/p>\n\n\n\n<p>\u2013 Chiesa Matrice dedicata a Santa Maria della Neve<\/p>\n\n\n\n<p>\u2013 Museo della ceramica<\/p>\n\n\n\n<p><strong>MARTANO<\/strong><\/p>\n\n\n\n<p><em>Ore 10.00<\/em><\/p>\n\n\n\n<p>Tra piazze, torri e palazzi baronali, il canto diventa espressione pubblica di fede e identit\u00e0.<\/p>\n\n\n\n<p>\u2013 Palazzo baronale<\/p>\n\n\n\n<p>\u2013 Torrione del castello<\/p>\n\n\n\n<p>\u2013 Chiesa matrice<\/p>\n\n\n\n<p>\u2013 Torre dell\u2019orologio<\/p>\n\n\n\n<p><strong>ZOLLINO<\/strong><\/p>\n\n\n\n<p>Tra cappelle, piazze e sagrati, un percorso essenziale e autentico che custodisce una tradizione religiosa ancora fortemente condivisa.<\/p>\n\n\n\n<p>\u2013 Largo pozzelle<\/p>\n\n\n\n<p>\u2013 Piazza San Pietro<\/p>\n\n\n\n<p>\u2013 Pisello nano \/ Piazza Pertini<\/p>\n\n\n\n<p>\u2013 Chiesa Madre<\/p>\n\n\n\n<p><strong>CARPIGNANO SALENTINO e fraz. di SERRANO<\/strong><\/p>\n\n\n\n<p><em>Ore 18.00<\/em><\/p>\n\n\n\n<p>Tra palazzi storici, torri civiche e Chiesa di San Giorgio Martire, il canto rafforza il senso di comunit\u00e0 di un piccolo borgo.<\/p>\n\n\n\n<p>\u2013 Cripta di Santa Cristina<\/p>\n\n\n\n<p>\u2013 Palazzo Lubelli<\/p>\n\n\n\n<p>\u2013 Chiesa matrice di San Giorgio<\/p>\n\n\n\n<p><strong>ALESSANO<\/strong><\/p>\n\n\n\n<p><em>Ore 18.30<\/em><\/p>\n\n\n\n<p>Dal centro storico al Convento dei Cappuccini, un percorso di silenzio e spiritualit\u00e0 nella terra di don Tonino Bello.<\/p>\n\n\n\n<p>\u2013 Chiesa madre di San Salvatore<\/p>\n\n\n\n<p>\u2013 Palazzo Legari<\/p>\n\n\n\n<p>\u2013 Piazza don Tonino Bello<\/p>\n\n\n\n<p>\u2013 Torre dell\u2019orologio<\/p>\n\n\n\n<p><strong>MARTIGNANO<\/strong><\/p>\n\n\n\n<p>a cura della Coop. Soc. Open di Parco Palmieri,<\/p>\n\n\n\n<p><em>Ore 17.30<\/em><\/p>\n\n\n\n<p>Un percorso raccolto tra piazza, frantoio ipogeo e chiese, che racconta la dimensione intima del pi\u00f9 piccolo borgo della Grec\u00eca.<\/p>\n\n\n\n<p>\u2013 Palazzo Palmieri<\/p>\n\n\n\n<p>\u2013 Frantoio ipogeo<\/p>\n\n\n\n<p>\u2013 Cappella di San Giovanni Battista<\/p>\n\n\n\n<p>\u2013 Chiesa Madre<\/p>\n\n\n\n<p><strong>A TAVOLA PRIMA DELLA PASQUA NEL SALENTO CON IL<\/strong>&nbsp;<strong>MEN\u00d9 DELLA PASSIONE<\/strong><\/p>\n\n\n\n<p>In collaborazione con la rete di ristoratori locali, viene proposto un menu che celebra la tradizione contadina, la cucina povera e di magro, tipica del periodo quaresimale. Un men\u00f9 completo a prezzo fisso, che prevede antipasti, primi, secondi, contorni e dolci quaresimali. In occasione della Rassegna \u201cCanti di Passione\u201d dal 21 marzo al 1 Aprile 2026, l\u2019Unione dei Comuni della Grec\u00eca Salentina promuove anche un percorso enogastronomico legato alla cucina quaresimale del territorio. I ristoratori aderenti propongono nel periodo della rassegna, un men\u00f9 dedicato a prezzo convenzionato ispirato alla tradizione locale.<\/p>\n\n\n\n<p><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2026\/03\/20\/i-canti-di-passione-nella-grecia-salentina-da-sabato-21-marzo-a-mercoledi-1-aprile-il-programma-completo-degli-appuntamenti\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2026\/03\/20\/i-canti-di-passione-nella-grecia-salentina-da-sabato-21-marzo-a-mercoledi-1-aprile-il-programma-completo-degli-appuntamenti\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Comunicazione istituzionale della Provincia di Lecce _______________ E&#8217; stata presentata nella sala stampa di Palazzo Adorno a\u00a0Lecce l\u2019edizione 2026 dei\u00a0\u201cCanti di Passione &#8211; Ce Custi o Gaddho na Cantalisi\u201d, alla presenza del presidente della Provincia di Lecce\u00a0Fabio Tarantino, del presidente dell\u2019Unione dei Comuni della Grec\u00eca Salentina\u00a0Roberto Casaluci, della presidente dell\u2019Istituto Diego Carpitella\u00a0Valentina Avantaggiato, di\u00a0Graziano Vantaggiato\u00a0per [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":256924,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31,75],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/256923"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=256923"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/256923\/revisions"}],"predecessor-version":[{"id":256925,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/256923\/revisions\/256925"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/256924"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=256923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=256923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=256923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}