{"id":258910,"date":"2026-05-07T13:07:39","date_gmt":"2026-05-07T11:07:39","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=258910"},"modified":"2026-05-07T13:08:28","modified_gmt":"2026-05-07T11:08:28","slug":"gallipoli-giovane-immigrato-egiziano-arrestato-per-furto-con-strappo","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2026\/05\/07\/gallipoli-giovane-immigrato-egiziano-arrestato-per-furto-con-strappo\/","title":{"rendered":"GALLIPOLI, GIOVANE IMMIGRATO EGIZIANO ARRESTATO PER FURTO CON STRAPPO"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"690\" height=\"600\" class=\"wp-image-247291\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/volanti_polizia.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/volanti_polizia.jpg 690w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/volanti_polizia-300x261.jpg 300w\" sizes=\"(max-width: 690px) 100vw, 690px\" \/><\/p>\n\n\n\n<p>(Rdl) ______________ <\/p>\n\n\n\n<p>Domenica corsa 3 maggio agenti del Commissariato di  Galatina in servizio di controllo del territorio hanno arrestato il presunto responsabile di un furto con strappo avvenuto pochi minuti prima nel centro di Gallipoli. <\/p>\n\n\n\n<p>Erano circa le 22.15 quando una pattuglia delle Volanti \u00e8 stata inviata a Gallipoli in seguito ad una richiesta di aiuto giunta sul numero unico di emergenza 112.<\/p>\n\n\n\n<p>Giunti sul posto hanno contattato il richiedente, un giovane di 22 anni, nato e residente in Germania e in vacanza nel Salento insieme ai genitori, che aveva appena subito un furto con strappo della collana d\u2019oro che indossava, ad opera di un ragazzo poi fuggito tra le vie della citt\u00e0.<\/p>\n\n\n\n<p>La reazione della vittima e del padre \u00e8 stata immediata. I due hanno inseguito il ladro riuscendo a raggiungerlo. Ne \u00e8 scaturita una colluttazione, durante la quale il tedesco ha riportato lesioni successivamente giudicate guaribili in cinque giorni. Nonostante ci\u00f2, sono riusciti a trattenerlo fino all\u2019arrivo della Polizia.<\/p>\n\n\n\n<p>Gli agenti hanno immediatamente recuperato e restituito la collanina al legittimo proprietario. Il responsabile del furto \u00e8 stato identificato come cittadino egiziano di 19 anni, incensurato e regolare sul territorio nazionale. Inoltre gli \u00e8 stato trovato addosso un coltellino multiuso, immediatamente sequestrato.<\/p>\n\n\n\n<p>E&#8217; stato quindi arrestato per rapina e posto ai domiciliari, come disposto dal pm di turno presso la Procura della Repubblica di Lecce. Il gip del Tribunale di Lecce all&#8217;udienza di convalida dell&#8217;arresto ha infine disposto per lui l&#8217;obbligo di dimora nel Comune di Presicce\/Acquarica.<\/p>\n\n\n\n<p><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2026\/05\/07\/gallipoli-giovane-immigrato-egiziano-arrestato-per-furto-con-strappo\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2026\/05\/07\/gallipoli-giovane-immigrato-egiziano-arrestato-per-furto-con-strappo\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(Rdl) ______________ Domenica corsa 3 maggio agenti del Commissariato di Galatina in servizio di controllo del territorio hanno arrestato il presunto responsabile di un furto con strappo avvenuto pochi minuti prima nel centro di Gallipoli. Erano circa le 22.15 quando una pattuglia delle Volanti \u00e8 stata inviata a Gallipoli in seguito ad una richiesta di [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":247291,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/258910"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=258910"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/258910\/revisions"}],"predecessor-version":[{"id":258911,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/258910\/revisions\/258911"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/247291"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=258910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=258910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=258910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}