{"id":2599,"date":"2012-07-09T10:07:08","date_gmt":"2012-07-09T10:07:08","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=2599"},"modified":"2012-07-09T10:13:08","modified_gmt":"2012-07-09T10:13:08","slug":"pisano-coordinatore-politico-di-perrone","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2012\/07\/09\/pisano-coordinatore-politico-di-perrone\/","title":{"rendered":"Pisan\u00f2 coordinatore politico di Perrone"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/07\/09\/pisano-coordinatore-politico-di-perrone\/pisano_coordinatore_politico\/\" rel=\"attachment wp-att-2603\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/07\/Pisano_coordinatore_politico.jpg\" alt=\"\" title=\"Pisano_coordinatore_politico\" width=\"300\" height=\"206\" class=\"alignnone size-full wp-image-2603\" \/><\/a><\/p>\n<p>Eugenio Pisan\u00f2, che alle recenti elezioni si \u00e8 presentato con la lista La Puglia prima di tutto senza riuscire fra gli eletti, ha avuto da Paolo Perrone l\u2019incarico, di natura politica, di coordinatore delle attivit\u00e0 del consiglio comunale, delle commissioni consiliari, della giunta e dei capigruppo consiliari. Pisan\u00f2 avr\u00e0 il compito, dunque, di relazionare esclusivamente al sindaco.<\/p>\n<p>L\u2019incarico sar\u00e0 espletato a titolo gratuito.<\/p>\n<p>Il provvedimento del primo cittadino scaturisce dalla sua esigenza di avere un supporto e un maggior raccordo tra gli organi istituzionali al fine di attuare gli indirizzi programmatici di governo.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2012\/07\/09\/pisano-coordinatore-politico-di-perrone\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/07\/09\/pisano-coordinatore-politico-di-perrone\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>&nbsp; Eugenio Pisan\u00f2, che alle recenti elezioni si \u00e8 presentato con la lista La Puglia prima di tutto senza riuscire fra gli eletti, ha avuto da Paolo Perrone l\u2019incarico, di natura politica, di coordinatore delle attivit\u00e0 del consiglio comunale, delle commissioni consiliari, della giunta e dei capigruppo consiliari. Pisan\u00f2 avr\u00e0 il compito, dunque, di relazionare [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2603,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/2599"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=2599"}],"version-history":[{"count":7,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/2599\/revisions"}],"predecessor-version":[{"id":2606,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/2599\/revisions\/2606"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/2603"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=2599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=2599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=2599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}