{"id":2630,"date":"2012-07-09T11:00:54","date_gmt":"2012-07-09T11:00:54","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=2630"},"modified":"2012-07-09T11:00:56","modified_gmt":"2012-07-09T11:00:56","slug":"irregolarita-dei-pubblici-esercizi-nelloccupazione-del-suolo-pubblico","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2012\/07\/09\/irregolarita-dei-pubblici-esercizi-nelloccupazione-del-suolo-pubblico\/","title":{"rendered":"Irregolarit\u00e0 dei pubblici esercizi nell\u2019occupazione del suolo pubblico"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/07\/09\/irregolarita-dei-pubblici-esercizi-nelloccupazione-del-suolo-pubblico\/tavolini_sedie_aperto_lecce_comune-300x259\/\" rel=\"attachment wp-att-2631\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/07\/Tavolini_sedie_aperto_lecce_comune-300x259.jpg\" alt=\"\" title=\"Tavolini_sedie_aperto_lecce_comune-300x259\" width=\"300\" height=\"259\" class=\"alignnone size-full wp-image-2631\" \/><\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019Amministrazione Comunale di Lecce ha deciso di coinvolgere gli esercenti dei pubblici esercizi per affrontare serenamente la questione relativa all\u2019occupazione di suolo pubblico all\u2019aperto da parte di bar, ristoranti e pub di Lecce.<\/p>\n<p>La decisione di aprire il confronto con le categorie produttive \u00e8 stata assunta dall\u2019assessore Luciano Battista in seguito alle numerose infrazioni riscontrare dai vigili urbani di Lecce nei locali cittadini. In particolare sono state registrate numerose difformit\u00e0 riguardo all\u2019occupazione del suolo pubblico, ritenuta superiore a quanto autorizzato agli interessati, alla mancata esposizione degli orari di apertura e chiusura dei locali e delle relative autorizzazioni.<\/p>\n<p>Nel corso dell\u2019incontro l\u2019assessore Battista ha invitato i rappresentanti di Confcommercio e Confesercenti a garantire il rispetto delle regole per evitare di incorrere in pesanti sanzioni da parte dell\u2019Amministrazione Comunale.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2012\/07\/09\/irregolarita-dei-pubblici-esercizi-nelloccupazione-del-suolo-pubblico\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/07\/09\/irregolarita-dei-pubblici-esercizi-nelloccupazione-del-suolo-pubblico\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>&nbsp; L\u2019Amministrazione Comunale di Lecce ha deciso di coinvolgere gli esercenti dei pubblici esercizi per affrontare serenamente la questione relativa all\u2019occupazione di suolo pubblico all\u2019aperto da parte di bar, ristoranti e pub di Lecce. La decisione di aprire il confronto con le categorie produttive \u00e8 stata assunta dall\u2019assessore Luciano Battista in seguito alle numerose infrazioni [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2631,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/2630"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=2630"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/2630\/revisions"}],"predecessor-version":[{"id":2634,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/2630\/revisions\/2634"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/2631"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=2630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=2630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=2630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}