{"id":26377,"date":"2014-03-27T11:56:16","date_gmt":"2014-03-27T11:56:16","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=26377"},"modified":"2014-03-27T11:56:16","modified_gmt":"2014-03-27T11:56:16","slug":"abusi-edilizi-nel-territorio-di-salve","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/03\/27\/abusi-edilizi-nel-territorio-di-salve\/","title":{"rendered":"ABUSI EDILIZI NEL TERRITORIO DI SALVE"},"content":{"rendered":"<p>\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 20%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\t\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-26377 gallery-columns-5 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2014\/03\/27\/abusi-edilizi-nel-territorio-di-salve\/finanza-13\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/03\/finanza-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2014\/03\/27\/abusi-edilizi-nel-territorio-di-salve\/finanza1-2\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/03\/finanza1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n<br \/>\nI proprietari sono stati denunciati all\u2018Autorit\u00e0 Giudiziaria.<br \/>\nI Finanzieri della Tenenza di Leuca hanno individuato due cantieri nel comune di Salve dove si stavano realizzando abitazioni abusive in un\u2019area ambientale di pregio sottoposta a vincolo paesaggistico.<br \/>\nNel primo caso, \u00e8 stata scoperta un\u2019abitazione realizzata in modo difforme rispetto al permesso a costruire rilasciato, con l\u2019edificazione di porticati e vani accessori non autorizzati per complessivi mq. 60.<br \/>\nNell\u2019altro, \u00e8 stato rilevato che una tipica \u201cpaiara\u201d, per la quale erano state concesse le autorizzazioni per la ristrutturazione secondo le tradizionali tecniche, cio\u00e8 a secco, stava per essere trasformata in una confortevole civile abitazione per le vacanze, mediante l\u2019utilizzo di conci di tufo e cemento.<br \/>\nTrattandosi di opere abusive in aree vincolate paesaggisticamente, i militari, informata l\u2019Autorit\u00e0 Giudiziaria, hanno proceduto al loro sequestro, denunciando i rispettivi proprietari, uno residente in provincia di Milano e l\u2019altro in provincia di Campobasso, per violazione alle norme in materia edilizia ed ambientale.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/03\/27\/abusi-edilizi-nel-territorio-di-salve\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/03\/27\/abusi-edilizi-nel-territorio-di-salve\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>I proprietari sono stati denunciati all\u2018Autorit\u00e0 Giudiziaria. I Finanzieri della Tenenza di Leuca hanno individuato due cantieri nel comune di Salve dove si stavano realizzando abitazioni abusive in un\u2019area ambientale di pregio sottoposta a vincolo paesaggistico. Nel primo caso, \u00e8 stata scoperta un\u2019abitazione realizzata in modo difforme rispetto al permesso a costruire rilasciato, con l\u2019edificazione [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/26377"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=26377"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/26377\/revisions"}],"predecessor-version":[{"id":26380,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/26377\/revisions\/26380"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=26377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=26377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=26377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}