{"id":26457,"date":"2014-03-28T11:39:14","date_gmt":"2014-03-28T11:39:14","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=26457"},"modified":"2014-03-28T11:39:14","modified_gmt":"2014-03-28T11:39:14","slug":"la-polizia-provinciale-rende-noto-il-piano-di-prevenzione-con-autovelox","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/03\/28\/la-polizia-provinciale-rende-noto-il-piano-di-prevenzione-con-autovelox\/","title":{"rendered":"LA POLIZIA PROVINCIALE RENDE NOTO  IL PIANO DI PREVENZIONE CON AUTOVELOX"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/09\/Autovelox-Telelaser-controllo-velocita.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/09\/Autovelox-Telelaser-controllo-velocita.jpg\" alt=\"\" width=\"187\" height=\"253\" class=\"alignleft size-full wp-image-20275\" \/><\/a>I CALENDARI DEL MESE DI APRILE<br \/>\nSono disponibili i calendari dei controlli sulle strade provinciali a cura della Polizia Provinciale, tramite autovelox e telelaser, relativi al mese di aprile.<br \/>\nAnche per il prossimo mese di aprile saranno attive delle <strong>postazioni fisse<\/strong> <strong>24 ore su 24<\/strong> su alcuni tratti della strada provinciale Otranto-San Cataldo.<\/p>\n<p><strong>CALENDARIO POSTAZIONI FISSE APRILE 2014<\/strong><\/p>\n<p align=\"center\">\n<p>&nbsp;<\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"94\">\n<p align=\"center\"><strong>\u00a0<\/strong><\/p>\n<p align=\"center\">Tutti i giorni festivi compresi<\/p>\n<p align=\"center\"><strong>\u00a0<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"297\">\n<p align=\"center\">S.P.\u00a0 366<\/p>\n<p align=\"center\">OTRANTO \u2013 SAN CATALDO<\/p>\n<h3>Km. 27+942 in direzione Otranto<\/h3>\n<p align=\"center\">Km. 27+083\u00a0 in direzione San Cataldo<strong><\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"98\">\n<p align=\"center\"><strong>\u00a0<\/strong><\/p>\n<p align=\"center\">00:00 \u2013 24:00<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table width=\"504\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td colspan=\"3\" valign=\"top\" width=\"504\">\n<h5 align=\"center\"><span style=\"text-decoration: underline\">CALENDARIO TELELASER APRILE 2014<\/span><\/h5>\n<p><span style=\"text-decoration: underline\">A CURA DELLA POLIZIA PROVINCIALE<\/span><\/p>\n<p align=\"center\">\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\">\n<p align=\"center\">01-04-2014<\/p>\n<\/td>\n<td valign=\"top\" width=\"270\">\n<p align=\"center\">S.P.\u00a0 367<\/p>\n<h5 align=\"center\">LECCE &#8211; MAGLIE<\/h5>\n<\/td>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\">\n<p align=\"center\">06,00 \u2013 13,00<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\">\n<p align=\"center\">03-04-2014<\/p>\n<\/td>\n<td valign=\"top\" width=\"270\">\n<p align=\"center\">S.P.\u00a0 119<\/p>\n<h5 align=\"center\">LEVERANO &#8211; LECCE<\/h5>\n<\/td>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\">\n<p align=\"center\">13,00 \u2013 20,00<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\">\n<p align=\"center\">04-04-2014<\/p>\n<\/td>\n<td valign=\"top\" width=\"270\">\n<p align=\"center\">S.P.\u00a0 112<\/p>\n<p align=\"center\">VILLAGGIO RESTA<\/p>\n<\/td>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\">\n<p align=\"center\">06,00 \u2013 13,00<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\">\n<p align=\"center\">07-04-2014<\/p>\n<\/td>\n<td valign=\"top\" width=\"270\">\n<p align=\"center\">S.P.\u00a0 359<\/p>\n<h3>NARDO\u2019 &#8211; AVETRANA<\/h3>\n<\/td>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\">\n<p align=\"center\">06,00 \u2013 13,00<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\">\n<p align=\"center\">09-04-2014<\/p>\n<\/td>\n<td valign=\"top\" width=\"270\">\n<p align=\"center\">S.P.\u00a0 13<\/p>\n<h5 align=\"center\">CARMIANO &#8211; NOVOLI<\/h5>\n<\/td>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\">\n<p align=\"center\">13,00 \u2013 20,00<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\">\n<p align=\"center\">10-04-2014<\/p>\n<\/td>\n<td valign=\"top\" width=\"270\">\n<h3>S.P.\u00a0 71<\/h3>\n<h3>RUFFANO &#8211; CASARANO<\/h3>\n<\/td>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\">\n<p align=\"center\">06,00 \u2013 13,00<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\">\n<p align=\"center\">12-04-2014<\/p>\n<h1><\/h1>\n<\/td>\n<td valign=\"top\" width=\"270\">\n<p align=\"center\">S.P.\u00a0 133<\/p>\n<h3>FRIGOLO &#8211; CASALABATE<\/h3>\n<\/td>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\">\n<p align=\"center\">13,00 \u2013 20,00<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\">\n<p align=\"center\">14-04-2014<\/p>\n<h1><\/h1>\n<\/td>\n<td valign=\"top\" width=\"270\">\n<p align=\"center\">S.P.\u00a0 119<\/p>\n<h3>LEVERANO &#8211; LECCE<\/h3>\n<\/td>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\">\n<p align=\"center\">06,00 \u2013 13,00<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\">\n<p align=\"center\">15-04-2014<\/p>\n<h1><\/h1>\n<\/td>\n<td valign=\"top\" width=\"270\">\n<p align=\"center\">S.P.\u00a0 367<\/p>\n<h3>LECCE &#8211; MAGLIE<\/h3>\n<\/td>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\">\n<p align=\"center\">13,00 \u2013 20,00<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\">\n<p align=\"center\">16-04-2014<\/p>\n<h1><\/h1>\n<\/td>\n<td valign=\"top\" width=\"270\">\n<h3>S.P.\u00a0 20<\/h3>\n<h3>DALLA S.S. 101 A COPERTINO<\/h3>\n<\/td>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\">\n<p align=\"center\">06,00 \u2013 13,00<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\">\n<p align=\"center\">18-04-2014<\/p>\n<h1><\/h1>\n<\/td>\n<td valign=\"top\" width=\"270\">\n<p align=\"center\">S.P.\u00a0 112<\/p>\n<h3>VILLAGGIO RESTA<\/h3>\n<\/td>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\">\n<p align=\"center\">13,00 \u2013 20,00<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\">\n<p align=\"center\">19-04-2014<\/p>\n<h1><\/h1>\n<\/td>\n<td valign=\"top\" width=\"270\">\n<p align=\"center\">S.P.\u00a0 13<\/p>\n<h3>CARMIANO &#8211; NOVOLI<\/h3>\n<\/td>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\">\n<p align=\"center\">06,00 \u2013 13,00<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\">\n<p align=\"center\">22-04-2014<\/p>\n<h1><\/h1>\n<\/td>\n<td valign=\"top\" width=\"270\">\n<p align=\"center\">S.P.\u00a0 06<\/p>\n<h3>MONTERONI &#8211; COPERTINO<\/h3>\n<\/td>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\">\n<p align=\"center\">06,00 \u2013 13,00<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\">\n<p align=\"center\">24-04-2014<\/p>\n<h1><\/h1>\n<\/td>\n<td valign=\"top\" width=\"270\">\n<p align=\"center\">S.P.\u00a0 71<\/p>\n<h3>RUFFANO &#8211; CASARANO<\/h3>\n<\/td>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\">\n<p align=\"center\">13,00 \u2013 20,00<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\">\n<p align=\"center\">28-04-2014<\/p>\n<h1><\/h1>\n<\/td>\n<td valign=\"top\" width=\"270\">\n<p align=\"center\">S.P.\u00a0 367<\/p>\n<h3>LECCE &#8211; MAGLIE<\/h3>\n<\/td>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\">\n<p align=\"center\">06,00 \u2013 13,00<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\">\n<p align=\"center\">30-04-2014<\/p>\n<\/td>\n<td valign=\"top\" width=\"270\">\n<p align=\"center\">S.P.\u00a0 133<\/p>\n<p align=\"center\">FRIGOLE &#8211; CASALABATE<\/p>\n<\/td>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\">\n<p align=\"center\">13,00 &#8211; 20,00<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"94\">\n<p align=\"center\"><strong>\u00a0<\/strong><\/p>\n<p align=\"center\"><strong>\u00a0<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"297\">\n<h5 align=\"center\"><span style=\"text-decoration: underline\">CALENDARIO AUTOVELOX APRILE 2014<\/span><\/h5>\n<p align=\"center\"><strong><span style=\"text-decoration: underline\">A CURA DELLA POLIZIA PROVINCIALE<\/span><\/strong><\/p>\n<p align=\"center\"><strong>\u00a0<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"98\">\n<p align=\"center\"><strong>\u00a0<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"94\">\n<p align=\"center\">\n<p align=\"center\">01-04-2014<\/p>\n<\/td>\n<td valign=\"top\" width=\"297\">\n<p align=\"center\">S.P.\u00a0 363<\/p>\n<p align=\"center\">SANTA CESAREA T. &#8211; MAGLIE<\/p>\n<h6 align=\"center\">DAL KM 25+670\u00a0 AL KM 31+670<\/h6>\n<\/td>\n<td valign=\"top\" width=\"98\">\n<p align=\"center\">\n<p align=\"center\">06,00 \u2013 13,00<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"94\">\n<p align=\"center\">\n<p align=\"center\">03-04-2014<\/p>\n<\/td>\n<td valign=\"top\" width=\"297\">\n<p align=\"center\">S.P.\u00a0 21<\/p>\n<p align=\"center\">LEVERANO \u2013 PORTO CESAREO<\/p>\n<p align=\"center\">DAL KM 2 AL KM 5<\/p>\n<\/td>\n<td valign=\"top\" width=\"98\">\n<p align=\"center\">\n<p align=\"center\">13,00 &#8211; 20,00<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"94\">\n<p align=\"center\">\n<p align=\"center\">04-04-2014<\/p>\n<\/td>\n<td valign=\"top\" width=\"297\">\n<p align=\"center\">S.P.\u00a0 90<\/p>\n<p align=\"center\">GALATONE \u2013 S.M. AL BAGNO<\/p>\n<p align=\"center\">DAL KM 3 AL KM 4<\/p>\n<p align=\"center\">dal limite dell\u2019abitato di Galatone<\/p>\n<\/td>\n<td valign=\"top\" width=\"98\">\n<p align=\"center\">\n<p align=\"center\">06,00 &#8211; 13,00<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"94\">\n<p align=\"center\">\n<p align=\"center\">07-04-2014<\/p>\n<\/td>\n<td valign=\"top\" width=\"297\">\n<p align=\"center\">S.P.\u00a0 362<\/p>\n<p align=\"center\">LECCE &#8211; GALATINA<\/p>\n<h3>DAL KM 9 AL KM 10<\/h3>\n<\/td>\n<td valign=\"top\" width=\"98\">\n<p align=\"center\">\n<p align=\"center\">06,00 &#8211; 13,00<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"94\">\n<p align=\"center\">\n<p align=\"center\">09-04-2014<\/p>\n<\/td>\n<td valign=\"top\" width=\"297\">\n<p align=\"center\">S.P.\u00a0 05<\/p>\n<p align=\"center\">LECCE &#8211; NOVOLI<\/p>\n<h3>DAL KM 1\u00a0 AL KM 2<\/h3>\n<h3>dal limite dell\u2019abitato di Lecce<\/h3>\n<\/td>\n<td valign=\"top\" width=\"98\">\n<p align=\"center\">\n<p align=\"center\">13,00 &#8211; 20,00<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"94\">\n<p align=\"center\">\n<p align=\"center\">10-04-2014<\/p>\n<\/td>\n<td valign=\"top\" width=\"297\">\n<p align=\"center\">S.P.\u00a0 174<\/p>\n<p align=\"center\">SUPERSANO &#8211; CASARANO<\/p>\n<p align=\"center\">DAL KM 4\u00a0 AL KM 5<\/p>\n<p align=\"center\">dal limite dell\u2019abitato di Supersano<\/p>\n<\/td>\n<td valign=\"top\" width=\"98\">\n<p align=\"center\">\n<p align=\"center\">06,00 &#8211; 13,00<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"94\">\n<p align=\"center\">\n<p align=\"center\">12-04-2014<\/p>\n<\/td>\n<td valign=\"top\" width=\"297\">\n<p align=\"center\">S.P.\u00a0 06<\/p>\n<p align=\"center\">LECCE &#8211; MONTERONI<\/p>\n<p align=\"center\">DAL KM 0 AL KM 1<\/p>\n<\/td>\n<td valign=\"top\" width=\"98\">\n<p align=\"center\">\n<p align=\"center\">13,00 &#8211; 20,00<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"94\">\n<p align=\"center\">\n<p align=\"center\">14-04-2014<\/p>\n<\/td>\n<td valign=\"top\" width=\"297\">\n<p align=\"center\">S.P.\u00a0 21<\/p>\n<p align=\"center\">LEVERANO \u2013 PORTO CESAREO<\/p>\n<p align=\"center\">DAL KM 2\u00a0 AL KM\u00a0 5<\/p>\n<\/td>\n<td valign=\"top\" width=\"98\">\n<p align=\"center\">\n<p align=\"center\">06,00 -13,00<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"94\">\n<p align=\"center\">\n<p align=\"center\">15-04-2014<\/p>\n<\/td>\n<td valign=\"top\" width=\"297\">\n<p align=\"center\">S.P.\u00a0 363<\/p>\n<h2 align=\"center\">MAGLIE \u2013 SANTA CESAREA T.<\/h2>\n<p align=\"center\">DAL KM 25+670 AL KM 31+670<\/p>\n<\/td>\n<td valign=\"top\" width=\"98\">\n<p align=\"center\">\n<p align=\"center\">13,00 \u2013 20,00<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"94\">\n<p align=\"center\">\n<p align=\"center\">16-04-2014<\/p>\n<\/td>\n<td valign=\"top\" width=\"297\">\n<p align=\"center\">S.P.\u00a0 362<\/p>\n<h3>LECCE &#8211; GALATINA<\/h3>\n<p align=\"center\">DAL KM 9 AL KM 10<\/p>\n<\/td>\n<td valign=\"top\" width=\"98\">\n<p align=\"center\">\n<p align=\"center\">06,00 \u2013 13,00<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"94\">\n<p align=\"center\">\n<p align=\"center\">18-04-2014<\/p>\n<\/td>\n<td valign=\"top\" width=\"297\">\n<p align=\"center\">S.P.\u00a0 90<\/p>\n<p align=\"center\">S.M. AL BAGNO &#8211; GALATONE<\/p>\n<h3>DAL KM 1 AL KM 2<\/h3>\n<p align=\"center\">dal limite dell\u2019abitato di S.M. al Bagno<\/p>\n<\/td>\n<td valign=\"top\" width=\"98\">\n<p align=\"center\">\n<p align=\"center\">13,00 &#8211; 20,00<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"94\">\n<p align=\"center\">\n<p align=\"center\">19-04-2014<\/p>\n<\/td>\n<td valign=\"top\" width=\"297\">\n<p align=\"center\">S.P.\u00a0 04<\/p>\n<p align=\"center\">NOVOLI &#8211; LECCE<\/p>\n<h6 align=\"center\">DAL KM 5 AL KM 6<\/h6>\n<p align=\"center\">dal limite dell\u2019abitato di Novoli<\/p>\n<\/td>\n<td valign=\"top\" width=\"98\">\n<p align=\"center\">\n<p align=\"center\">06,00 &#8211; 13,00<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"94\">\n<p align=\"center\">\n<p align=\"center\">22-04-2014<\/p>\n<\/td>\n<td valign=\"top\" width=\"297\">\n<p align=\"center\">S.P.\u00a0 06<\/p>\n<p align=\"center\">LECCE &#8211; MONTERONI<\/p>\n<p align=\"center\">DAL KM 0 AL KM 1<\/p>\n<\/td>\n<td valign=\"top\" width=\"98\">\n<p align=\"center\">\n<p align=\"center\">06,00 &#8211; 13,00<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"94\">\n<p align=\"center\">\n<p align=\"center\">24-04-2014<\/p>\n<\/td>\n<td valign=\"top\" width=\"297\">\n<p align=\"center\">S.P.\u00a0 174<\/p>\n<p align=\"center\">CASARANO &#8211; SUPERSANO<\/p>\n<h3>DAL KM 1 AL KM 2<\/h3>\n<p align=\"center\">dal limite dell\u2019abitato di Casarano<\/p>\n<\/td>\n<td valign=\"top\" width=\"98\">\n<p align=\"center\">\n<p align=\"center\">13,00 &#8211; 20,00<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"94\">\n<p align=\"center\">\n<p align=\"center\">28-04-2014<\/p>\n<\/td>\n<td valign=\"top\" width=\"297\">\n<p align=\"center\">S.P.\u00a0 363<\/p>\n<p align=\"center\">SANTA CESAREA T. &#8211; MAGLIE<\/p>\n<h3>DAL KM 25+670\u00a0 AL KM 31+670<\/h3>\n<\/td>\n<td valign=\"top\" width=\"98\">\n<p align=\"center\">\n<p align=\"center\">06,00 &#8211; 13,00<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"94\">\n<p align=\"center\">\n<p align=\"center\">30-04-2014<\/p>\n<p align=\"center\">\n<\/td>\n<td valign=\"top\" width=\"297\">\n<p align=\"center\">S.P.\u00a0 21<\/p>\n<p align=\"center\">LEVERANO \u2013 PORTO CESAREO<\/p>\n<p align=\"center\">DAL KM 2 AL KM 5<\/p>\n<\/td>\n<td valign=\"top\" width=\"98\">\n<p align=\"center\">\n<p align=\"center\">13,00 &#8211; 20,00<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/03\/28\/la-polizia-provinciale-rende-noto-il-piano-di-prevenzione-con-autovelox\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/03\/28\/la-polizia-provinciale-rende-noto-il-piano-di-prevenzione-con-autovelox\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>I CALENDARI DEL MESE DI APRILE Sono disponibili i calendari dei controlli sulle strade provinciali a cura della Polizia Provinciale, tramite autovelox e telelaser, relativi al mese di aprile. Anche per il prossimo mese di aprile saranno attive delle postazioni fisse 24 ore su 24 su alcuni tratti della strada provinciale Otranto-San Cataldo. CALENDARIO POSTAZIONI [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":20275,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/26457"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=26457"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/26457\/revisions"}],"predecessor-version":[{"id":26459,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/26457\/revisions\/26459"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/20275"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=26457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=26457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=26457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}