{"id":2648,"date":"2012-07-09T15:46:04","date_gmt":"2012-07-09T15:46:04","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=2648"},"modified":"2012-11-15T17:14:25","modified_gmt":"2012-11-15T17:14:25","slug":"tormentoni-estivi-p40-e-biagio-antonacci","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2012\/07\/09\/tormentoni-estivi-p40-e-biagio-antonacci\/","title":{"rendered":"Tormentoni estivi- P40 e Biagio Antonacci"},"content":{"rendered":"<p>Tormentoni estivi- P40 e Biagio Antonacci<\/p>\n<p>di\u00a0 Rdl<\/p>\n<p>Ce n\u2019\u00e8 uno in dialetto, almeno al titolo di tormentone musicale dell\u2019estate aspira ardentemente, anche se non lo \u00e8 ancora diventato: \u201dMe tira na friseddhra\u201d, del cantautore P40, per l\u2019anagrafe Pasquale Quaranta; ma con l\u2019impegno dei giovani studenti del \u201cCosta\u201d e una programmazione assicurata dai lidi dei due mari nei prossimi giorni sicuramente si far\u00e0 notare, anche per il suo messaggio subliminale di corretta alimentazione.<\/p>\n<p>Ce n\u2019\u00e8 un altro che si \u00e8 gi\u00e0 fatto notare, anche se pare una furba operazione di marketing commerciale, con quel finale esplicito, dopo le protagoniste femminili pi\u00f9 modelle, che autentiche interpreti salentine.<\/p>\n<p>Biagio Antonacci scopre e far\u00e0 scoprire la pizzica a chi ancora non la conosce nel brano musicale e relativo video \u201cNon vivo pi\u00f9 senza te\u201d, una canzone che racconta il viaggio nel Salento di un innamorato che per dimenticare una delusione trascorre una vacanza nel Salento e sfoga i suoi dolori chiss\u00e0 quanto giovani con la scoperta di nuiovi ritmi e nuovi pensieri.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2012\/07\/09\/tormentoni-estivi-p40-e-biagio-antonacci\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/07\/09\/tormentoni-estivi-p40-e-biagio-antonacci\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Tormentoni estivi- P40 e Biagio Antonacci di\u00a0 Rdl Ce n\u2019\u00e8 uno in dialetto, almeno al titolo di tormentone musicale dell\u2019estate aspira ardentemente, anche se non lo \u00e8 ancora diventato: \u201dMe tira na friseddhra\u201d, del cantautore P40, per l\u2019anagrafe Pasquale Quaranta; ma con l\u2019impegno dei giovani studenti del \u201cCosta\u201d e una programmazione assicurata dai lidi dei [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/2648"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=2648"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/2648\/revisions"}],"predecessor-version":[{"id":6493,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/2648\/revisions\/6493"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=2648"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=2648"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=2648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}