{"id":26602,"date":"2014-03-29T09:54:49","date_gmt":"2014-03-29T09:54:49","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=26602"},"modified":"2014-03-29T09:58:36","modified_gmt":"2014-03-29T09:58:36","slug":"i-canti-della-passione","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/03\/29\/i-canti-della-passione\/","title":{"rendered":"SALENTO: I CANTI DELLA PASSIONE"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/03\/280_0_3629136_389222.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/03\/280_0_3629136_389222.jpg\" alt=\"\" title=\"280_0_3629136_389222\" width=\"194\" height=\"244\" class=\"alignleft size-full wp-image-26605\" \/><\/a>Dal\u00a0<strong>5 al 13 aprile<\/strong>, nella settimana antecedente la domenica delle Palme, tornano i<strong>\u00a0\u201cCanti di Passione<\/strong>\u201d, canti devozionali\u00a0 in lingua grica e dialettale che ripropongono in sequenza gli ultimi toccanti momenti di vita di Ges\u00f9. Quest\u2019anno, per la prima volta, la Fondazione \u201c<em>La Notte della Taranta<\/em>\u201d coordina il progetto, voluto anche da\u00a0<em>Regione Puglia, Unione di Comuni della Grec\u00eca Salentina e Istituto Diego Carpitella.<\/em>\u00a0Sedici tappe che coinvolgeranno le principali chiese della\u00a0<span style=\"text-decoration: underline;\">Grec\u00eca Salentina, Lecce, Alessano e\u00a0 Palmariggi.<\/span>L\u2019antichissima tradizione grica, nata dalla fusione di musica, canti e gestualit\u00e0 mimica,\u00a0 di fortissimo impatto emotivo, incontrer\u00e0 i riti della Settimana Santa\u00a0 di altri luoghi della Puglia e del resto d\u2019Italia.\u00a0<strong>L\u2019Arciconfraternita del SS Sacramento di Minori<\/strong>, in Campania, proporr\u00e0 nel Salento il canto plurisecolare che il pio sodalizio proveniente dalla costiera amalfitana\u00a0 ha cura di tramandare. Dalla Puglia arriveranno, tra gli altri, i\u00a0<strong>Cantori del Venerd\u00ec Santo di Grumo Appula, le Confraternite di Vico del Gargano<\/strong>\u00a0che intoneranno i canti pi\u00f9 rappresentativi e suggestivi dei riti pasquali. Dalla Sardegna, tradizione e devozione con i \u201c<strong>Su Concurdu de C\u00f9glieri<\/strong>\u201d coro di musica antica, polivocale, tradizionale composto da voci maschili \u00a0che in occasione della rassegna \u201cCanti di Passione\u201d proporr\u00e0\u00a0 la liturgia della Settima Santa che C\u00f9glieri, conserva intatta come pochi paesi dell\u2019isola. Accanto ai gruppi provenienti dal resto d\u2019Italia ci saranno numerosi cantori locali e gruppi storici della musica popolare salentina che da anni portano avanti l\u2019attivit\u00e0 di recupero e valorizzazione di questo importante patrimonio linguistico, artistico e culturale legato a \u201c<em>I Passi\u00f9na tu Christ\u00f9<\/em>\u201d e a \u201c<em>Santu Lazzaru<\/em>\u201d. Nella tappa conclusiva di Zollino, a chiusura del ricco programma dei \u201cCanti di Passione\u201d, un suggestivo finale con<strong>Antimo Pellegrino<\/strong>, uno dei cantori pi\u00f9 anziani della Grec\u00eca Salentina, depositario dell\u2019autenticit\u00e0 di questa \u00a0antica tradizione che insieme ai Cantori della Bottega del Teatro di Zollino \u00a0metter\u00e0 in scena \u201cI Passiuna tu Christ\u00f9\u201d, la testimonianza pi\u00f9 alta, per la comunit\u00e0 di Zollino, \u00a0della propria identit\u00e0 grica.\u00a0 Da segnalare sempre nell\u2019ultima tappa, la<strong>Messa laica per Don Tonino Bello di Michele Lobaccaro<\/strong>. L\u2019autore e musicista dei Radiodervish ha voluto fare un omaggio al vescovo\u00a0sempre in prima linea per la pace e la lotta ad ogni forma di emarginazione attraverso un progetto musicale ispirato agli scritti pi\u00f9 poetici di Don Tonino. Ospiti speciali di Lobaccaro:\u00a0<strong>Nabil\u00a0 Salameh, Alessia Tondo, Antonio Castrignan\u00f2, Claudio Prima.<\/strong><\/p>\n<p>La direzione artistica della rassegna di musica legata ai riti della Pasqua \u00e8 affidata a:\u00a0<strong>Luigi Chiriatti, Gianni De Santis eSergio Torsello,\u00a0<\/strong>con la consulenza di\u00a0<strong>Antonio Melegari<\/strong>.<\/p>\n<p><em>\u201cLa Fondazione \u201cLa Notte della Taranta\u201d ha voluto riprendere e rivitalizzare queste tradizioni del periodo pasquale dalla secolare valenza culturale e religiosa, per ridare impulso\u00a0 ad un patrimonio culturale di valore inestimabile. Accanto agli anziani cantori della tradizione ci sono giovani musicisti, segno tangibile di come questa eredit\u00e0\u00a0 si tramandi di generazione in generazione. Non mancano\u00a0in questa edizione, gli scambi culturali con altri luoghi \u00a0d\u2019Italia che hanno vissuto e vivono con fede, fervore e senso di appartenenza i riti pasquali.\u201d\u00a0<\/em>E\u2019 quanto afferma il presidente della Fondazione\u201d La Notte della Taranta<strong>\u201d Massimo Manera<\/strong>.<\/p>\n<div><\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/03\/29\/i-canti-della-passione\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/03\/29\/i-canti-della-passione\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Dal\u00a05 al 13 aprile, nella settimana antecedente la domenica delle Palme, tornano i\u00a0\u201cCanti di Passione\u201d, canti devozionali\u00a0 in lingua grica e dialettale che ripropongono in sequenza gli ultimi toccanti momenti di vita di Ges\u00f9. Quest\u2019anno, per la prima volta, la Fondazione \u201cLa Notte della Taranta\u201d coordina il progetto, voluto anche da\u00a0Regione Puglia, Unione di Comuni [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":26605,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/26602"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=26602"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/26602\/revisions"}],"predecessor-version":[{"id":26604,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/26602\/revisions\/26604"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/26605"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=26602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=26602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=26602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}