{"id":26916,"date":"2014-04-04T06:31:12","date_gmt":"2014-04-04T06:31:12","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=26916"},"modified":"2014-04-04T06:31:12","modified_gmt":"2014-04-04T06:31:12","slug":"bere-a-go-go-quando-lidiozia-si-fa-moda","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/04\/bere-a-go-go-quando-lidiozia-si-fa-moda\/","title":{"rendered":"BERE A GO GO&#8217;. QUANDO L&#8217;IDIOZIA SI FA MODA."},"content":{"rendered":"<p><strong><span style=\"font-family: 'Times New Roman'; font-size: small;\"><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/Donna-ubriaca.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/Donna-ubriaca-300x200.jpg\" alt=\"\" title=\"Donna-ubriaca\" width=\"300\" height=\"200\" class=\"alignleft size-medium wp-image-26918\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/Donna-ubriaca-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/Donna-ubriaca.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\u00abNeknomination\u00bb. L\u2019assurda moda di bere alcol a go go sfidandosi sui social network. Dall\u2019Inghilterra\u00a0<\/span><\/strong><strong>arriva la prima\u00a0denuncia contro Facebook per il caso di una ragazza di 9 anni.<\/strong><br \/>\n<span style=\"font-family: 'Times New Roman'; font-size: small;\">Lo \u201c<a href=\"http:\/\/www.sportellodeidiritti.org\/\" target=\"_blank\">Sportello dei Diritti<\/a>\u201d, \u00e8 stata tra le prime associazioni in Italia a denunciare l\u2019assurda moda diffusa rapidamente tra i giovani nota con l\u2019apparente innocuo nomignolo di \u00abNekNomination\u00bb.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman'; font-size: small;\">In realt\u00e0 si tratta di una sorta di sfida alcolica che i giovani si lanciano attraverso i social network mettendo alla prova la propria resistenza agli alcolici, birra su tutti, sino allo stremo.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman'; font-size: small;\">Ed ora per Facebook sembra sia arrivata la prima denuncia. Sono stati i genitori della piccola Rhiannon Scully, di appena nove anni d\u2019et\u00e0, a rivolgersi alle autorit\u00e0 dopo che la bimba era stata ricoverata in ospedale e sottoposta ad un lavaggio gastrico dopo aver bevuto una combinazione di vodka e whisky.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman'; font-size: small;\">\u00c8 stata la madre della ragazzina che ha chiesto a Facebook di rimuovere i video di questo \u201cgioco\u201d, mentre gli inquirenti britannici starebbero gi\u00e0 indagando per la morte di quattro persone associate a questa pratica.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman'; font-size: small;\">La madre di Rhiannon ha lanciato un appello chiedendo l\u2019immediata rimozione di ogni contenuto video di questo tipo dichiarando espressamente che: \u00abi video del NekNomination dovrebbero essere vietati per proteggere i bambini\u00bb.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman'; font-size: small;\">Un appello che Giovanni D&#8217;Agata, presidente dello \u201c<a href=\"http:\/\/www.sportellodeidiritti.org\/\" target=\"_blank\">Sportello dei Diritti<\/a>\u201d, rilancia anche in Italia rivolgendosi ai responsabili del social network.<\/span><\/p>\n<p><span style=\"font-family: Arial; font-size: x-small;\">\u00a0<\/span><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/04\/bere-a-go-go-quando-lidiozia-si-fa-moda\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/04\/bere-a-go-go-quando-lidiozia-si-fa-moda\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>\u00abNeknomination\u00bb. L\u2019assurda moda di bere alcol a go go sfidandosi sui social network. Dall\u2019Inghilterra\u00a0arriva la prima\u00a0denuncia contro Facebook per il caso di una ragazza di 9 anni. Lo \u201cSportello dei Diritti\u201d, \u00e8 stata tra le prime associazioni in Italia a denunciare l\u2019assurda moda diffusa rapidamente tra i giovani nota con l\u2019apparente innocuo nomignolo di \u00abNekNomination\u00bb. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":26918,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/26916"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=26916"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/26916\/revisions"}],"predecessor-version":[{"id":26919,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/26916\/revisions\/26919"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/26918"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=26916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=26916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=26916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}