{"id":26973,"date":"2014-04-05T06:46:23","date_gmt":"2014-04-05T06:46:23","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=26973"},"modified":"2014-04-05T06:46:23","modified_gmt":"2014-04-05T06:46:23","slug":"malaria-a-rischio-anche-litalia","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/05\/malaria-a-rischio-anche-litalia\/","title":{"rendered":"MALARIA A RISCHIO ANCHE L&#8217;ITALIA"},"content":{"rendered":"<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div>\n<div title=\"\">\n<div>\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div title=\"\" dir=\"ltr\">\n<div>\n<div>\n<p><span style=\"font-family: 'Times New Roman'; font-size: small;\"><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/Malaria.png\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/Malaria-300x148.png\" alt=\"\" title=\"Malaria\" width=\"300\" height=\"148\" class=\"alignleft size-medium wp-image-26974\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/Malaria-300x148.png 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/Malaria.png 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>La pi\u00f9 nota malaria, ma anche la dengue e la febbre chikungunya continuano ad essere introdotte in Europa dai viaggiatori.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman'; font-size: small;\">L&#8217;Organizzazione Mondiale della Sanit\u00e0 (OMS) mette in guardia contro i rischi delle malattie esotiche.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman'; font-size: small;\">Le malattie esotiche come la febbre chikungunya possono sostanzialmente colpire i viaggiatori imprudenti e diffondersi a causa delle temperature sempre pi\u00f9 elevate in Europa.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman'; font-size: small;\">A segnalare i nuovi pericoli mercoled\u00ec scorso \u00e8 stato l&#8217;Ufficio Regionale dell&#8217;Organizzazione Mondiale della Sanit\u00e0 (OMS) a Copenhagen.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman'; font-size: small;\">La Chikungunya si verifica in genere nei tropici, ed \u00e8 causa, tra le altre cose, di dolori muscolari e articolari. Il rischio di punture di zanzare, flebotomi e zecche riguarda circa 77.000 persone in 53 paesi della regione europea globale che sono colpiti ogni anno da queste cosiddette malattie trasmesse da vettori.\u00a0 Molti vettori come le zanzare o le zecche succhiano il sangue degli animali.\u00a0<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman'; font-size: small;\">Tra il 1990 e il 2010, ben 1,5 milioni di persone sono state colpite, secondo l&#8217;OMS.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman'; font-size: small;\">In occasione della \u201cGiornata mondiale della salute\u201d dell\u2019anno corrente che si terr\u00e0 il prossimo 7 aprile l\u2019attenzione \u00e8 portata proprio sulle malattie trasmesse da vettori tale.\u00a0<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman'; font-size: small;\">Nel 2012 la febbre dengue ha colpito Madeira l\u2019isola portoghese a largo dell\u2019Atlantico.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman'; font-size: small;\">Secondo Zsuzsanna Jakab, Direttore Regionale OMS &#8220;Ci sono chiari avvertimenti per la regione europea che le malattie trasmesse da vettori si diffonder\u00e0 di pi\u00f9 nei prossimi anni&#8221;.\u00a0<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman'; font-size: small;\">In Europa vi \u00e8 il rischio di una epidemia di febbre dengue . &#8220;Nel 2012 ci sono stati, sull&#8217;isola portoghese di Madeira un primo focolaio (&#8230;) con oltre 2000 casi&#8221;.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman'; font-size: small;\">Cos\u00ec, malattie come la malaria, dengue o febbre chikungunya non dovrebbero essere cos\u00ec diffuse in Europa e avrebbe dovuto essere specificamente impedite e frenate, secondo l&#8217;Ufficio Regionale dell&#8217;OMS.\u00a0<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman'; font-size: small;\">In tal senso, lo scopo dell\u2019istituzione delle Nazioni Unite \u00e8 quello di educare le persone e sensibilizzare il personale medico. Il progetto si basa su una scala di sette anni di azioni, a cui i 53 paesi della regione europea hanno concordato fine del 2013.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman'; font-size: small;\">Sono anni, ricorda Giovanni D&#8217;Agata, presidente dello \u201c<a href=\"http:\/\/www.sportellodeidiritti.org\/\" target=\"_blank\">Sportello dei Diritti<\/a>\u201d, che con la nostra associazione da anni cerchiamo di sensibilizzare turisti e viaggiatori circa i rischi di contagio delle malattie tropicali, ed\u00a0<a href=\"https:\/\/webmaildomini.aruba.it\/ext_aruba\/classic\/html\/mainframe.html?_v_=v4r2b20.20140218_0903?lang=it&amp;flavour=orange&amp;theme=ext_aruba\/classic&amp;useSprite=0\">oggi<\/a>\u00a0troviamo un\u2019importante conferma nell\u2019azione dell\u2019OMS che porta alla ribalta i pericoli per milioni di cittadini europei che potrebbero derivare dalla scarsa informazione circa queste patologie anche, purtroppo, nell\u2019ambiente sanitario.<\/span><\/p>\n<p><span style=\"font-family: Arial; font-size: x-small;\">\u00a0<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/05\/malaria-a-rischio-anche-litalia\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/05\/malaria-a-rischio-anche-litalia\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>La pi\u00f9 nota malaria, ma anche la dengue e la febbre chikungunya continuano ad essere introdotte in Europa dai viaggiatori. L&#8217;Organizzazione Mondiale della Sanit\u00e0 (OMS) mette in guardia contro i rischi delle malattie esotiche. Le malattie esotiche come la febbre chikungunya possono sostanzialmente colpire i viaggiatori imprudenti e diffondersi a causa delle temperature sempre pi\u00f9 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":26974,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/26973"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=26973"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/26973\/revisions"}],"predecessor-version":[{"id":26975,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/26973\/revisions\/26975"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/26974"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=26973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=26973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=26973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}