{"id":26979,"date":"2014-04-05T06:51:32","date_gmt":"2014-04-05T06:51:32","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=26979"},"modified":"2014-04-05T06:51:32","modified_gmt":"2014-04-05T06:51:32","slug":"sistemiamo-la-famiglia","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/05\/sistemiamo-la-famiglia\/","title":{"rendered":"SISTEMIAMO LA FAMIGLIA"},"content":{"rendered":"<p style=\"text-align: left;\" align=\"center\"><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/FAMIGLIA.jpeg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/FAMIGLIA.jpeg\" alt=\"\" title=\"FAMIGLIA\" width=\"228\" height=\"221\" class=\"alignleft size-full wp-image-21207\" \/><\/a>Un convegno nazionale per discutere sulle politiche familiari. Appuntamento luned\u00ec 7 aprile, alle ore 9, alle Officine Cantelmo. Tra i relatori anche il professor Stefano Zamagni, delegato a realizzare una legge quadro sulla famiglia.<br \/>\n<strong>Luned\u00ec 7 aprile, alle ore 9, a Lecce, alle Officine Cantelmo (viale Michele De Pietro, 12), si aprir\u00e0 il convegno nazionale dal titolo <em>\u201cSistemiamo la famiglia \u2013 Comuni e politiche familiari innovative. Linee guida metodologie e buone prassi di welfare e dimensione locale\u201d.<\/em><\/strong><\/p>\n<p>Si tratta di un momento di riflessione e di confronto tra gli attori istituzionali, i rappresentanti del Terzo settore e gli studiosi, ma anche un laboratorio dove generare proposte e idee innovative per rimettere la famiglia al centro delle Istituzioni e della Politica, un compito demandato ai gruppi di lavoro che si confronteranno nella fase pomeridiana del convegno.<\/p>\n<p>L\u2019evento \u00e8 stato presentato questa mattina a Palazzo Carafa alla presenza del<strong><em> <\/em><\/strong>\u00a0vicesindaco e assessore ai Servizi Sociali,<strong> Carmen<\/strong> <strong>Tessitore, <\/strong>del<strong> <\/strong>professor<strong> Luigi Spedicato<\/strong>, presidente del Consiglio didattico in Servizio Sociale<strong> <\/strong>dell\u2019Universit\u00e0 del Salento, del direttore artistico di Lecce 2019, <strong>Airan Berg<\/strong>, del vicepresidente dell\u2019Istituto Antonacci di Lecce, <strong>Tony Donno<\/strong>, del consigliere dell\u2019Ordine degli Assistenti Sociali, <strong>Chiara Greco <\/strong>e della dirigente del settore Servizi Sociali del Comune di Lecce, <strong>Annamaria Perulli<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>Nel convegno si vuol fare emergere le linee-guida da seguire per una evoluzione delle politiche familiari capace di guardare alla famiglia come sistema generatore di ricchezza relazionale. Da questo punto di vista i Comuni dovranno svolgere un ruolo fondamentale per dare risposte ai bisogni della famiglia in una prospettiva sinergica tra l\u2019ente locale, le associazioni e i diversi soggetti del territorio. Per raggiungere un ottimo livello di buone prassi nel campo delle politiche familiari occorre, dunque, ripartire \u201cdal basso\u201d, cio\u00e8 dalle realt\u00e0 locali.<em> <\/em><\/p>\n<p>A fare gli onori di casa sar\u00e0 il sindaco <strong>Paolo Perrone<\/strong><em>: \u201cCome dice giustamente Papa Francesco, \u2018la famiglia \u00e8 il motore del mondo e della storia, il luogo dove si impara ad amare, il centro naturale della vita umana\u2019. Ma per troppi anni \u00e8 stata dimenticata, relegata ad un ruolo marginale, tirata in ballo inopinatamente o artatamente. Ora \u00e8 giunto il momento di riportare la famiglia realmente al centro del dibattito politico per individuare soluzioni concrete agli aumentati bisogni e alle<\/em><em> esigenze dei cittadini.\u00a0 In questo particolare momento di difficolt\u00e0 i sindaci non possono e non devono essere lasciati soli a fronteggiare questi gravi problemi sociali\u201d. <\/em><\/p>\n<p>Al convegno sar\u00e0 presente anche il professor <strong>Stefano Zamagni<\/strong> dell\u2019Universit\u00e0 di Bologna, il massimo esperto in materia, a cui \u00e8 stato affidato il compito di realizzare una legge quadro sulla famiglia. L\u2019Italia, infatti, \u00e8 l&#8217;unico paese europeo che non ha una legge quadro sulle politiche familiari.<\/p>\n<p><em>\u00a0\u201cLa crisi non passer\u00e0 <\/em>\u2013 ha spiegato Zamagni &#8211; <em>se non ci decideremo a sostenere la famiglia. spesso lodata come ammortizzatore sociale ma altrettanto spesso incentivata soltanto a parole.<\/em><em> L\u2019iniziativa\u00a0 organizzata dal Comune di Lecce \u00e8 doppiamente meritoria. In\u00a0 primo luogo perch\u00e9 dice della vivacit\u00e0 culturale e civile del territorio salentino. Secondariamente perch\u00e9 siamo oggi alla vigilia di un importante evento e cio\u00e8 la\u00a0 terza Conferenza Nazionale sulle Politiche Familiari, rispetto alla quale il convegno di Lecce potr\u00e0 offrire\u00a0 decisivi spunti di riflessione ed importanti suggerimenti per l\u2019azione pratica\u201d.\u00a0 <\/em><\/p>\n<p><em>\u201cOccorre dare risposte nuove a problemi nuovi \u2013 sostiene il professor Luigi Spedicato &#8211; Sono i numeri a dircelo: il Fondo Nazionale delle Politiche Sociali in pochi anni, dal 2008 al 2012 \u00e8 passato da 670 milioni a 69 milioni di euro. I bisogni crescono e si diversificano, la popolazione invecchia e i processi migratori necessitano una rivisitazione. Sono segnali che dobbiamo sapere cogliere. E la comunit\u00e0 locale deve saper mobilitare le proprie risorse verso quello che viene definito capitale sociale\u201d. \u00a0<\/em><\/p>\n<p><em>\u201cLecce 2019 &#8211;<\/em> ha sottolineato\u00a0 il direttore artistico di Lecce 2019, <strong>Airan Berg<\/strong> &#8211;<em>\u00a0 guarda con estrema attenzione alle buone prassi. In questo senso il convegno nazionale che si tiene a Lecce pu\u00f2 rappresentare un modello vincente. Le politiche familiari debbono essere inclusive e aperte per dar modo, con l\u2019aiuto di tutti, di creare un\u2019autentica capitale della cultura della famiglia\u201d.<\/em><\/p>\n<p>Il convegno sar\u00e0 anche l\u2019occasione per avviare un confronto e uno scambio reciproco \u00a0al fine di verificare le esperienze positive presenti in Italia e nel mondo. L\u2019obiettivo \u00e8 quello di prendere in prestito modelli vincenti per trasferirli sul territorio.<\/p>\n<p>&nbsp;<\/p>\n<p><em>\u201cA causa dell\u2019esiguit\u00e0 delle risorse a disposizione degli Enti locali <\/em>\u2013 ha affermato la<em> <\/em>consigliera comunale <strong>Maria<\/strong> <strong>Paola Leucci<\/strong> \u2013<em> si sono sviluppate attivit\u00e0 trasversali per dare sostegno alle famiglie. Ebbene, \u00e8 necessario dare pi\u00f9 forza alle famiglie, magari con una rete, come nelle corti di una volta\u201d. <\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em>\u201cCon questo evento <\/em>\u2013 spiega il vicesindaco e assessore ai Servizi Sociali,<strong> Carmen<\/strong> <strong>Tessitore<\/strong> &#8211;<em> la citt\u00e0 di Lecce si propone come luogo di incontro per la riflessione e il confronto sulle esperienze e sulle buone prassi\u00a0in tema di welfare locale.<\/em><\/p>\n<p><em>Vogliamo ribadire la nostra attenzione alle politiche familiari con il coinvolgimento dell\u2019associazionismo, delle istituzioni e delle realt\u00e0 di vari territori. L\u2019obiettivo \u00e8 ridare alla famiglia la \u2018soggettivit\u00e0 sociale\u2019 che le spetta, negata per anni: perch\u00e9 \u00e8 risorsa sociale, patrimonio produttore di beni relazionali, luogo in cui \u2018si impara a vivere nella differenza\u2019, e si genera ben-essere sociale. Realizzare Alleanze locali per la Famiglia, investendo nella famiglia \u00e8 ridare speranza al futuro\u201d. <\/em><strong>\u00a0<\/strong>\u201c<em>Le politiche sulla famiglia <\/em>\u2013 conclude il vicesindaco Tessitore &#8211; <em>sono trasversali perch\u00e9 richiedono una soggettivit\u00e0 sociale senza pregiudizi e senza alcun tipo di steccato. Ecco perch\u00e9 c\u2019\u00e8 bisogno del contributo di tutti\u201d. <\/em><em><\/em><\/p>\n<p>Insomma investire nella famiglia, sistemandola, significa investire nel futuro.<\/p>\n<p>L\u2019evento \u00e8 organizzato dall\u2019Assessorato alle Politiche della Famiglia del Comune di Lecce e dal dipartimento di Storia, Societ\u00e0 e Studi sull\u2019Uomo e Corso di Studio in Servizio Sociale in con Universit\u00e0 del Salento in collaborazione con Anci.<\/p>\n<p>Al convegno saranno presenti anche <strong>Alessandro Delli Noci<\/strong>, assessore alle Politiche Comunitarie del Comune di Lecce, <strong>Francesco Belletti<\/strong>, presidente nazionale del Forum delle Associazioni Familiari, <strong>Lodovica Carli<\/strong>, presidente regionale del Forum delle Associazioni Familiari <strong>Achille Variati<\/strong>, sindaco di Vicenza e delegato Anci al Welfare, <strong>Maria Cristina Rizzo<\/strong>, vicepresidente Anci Puglia con delega al Welfare e l\u2019europarlamentare <strong>Raffaele Baldassarre<\/strong>, relatore al Parlamento Europeo sulla Responsabilit\u00e0 Sociale delle Imprese.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/05\/sistemiamo-la-famiglia\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/05\/sistemiamo-la-famiglia\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Un convegno nazionale per discutere sulle politiche familiari. Appuntamento luned\u00ec 7 aprile, alle ore 9, alle Officine Cantelmo. Tra i relatori anche il professor Stefano Zamagni, delegato a realizzare una legge quadro sulla famiglia. Luned\u00ec 7 aprile, alle ore 9, a Lecce, alle Officine Cantelmo (viale Michele De Pietro, 12), si aprir\u00e0 il convegno nazionale [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":21207,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/26979"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=26979"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/26979\/revisions"}],"predecessor-version":[{"id":26980,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/26979\/revisions\/26980"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/21207"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=26979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=26979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=26979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}