{"id":27097,"date":"2014-04-07T10:35:26","date_gmt":"2014-04-07T10:35:26","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=27097"},"modified":"2014-04-07T10:47:34","modified_gmt":"2014-04-07T10:47:34","slug":"sequestrate-cinque-discariche-abusive-nei-comuni-di-alezio-secli-e-parabita","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/07\/sequestrate-cinque-discariche-abusive-nei-comuni-di-alezio-secli-e-parabita\/","title":{"rendered":"SEQUESTRATE CINQUE DISCARICHE ABUSIVE NEI COMUNI DI ALEZIO, SECLI\u2019 E PARABITA"},"content":{"rendered":"<p style=\"text-align: justify;\" align=\"center\"><em><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/07\/sequestrate-cinque-discariche-abusive-nei-comuni-di-alezio-secli-e-parabita\/foto-45\/\" rel=\"attachment wp-att-27098\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/Foto-45-150x150.jpg\" alt=\"\" title=\"Foto 45\" width=\"150\" height=\"150\" class=\"alignnone size-thumbnail wp-image-27098\" \/><\/a>DENUNCIATI I PROPRIETARI DEI TERRENI PER VIOLAZIONE ALLE NORME SULLA TUTELA DELL\u2019AMBIENTE<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\">Nei giorni scorsi, la Compagnia della Guardia di Finanza di Gallipoli ha sequestrato cinque discariche abusive localizzate nei comuni di Alezio, Parabita e Secl\u00ec.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">I terreni agricoli, completamente recintati e classificati come seminativi ed uliveti, appartenenti a persone del posto, avevano un\u2019estensione superficiale complessiva di 19.467 metri quadrati.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Su di essi erano stoccati, in parte miscelati tra loro, rifiuti industriali (lana di vetro, spugne etc.), eternit, canne fumarie, asfalto derivante da raschiamenti di manto stradale, plastica, pneumatici e scarti della costruzione e demolizione di edifici.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">I proprietari dei terreni sono stati denunciati alla Procura della Repubblica di Lecce per violazioni alle norme sull\u2019ambiente (art. 256 del D.Lvo 152\/2006) e segnalate ai Comuni di competenza per l\u2019emissione delle ordinanze di bonifica dei siti, ripristino e messa in sicurezza dello stato dei luoghi.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/07\/sequestrate-cinque-discariche-abusive-nei-comuni-di-alezio-secli-e-parabita\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/07\/sequestrate-cinque-discariche-abusive-nei-comuni-di-alezio-secli-e-parabita\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>DENUNCIATI I PROPRIETARI DEI TERRENI PER VIOLAZIONE ALLE NORME SULLA TUTELA DELL\u2019AMBIENTE \u00a0 Nei giorni scorsi, la Compagnia della Guardia di Finanza di Gallipoli ha sequestrato cinque discariche abusive localizzate nei comuni di Alezio, Parabita e Secl\u00ec. I terreni agricoli, completamente recintati e classificati come seminativi ed uliveti, appartenenti a persone del posto, avevano un\u2019estensione [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":27098,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/27097"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=27097"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/27097\/revisions"}],"predecessor-version":[{"id":27119,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/27097\/revisions\/27119"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/27098"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=27097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=27097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=27097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}