{"id":27141,"date":"2014-04-07T16:11:18","date_gmt":"2014-04-07T16:11:18","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=27141"},"modified":"2014-04-07T16:14:34","modified_gmt":"2014-04-07T16:14:34","slug":"domenico-mennitti-non-e-piu-tra-noi","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/07\/domenico-mennitti-non-e-piu-tra-noi\/","title":{"rendered":"DOMENICO MENNITTI RICORDATO ANCHE DAI GRECI"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/mennitti.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/mennitti-300x168.jpg\" alt=\"\" title=\"mennitti\" width=\"300\" height=\"168\" class=\"alignleft size-medium wp-image-27143\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/mennitti-300x168.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/mennitti.jpg 480w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/BodyPart2.jpeg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/BodyPart2-225x300.jpg\" alt=\"\" title=\"BodyPart\" width=\"225\" height=\"300\" class=\"alignleft size-medium wp-image-27148\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/BodyPart2-225x300.jpg 225w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/BodyPart2.jpeg 540w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a>CONDOGLIANZE ELLENICHE<\/p>\n<p>Io Domenico Mennitti l\u2019ho conosciuto nella sua ultima fase di carriera politica, quando dal 2004 al 2011 \u00e8 stato il sindaco di Brindisi. Tralasciando il fatto che personalmente mi trovavo abbastanza lontano dalle sue idee politiche, devo invece ammettere che sono stato subito convinto dal suo discorso politico specifico riguardo il destino della Brindisi post-Antonino. Mi era da subito piaciuto il suo modo di pensare, di parlare, il suo pathos travolgente anche su questioni tab\u00f9 che inizialmente lasciavano indifferente una grande parte\u00a0 dell\u2019opinione pubblica. Come per esempio la necessit\u00e0 del rilancio culturale della citt\u00e0 di Brindisi. L&#8217;urgente bisogno di ritrovare il giusto orgoglio brindisino al di l\u00e0 della tifoseria sportiva.<\/p>\n<p>Non posso dire che Mennitti sia stato un filogreco sfegatato\u2026 Tutt&#8217;altro!.. Una volta mi ha detto: \u201cIo evito la tua Grecia perch\u00e9 soffro il caldo e da voi fa tanto caldo!\u201d. A me, pi\u00f9 che un uomo di mare, dava l\u2019impressione di un uomo di montagna, che per\u00f2 ha avuto il pregio di capire l\u2019importanza della sua \u201ccitt\u00e0 d&#8217;acqua\u201d e quindi del porto, prima di tanti altri\u2026 E poi per rilanciare il porto ha scelto uno di nome Hercules&#8230; forse non immaginando le reazioni del \u201csistema portuale\u201d, locale e pugliese, ad un&#8217;eventualit\u00e0 di decollo e quindi una \u201csproporzionata\u201d crescita dell\u2019economia trainante locale\u2026<\/p>\n<p>Con Mennitti, personalmente, ho avuto un feeling di reciproca approvazione e simpatia che per\u00f2 non ha mai generato risultati eccellenti. Ostacolo? Credo il mio rapporto di amicizia personale con l\u2019allora presidente del Consiglio Comunale Giampietro Pennetta. Mimmo essendo in aspra contrapposizione politica con Giam praticava la regola antica di guerra \u201cgli amici dei miei nemici sono miei nemici\u201d . Peccato.<\/p>\n<p>Devo, per\u00f2, riconoscere che Mennitti ha sorvolato pi\u00f9 di una volta a questa regola di guerra ed ha aperto per la mia Comunit\u00e0 Ellenica il portone del suo Palazzo Nervegna in varie occasioni importanti. Ci siamo incontrati pi\u00f9 volte con la delegazione di Corf\u00f9, abbiamo paventato e lanciato\u00a0 con il sindaco Trepeklis la grande idea di rilancio del turismo in rete &#8211; mai decollata; ci siamo incontrati con la delegazione di Cipro per denunciare l&#8217;assurda occupazione di una isola &#8211; stato membro della Comunit\u00e0 Europea &#8211; da parte della Turchia aspirante new entry nella famiglia Europea. Da sottolineare, tra gli altri incontri, quello con \u201dIstanbul Capitale d\u2019Europa 2010\u201d che gli aveva garantito tra l\u2019altro l&#8217;appoggio di quella citt\u00e0, alla candidatura di Brindisi Capitale d\u2019Europa 2019. Nessuno poteva all\u2019epoca immaginare il dietro-front del suo successore e la consegna del sogno, bench\u00e9 in condivisione, alla vicina e cosiddetta, \u201crivale storica\u201d, Lecce.<\/p>\n<p>Mi fermo qui. La mia vuole essere solamente una piccola nota alla memoria del \u201csindaco Mennitti\u201d visto da lato \u201cellenico\u201d. Rapporti difficili ma passati alla storia per quello che riguarda la nostra modesta presenza in citt\u00e0. Certo si poteva fare molto di pi\u00f9. Non ce l&#8217;hanno permesso personaggi e circostanze di contorno. Non importa, forse i tempi non erano allora maturi, forse \u00e8 saggio fare nostra, per il caso, la filosofia orientale secondo la quale \u201cquel che avviene, conviene\u201d\u2026<\/p>\n<p>Oggi voglio semplicemente salutare l\u2019uscita del sindaco Mennitti dalla scena terrestre come avevo fatto il 2004 in un breve articolo per salutare il suo arrivo da sindaco in citt\u00e0: in quella occasione lo avevo chiamato Kyri\u00e0kos (versione greca di Domenico). Anche oggi voglio chiamarlo per ultima volta cosi, aggiungendo \u201ckal\u00f2 tax\u00ecdi\u201d. E dunque, Kal\u00f2 tax\u00ecdi, Kyri\u00e0kos! Buon viaggio Kyri\u00e0kos!<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Ioannis Davilis<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/07\/domenico-mennitti-non-e-piu-tra-noi\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/07\/domenico-mennitti-non-e-piu-tra-noi\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>CONDOGLIANZE ELLENICHE Io Domenico Mennitti l\u2019ho conosciuto nella sua ultima fase di carriera politica, quando dal 2004 al 2011 \u00e8 stato il sindaco di Brindisi. Tralasciando il fatto che personalmente mi trovavo abbastanza lontano dalle sue idee politiche, devo invece ammettere che sono stato subito convinto dal suo discorso politico specifico riguardo il destino della [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":27143,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/27141"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=27141"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/27141\/revisions"}],"predecessor-version":[{"id":27149,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/27141\/revisions\/27149"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/27143"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=27141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=27141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=27141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}