{"id":27158,"date":"2014-04-08T10:12:40","date_gmt":"2014-04-08T10:12:40","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=27158"},"modified":"2014-04-08T10:13:33","modified_gmt":"2014-04-08T10:13:33","slug":"fucile-occultato-in-muro-a-secco","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/08\/fucile-occultato-in-muro-a-secco\/","title":{"rendered":"FUCILE OCCULTATO IN MURO A SECCO"},"content":{"rendered":"<p style=\"text-align: left;\" align=\"center\"><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/carabiniere-con-fucile.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/carabiniere-con-fucile-267x300.jpg\" alt=\"\" title=\"carabiniere con fucile\" width=\"267\" height=\"300\" class=\"alignleft size-medium wp-image-27160\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/carabiniere-con-fucile-267x300.jpg 267w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/carabiniere-con-fucile.jpg 489w\" sizes=\"(max-width: 267px) 100vw, 267px\" \/><\/a>I Carabinieri di Tricase nel week end appena trascorso hanno svolto un servizio straordinario di controllo del territorio nei comuni di Castrignano del Capo, Salve, Acquarica del Capo e Presicce.<\/p>\n<p>Nel corso dell\u2019attivit\u00e0 sono stati raccolti i seguenti risultati:<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0ritirate 3 patenti per guida in stato di ebrezza alcolica e contestuale denuncia in stato di libert\u00e0;<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0segnalate alla Prefettura di Lecce ben 6 persone quali assuntori di sostanze stupefacenti ex art. 75 DPR 309\/90;<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0denunciate in stato di libert\u00e0 2 persone per guida senza patente perch\u00e9 mai conseguita.<\/p>\n<p>L\u2019attivit\u00e0 di polizia \u00e8 stato poi premiata dal rinvenimento di un fucile perfettamente funzionante nelle campagne dei comuni interessati; l\u2019arma era occultata in un muro a secco e non si esclude che la stessa possa essere stata utilizzata in passato per compiere episodi delittuosi.<\/p>\n<p>L\u2019arma verr\u00e0 inviata al RACIS per gli accertamenti balistici, dattiloscopici e biologici.<\/p>\n<div><\/div>\n<div id=\"wrchoverdiv\">\n<div id=\"wrccontainer\">\n<div id=\"wrcheader\">\n<div id=\"wrctitle\">WebRep<\/div>\n<\/div>\n<div class=\"wrchorizontal\"><\/div>\n<div id=\"wrccurrentvote\">currentVote<\/div>\n<div class=\"wrchorizontal\"><\/div>\n<div id=\"wrcrating\"><\/div>\n<div id=\"wrcratingtext\">noRating<\/div>\n<div id=\"wrcweighttext\">noWeight<\/div>\n<div id=\"wrcflags\"><\/div>\n<div class=\"wrchorizontal\"><\/div>\n<\/div>\n<\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/08\/fucile-occultato-in-muro-a-secco\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/08\/fucile-occultato-in-muro-a-secco\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>I Carabinieri di Tricase nel week end appena trascorso hanno svolto un servizio straordinario di controllo del territorio nei comuni di Castrignano del Capo, Salve, Acquarica del Capo e Presicce. Nel corso dell\u2019attivit\u00e0 sono stati raccolti i seguenti risultati: &#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0ritirate 3 patenti per guida in stato di ebrezza alcolica e contestuale denuncia in stato di [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":27160,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/27158"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=27158"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/27158\/revisions"}],"predecessor-version":[{"id":27164,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/27158\/revisions\/27164"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/27160"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=27158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=27158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=27158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}