{"id":27171,"date":"2014-04-08T12:30:26","date_gmt":"2014-04-08T10:30:26","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=27171"},"modified":"2014-04-08T12:30:26","modified_gmt":"2014-04-08T10:30:26","slug":"bon-a-tirer","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/08\/bon-a-tirer\/","title":{"rendered":"Bon \u00e0 tirer"},"content":{"rendered":"<p style=\"text-align: left;\" align=\"center\"><strong><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/Salvatore-Fiume.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/Salvatore-Fiume-222x300.jpg\" alt=\"\" title=\"Salvatore Fiume\" width=\"222\" height=\"300\" class=\"alignleft size-medium wp-image-27173\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/Salvatore-Fiume-222x300.jpg 222w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/Salvatore-Fiume.jpg 742w\" sizes=\"(max-width: 222px) 100vw, 222px\" \/><\/a><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/Renato-Guttuso.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/Renato-Guttuso-246x300.jpg\" alt=\"\" title=\"Renato Guttuso\" width=\"246\" height=\"300\" class=\"alignleft size-medium wp-image-27172\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/Renato-Guttuso-246x300.jpg 246w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/Renato-Guttuso.jpg 820w\" sizes=\"(max-width: 246px) 100vw, 246px\" \/><\/a>Arte del Novecento italiano dalla collezione Muscetra<br \/>\n<\/strong>Una panoramica da Renato Guttuso a Emilio Vedova<br \/>\n<strong>Biblioteca provinciale di Lecce \u2013 ex Convitto Palmieri\u00a0<\/strong><strong>12 aprile \u2013 17 settembre 2014<br \/>\n<\/strong><strong>Inaugurazione: 12 aprile alle 19 con una conferenza dello chef Gualtiero Marchesi, collezionista e compagno di strada di molti artisti<\/strong><\/p>\n<p style=\"text-align: left;\">\u00a0Renato Guttuso, Enrico Baj Gregorio Sciltian, Emilio Vedova, Graham Sutherland, David Alfaro Siqueiros, Aligi Sassu, Giuseppe Migneco, Remo Brindisi, Domenico Cantatore, Gianni Dova, Salvatore Fiume, Emilio Greco, Carlo Levi, Luciano Minguzzi, Ennio Morlotti: sono solo alcuni protagonisti dell\u2019intenso percorso espositivo \u201cBon \u00e0 tirer\u201d allestito negli spazi della Biblioteca Provinciale di Lecce su iniziativa dell\u2019assessorato alla cultura e dell\u2019Istituto di culture mediterranee in collaborazione con <em>AXA. Aziende per l\u2019ambiente<\/em>.<\/p>\n<p>Le opere \u2013 tecniche miste su carta, ma soprattutto litografie ritoccate a mano \u2013 sono state realizzate da grandi maestri del Novecento italiano (oppure da nomi stranieri amanti dell\u2019Italia) nella celebre stamperia milanese di Siro Teodorani.<\/p>\n<p>Perch\u00e9 \u201cbon \u00e0 tirer\u201d? Nel gergo artistico con questa espressione s\u2019individua la prova finale firmata dall\u2019artista che d\u00e0 il via alla stampa dell\u2019intera tiratura grafica. Perci\u00f2 non sono semplici multipli, ma opere fondamentali per comprendere l\u2019approccio tecnico e concettuale di un artista rispetto a un tema o a un soggetto specifico. Tra l\u2019altro la maggior parte delle opere sono accompagnate da appunti manoscritti, indicazioni tracciate dall\u2019artista con matite o pastelli e destinate allo stampatore, oppure dediche amicali a Enrico Muscetra, scultore e pittore salentino compagno di strada di tutti loro, frequentati nei lunghi e intensi anni milanesi.<\/p>\n<p>Secondo lo stesso Muscetra \u201cConcepire una mostra di litografie bon \u00e0 tirer di alcuni maestri contemporanei a cui sono stato vicino negli anni della mia formazione, mi \u00e8 sembrata un\u2019idea pi\u00f9 interessante rispetto a quella scontata della solita e ripetitiva mostra personale. Una mostra questa \u2013 ha aggiunto l\u2019artista \u2013 corredata anche di disegni preparatori, di studi e foto degli autori stessi che illustrano le fasi che precedono il Bon \u00e0 tirer\u201d. Infatti la mostra \u00e8 accompagnata da una serie di contenuti extra: fotografie, cataloghi e lettere degli amici<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>artisti, oltre che da una serie di apparati didattici utili a comprendere pienamente lo spirito del progetto e la natura del percorso espositivo.<\/p>\n<p>&nbsp;<\/p>\n<p>Non si tratta infatti di una mostra di opere generiche del percorso di questi artisti, ma di un percorso tra i maggiori maestri dell\u2019arte italiana, e non solo, del XX secolo, che hanno a lungo frequentato il laboratorio di Siro Teodorani, considerando quello studio una seconda casa. Muscetra, che di Teodorani, come ricorda, era \u201ccome un figlio\u201d, ha avuto cos\u00ec modo di lavorare gomito a gomito con questi maestri, condividere gioie e passioni, custodire confidenze e segreti che oggi ha raccolto in un libro edito da Lupo Editore intitolato \u201cDiario di uno scultore\u201d, in vendita in mostra al costo speciale di 10,00 Euro.<\/p>\n<p>&nbsp;<\/p>\n<p>Sempre a proposito di quell\u2019indimenticabile periodo, Muscetra ha ricordato \u201cE, nell\u2019ebbrezza che arreca il lavorare con materiali diversi, tipo la lastra di zinco o la pietra \u2013 ebbrezza rinforzata non solo dalla condivisione e dalla confidenziale collaborazione con gli artigiani litografi, ma anche da un buon vino che non mancava mai di essere bevuto \u2013, ci si lasciava andare a confidenze rivelatrici sulla vita e la creazione artistica\u201d.<\/p>\n<p>Gli aneddoti che costellano la genesi e la realizzazione di tante belle e originali opere d\u2019arte litografiche sono davvero infiniti, e molti di essi dispiegano un\u2019aurea artistico-esistenziale che difficilmente potr\u00e0 ripetersi.<\/p>\n<p>&nbsp;<\/p>\n<p>Biografia essenziale del maestro Muscetra<\/p>\n<p>&nbsp;<\/p>\n<p>Enrico Muscetra \u00e8 nato ad Alezio, in provincia di Lecce, nel 1946. Del 1971 \u00e8 la sua personale a Milano. In questi anni realizza numerosi dipinti murali di carattere onirico-informale. Estranea ad ogni vocazione narrativa. Numerose le mostre personali e collettive in Italia e all\u2019estero, in cui il maestro ha proposto le proprie opere pittoriche e scultoree. Dalle personali alla Galleria Schettini di Milano (1972), a Palazzo dei Diamanti di Ferrara (1992), al castello Angioino di Gallipoli (1996), alle importanti collettive, come la Biennale di Monza del 1979, ordinata nei magnifici spazi di Villa Reale. Del suo lavoro si sono occupati Renato Guttuso, Carlo Levi, Ernesto Treccani, Remo Brindisi, Vittorio Sgarbi, Goran Bregovic, Enrico Crispolti e altri importanti artisti e intellettuali italiani e stranieri. Vive e opera tra il Salento e la Polonia.<\/p>\n<p>&nbsp;<\/p>\n<p>Info: <strong>La mostra sar\u00e0 visitabile tutti i giorni dalle 10 alle 13 e dalle 16 alle 19. <\/strong><\/p>\n<p>Costo d\u2019ingresso: 3,00 Euro.<\/p>\n<p>Ridotto (studenti Accademie di Belle Arti, Facolt\u00e0 universitarie di Beni Culturali o affini, bambini sotto i dieci anni, gruppi superiori alle 30 unit\u00e0): 2,00 Euro.<\/p>\n<p>&nbsp;<\/p>\n<p>Prenotazioni visite per gruppi (consigliato): telefono 0832.68.35.44 \/ 347.37.82.163 \/ email staff.incima@gmail.com.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/08\/bon-a-tirer\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/08\/bon-a-tirer\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Arte del Novecento italiano dalla collezione Muscetra Una panoramica da Renato Guttuso a Emilio Vedova Biblioteca provinciale di Lecce \u2013 ex Convitto Palmieri\u00a012 aprile \u2013 17 settembre 2014 Inaugurazione: 12 aprile alle 19 con una conferenza dello chef Gualtiero Marchesi, collezionista e compagno di strada di molti artisti \u00a0Renato Guttuso, Enrico Baj Gregorio Sciltian, Emilio [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":27173,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/27171"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=27171"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/27171\/revisions"}],"predecessor-version":[{"id":27174,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/27171\/revisions\/27174"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/27173"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=27171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=27171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=27171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}