{"id":2763,"date":"2012-07-18T15:23:55","date_gmt":"2012-07-18T15:23:55","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=2763"},"modified":"2012-07-19T09:51:36","modified_gmt":"2012-07-19T09:51:36","slug":"a-specchia-dal-25-al-28-luglio-la-festa-del-cinema-del-reale","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2012\/07\/18\/a-specchia-dal-25-al-28-luglio-la-festa-del-cinema-del-reale\/","title":{"rendered":"A Specchia, dal 25 al 28 luglio LA FESTA DEL CINEMA DEL REALE"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/07\/18\/a-specchia-dal-25-al-28-luglio-la-festa-del-cinema-del-reale\/la-festa-di-cinema-del-reale-2\/\" rel=\"attachment wp-att-2764\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/07\/La-festa-di-Cinema-del-Reale-2-300x200.jpg\" alt=\"\" title=\"La festa di Cinema del Reale\" width=\"300\" height=\"200\" class=\"alignnone size-medium wp-image-2764\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/07\/La-festa-di-Cinema-del-Reale-2-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/07\/La-festa-di-Cinema-del-Reale-2-1024x685.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/07\/La-festa-di-Cinema-del-Reale-2.jpg 1772w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>La Festa di Cinema del reale<\/strong><\/p>\n<p><strong><em>FESTIVAL DEL CINEMA DOCUMENTARIO <\/em><\/strong><strong><em><\/em><\/strong><\/p>\n<p><strong>Specchia (Lecce) \u2022 25\/28 luglio 2012<\/strong><\/p>\n<p><strong>IX edizione<\/strong><\/p>\n<p><em>www.cinemadelreale.it<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><strong><em>La Festa di Cinema del reale \u00e8 ideata e organizzata da<\/em><\/strong><em> Big Sur, Associazione Cinema del reale e OfficinaVisioni, con la direzione artistica di Paolo Pisanelli, <strong>\u00e8 cofinanziata da<\/strong> Unione Europea (Iniziativa cofinanziata con fondi P.O. FESR Puglia 2007-2013 Asse IV &#8211; Linea d&#8217;intervento 4.3), Regione Puglia (Assessorato al Mediterraneo Settore Attivit\u00e0 Culturali) e Fondazione Apulia Film Commission, <\/em><strong>con il contributo<\/strong><em> <\/em><strong>di<\/strong><em> Comune di Specchia, Ambasciata Svizzera, Consolato Svizzero a Bari.<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>Parole chiave:<\/em><strong> CRISI \/ AMORI \/ FOLLIE<\/strong><\/p>\n<p><em>Ospite d\u2019onore:<\/em><strong> ALEXANDER J. SEILER<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Dal 25 al 28 luglio<\/strong> torna a <strong>Specchia<\/strong> (provincia di <strong>Lecce<\/strong>) la <strong>Festa di Cinema del reale<\/strong>: giunto alla sua nona edizione, l\u2019appuntamento\u00a0 propone <strong>quattro giorni all\u2019insegna del cinema pi\u00f9 spericolato, curioso e inventivo<\/strong>. Pi\u00f9 che una rassegna, una originale \u201c<strong>festa di sguardi<\/strong>\u201d che promuove le narrazioni del reale e il documentario e fa dialogare film e musica, fotografia e scrittura, cucina e grafica, coinvolgendo il territorio e trasformando uno dei borghi pi\u00f9 suggestivi d\u2019Italia \u2013 e in particolare la \u201csala en plein air\u201d allestita nella corte del Castello Risolo \u2013 in una vera Cittadella del Cinema del reale, abitata (oltre che dai cittadini di Specchia) da autori, produttori, studenti, turisti e appassionati.<\/p>\n<p>&nbsp;<\/p>\n<p>Autori invitati: oltre all\u2019ospite d\u2019onore <strong>Alexander J. Seiler<\/strong> ci saranno <strong>Daniele Vicari<\/strong>, <strong>Stefano Savona<\/strong>, <strong>Franco Arminio<\/strong>, <strong>Gustav Hofer<\/strong> e <strong>Luca Ragazzi<\/strong>, <strong>Mariangela Barbanente<\/strong>, <strong>Benoit Felici<\/strong>, <strong>Valentina Pedicini<\/strong>, <strong>Mario Perrotta<\/strong>, <strong>Chiara Idrusa Scrimieri<\/strong>, <strong>Christian Sabatelli<\/strong>, <strong>Pippo Cariglia<\/strong>, <strong>Sophie<\/strong> e <strong>Annalisa Chiarello<\/strong>. Inoltre, a presentare i film di <strong>Riccardo Napolitano<\/strong> (1928-1993), la montatrice <strong>Carla Simoncelli, <\/strong>compagna del regista.<\/p>\n<p>&nbsp;<\/p>\n<p>Il <strong>Premio Cinema del reale<\/strong>, conferito ad autori, produttori, distributori, e operatori culturali che danno impulso alla creazione, realizzazione e diffusione del cinema del reale in Italia, sar\u00e0 consegnato quest\u2019anno dal Governatore della Regione Puglia, <strong>Nichi Vendola<\/strong> e dalla Presidente della Apulia Film Commission <strong>Antonella Gaeta<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>Cinema del reale \u00e8 un cinema \u201cambulante\u201d, senza botteghino (tutte le proiezioni sono a ingresso libero) e senza effetti speciali. \u00c8 il cinema che attraversa periferie, fabbriche, deserti, mari, isole, metropoli, fiumi, terremoti, televisioni; che \u201csi fa fuori\u201d, per strada e ovunque, e invita le persone ad incontrarsi, a guardare i luoghi dove viviamo, le cose che succedono, raccogliendo memorie e amnesie per attraversare luci e ombre del presente, del passato, del futuro. Un cinema che dispone di limitate risorse economiche ma \u00e8 dotato di grandi capacit\u00e0 inventive.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Crisi, amori, follie<\/strong><\/p>\n<p>Sono le tre parole chiave della nona edizione della Festa di Cinema del reale. Parole che esprimono ci\u00f2 che viviamo: crisi di identit\u00e0, di economia, di lavoro, di abitazione, di democrazia e crisi di amori; amori di persone, luoghi, territori, immagini; follie creative e follie di violenze, speculazioni, leggi e reclusioni. Parole che, insieme a molte altre, risuonano nelle immagini (non solo cinematografiche) che animano questa \u2018festa di sguardi\u2019 e che fanno di \u201cCinema del reale\u201d <strong>un corpo a corpo con le realt\u00e0 possibili.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Alexander J. Seiler\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><\/p>\n<p>Agn\u00e8s Varda, grande protagonista della scorsa edizione, passa il testimone all\u2019ospite d\u2019onore di quest\u2019anno, uno dei grandi autori del documentario europeo, lo svizzero<strong> Alexander J. Seiler<\/strong>, <strong>Palma d\u2019oro nel 1963<\/strong> con il cortometraggio <strong><em>A fleur d\u2019eau<\/em><\/strong> e autore legato a filo doppio al nostro Paese. Risale infatti al 1964 uno dei suoi capolavori, <strong><em>Siamo italiani<\/em><\/strong>, autentico \u201cresoconto etnografico\u201d sulla grande comunit\u00e0 di emigranti nostri connazionali, costretti a fare i conti con la discriminazione svizzera. Un film intenso e importante, che a Specchia si vedr\u00e0 insieme al suo \u201cseguito ideale\u201d: quel <strong><em>Vento di Settembre<\/em><\/strong> che, realizzato nel 2002, indaga la cosiddetta \u201cemigrazione di ritorno\u201d vissuta quarant\u2019anni dopo da chi ha deciso di lasciare la Svizzera per tornare ad Acquarica del Capo, nel Salento. Storie di anziani rientrati a casa dopo decenni di duro lavoro, che aspettano per tutto l\u2019anno la visita dei figli rimasti in Svizzera, vivendo sulla propria pelle un nuovo, costante sradicamento. Perch\u00e9 l\u00ec come qui, spiega Tonuccio, \u00abla distanza e il desiderio ti spezzano il cuore\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Quattro grandi del documentario italiano<\/strong><\/p>\n<p>A dialogare con Seiler, una \u201cpioniera\u201d del documentario europeo, l\u2019italiana <strong>Cecilia Mangini<\/strong>, amica e grande promotrice della Festa, che quest\u2019anno presenter\u00e0 <em>Ring Sardegna<\/em>, un estratto da <em>Domani vincer\u00f2<\/em> e parteciper\u00e0 all\u2019incontro <em>Raccontare il territorio<\/em>.<\/p>\n<p>&nbsp;<\/p>\n<p>Oltre al film della Mangini, anche due brevi opere firmate da due maestri, amici e sostenitori di \u201cCinema del reale\u201d, da poco scomparsi: <strong>Vittorio De Seta<\/strong> (il cui <em>Isole di fuoco<\/em> sar\u00e0 musicato dal vivo dal compositore Gabriele Panico) e <strong>Ansano Giannarelli<\/strong> (con una straordinaria indagine del 1972 su ritmi e visioni in fabbrica: <em>Analisi del lavoro<\/em>).<\/p>\n<p>&nbsp;<\/p>\n<p>Un tributo particolare sar\u00e0 dedicato a <strong>Riccardo Napolitano<\/strong>, eccezionale cineasta e instancabile promotore dei circoli del cinema FICE. Due i titoli scelti per questo omaggio: <strong><em>1904, N. 36<\/em><\/strong> racconta attraverso immagini drammatiche la vita (meglio: la \u201cnon\u201d vita) all&#8217;interno di un ospedale psichiatrico del 1967. La legge che regola l&#8217;organizzazione degli ospedali psichiatrici \u00e8 ancora la numero 36 del 1904: si basa sul concetto di pericolosit\u00e0 e inguaribilit\u00e0 del malato e sul ricovero coattivo che assomiglia pi\u00f9 a una detenzione in carcere. Il film, oltre a mostrare le immagini dei ricoverati, ripresi senza volto (anche se i primi piani delle mani sono altrettanto indicativi nel testimoniarne la sofferenza) all&#8217;interno dell&#8217;ospedale, lancia proposte alternative gi\u00e0 all&#8217;esame di esperti psicologi e chiede l&#8217;abrogazione della legge vigente ormai superata dalle nuove teorie della psicologia.<\/p>\n<p>L\u2019altro film \u00e8 <strong><em>Funerali verdi<\/em><\/strong> (1971), documentario di denuncia contro gli sprechi legati al mercato ortofrutticolo le cui spietate logiche di profitto impongono la distruzione di enormi quantit\u00e0 di prodotto per mantenere alti i prezzi.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Visioni doc<\/strong><\/p>\n<p>Accanto a questi grandi, una selezione del meglio della produzione italiana dell\u2019ultima stagione: dal viaggio in Italia, alla ricerca dei buoni motivi per amarla o lasciarla, compiuto da <strong>Gustav Hofer<\/strong> e <strong>Luca Ragazzi<\/strong> in <strong><em>Italy: Love It or Leave It<\/em><\/strong>, al viaggio a<strong><em> Teora<\/em><\/strong>, un piccolo paese dell\u2019Irpinia colpito dal terremoto dell\u201980, intrapreso da <strong>Franco Arminio<\/strong>; dal campo di calcio abbandonato de <strong><em>L\u2019altra citt\u00e0<\/em><\/strong>, che a Lecce ospita un torneo antirazzista che diventa un vero laboratorio sociale (come raccontano <strong>Cristian Sabatelli<\/strong> e <strong>Pippo Cariglia<\/strong>) a <strong><em>My Marlboro City<\/em><\/strong> di <strong>Valentina Pedicini<\/strong>, che attraverso 4 storie e altrettante generazioni ci fa scoprire cosa \u00e8 rimasto della Brindisi che fu capitale del contrabbando di sigarette. E ancora: <strong><em>Unfinished Italy<\/em><\/strong> di <strong>Benoit Felici<\/strong>, che con amara ironia punta gli occhi sull\u2019incompiuto, lo stile architettonico pi\u00f9 praticato nel Belpaese dal dopoguerra ad oggi; <strong><em>Ferrhotel<\/em><\/strong> di <strong>Mariangela Barbanente<\/strong>, microcosmo somalo in un piccolo albergo dismesso a due passi dalla stazione di Bari; <strong><em>Ritals \u2013 Domani me ne vado<\/em><\/strong> di Sophie e Annalise Chiarello, curiosamente vicino al cinema di Seiler nel raccontare l\u2019emigrazione di Maria e Vincenzo negli anni \u201950 dal Basso Salento in Francia (e ritorno, all\u2019insegna di un nuovo spaesamento).<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Filmare eventi collettivi, <\/strong><\/p>\n<p><strong>raccontare il territorio e storie di migranti<\/strong><\/p>\n<p>Due incontri e un seminario vengono proposti in quest\u2019edizione: <strong>CRISI \/ AMORI \/ FOLLIE: FILMARE STORIE DI MIGRANTI<\/strong>, con Alexander J. Seiler, Mariangela Barbanente, Christian Sabatelli, Pippo Cariglia, Sophie e Annalisa Chiarello, Daniele Vicari;\u00a0\u00a0\u00a0 <strong>RACCONTARE IL TERRITORIO <\/strong><em>con Franco Arminio, Giuseppe Cristaldi, Benoit Felici, Cecilia Mangini, Alessia Rollo, Maira Marzioni, Valentina Pedicini, Mauro Marino, Stefano Cristante, Luigi Russo;<\/em><strong> <\/strong>Il seminario<strong> FILMARE EVENTI COLLETTIVI<\/strong>, che fa il punto su cosa vuol dire essere testimoni di momenti di partecipazione che \u2013 in piccolo o in grande, in positivo o in negativo \u2013 sono destinati a entrare nella memoria collettiva: tra i partecipanti, il critico cinematografico <strong>Antonio Medici<\/strong>, il direttore artistico della Festa <strong>Paolo Pisanelli<\/strong> (che in <em>Ju tarramutu<\/em> ha filmato la rivolta delle carriole de L\u2019Aquila); <strong>Stefano Savona<\/strong>, che con <strong><em>Tahrir Square<\/em><\/strong> (Premio David di Donatello 2012, in programma al festival) ha offerto all\u2019Occidente un eccezionale documento in presa diretta sulle proteste che infiammarono Il Cairo durante la primavera (araba) dello scorso anno; e <strong>Daniele Vicari<\/strong>, che in <em>Diaz<\/em> (anche questo in programma) ha ricostruito \u2013 tra fiction e materiali d\u2019archivio \u2013 i fatti del G8 di Genova.\u00a0\u00a0 <strong><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Italia-Grecia<\/strong><\/p>\n<p>La Festa di cinema del reale vuole illuminare quest\u2019anno il ponte linguistico e culturale che congiunge l\u2019Italia e la Grecia: per farlo ha scelto <strong><em>Encardia<\/em><\/strong>, il film di <strong>Angelos Kovotsos<\/strong> che \u2013 attraverso l\u2019omonimo gruppo musicale, che si ispira alle forme musicali e alle canzoni della ricca tradizione del nostro sud \u2013 va alla ricerca delle tracce di questo inscindibile legame. Una su tutte, il Griko, antico idioma ellenico ancora oggi parlato in alcune zone della Calabria e della Grecia salentina. Prima della proiezione, la musica degli Encardia dal vivo.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Evento speciale \u201cFormato ridotto\u201d<\/strong><\/p>\n<p>Tra gli eventi speciali della Festa, anche <strong><em>Formato ridotto<\/em><\/strong>, il film collettivo che segna l\u2019incontro tra <strong>Home Movies<\/strong> e gli scrittori <strong>Enrico Brizzi<\/strong>, <strong>Ermanno Cavazzoni<\/strong>, <strong>Emidio Clementi<\/strong>, <strong>Ugo Cornia<\/strong> e <strong>Wu Ming 2<\/strong>, che hanno elaborato dei testi originali trovando nelle immagini dell\u2019Archivio Nazionale del Film di Famiglia l\u2019occasione di sperimentare nuove tecniche narrative. Grazie ad approcci molto diversi tra loro, in un\u2019opera unica convergono cinque episodi dagli esiti sorprendenti, singoli episodi di breve durata, di volta in volta trasfigurati in saggio, racconto, cronaca, divagazione. Forme del cinema documentario accomunate da una matrice comune: il variegato universo emiliano-romagnolo.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Sguardi e visioni<\/strong><\/p>\n<p>Non solo cinema, alla Festa di Cinema del reale, ma anche una meravigliosa festa di sguardi con <strong>allestimenti<\/strong>, <strong>performance<\/strong>, <strong>workshop fotografici<\/strong>, <strong>videoinstallazioni<\/strong>, a cura di <strong>Big Sur Lab<\/strong>, che si dipanano nelle sale e sul terrazzo del Castello Risolo, in Piazza del Popolo e tra i vicoli di Specchia.<\/p>\n<p>Nella sezione \u201cSguardi e visioni\u201d ci si imbatte nei ritratti <strong><em>Pop&amp;Brut<\/em><\/strong> di <strong>Marco Biffoli<\/strong>, singolare artista del Centro di attivit\u00e0 espressive La Tinaia (ex ospedale psichiatrico di Firenze) autore di coloratissime tele in cui l\u2019inquietudine della contemporaneit\u00e0 emerge dai volti dei personaggi noti del mondo della politica, dell\u2019arte e della storia. <strong><em>Diariovisioni<\/em><\/strong> \u00e8 un fotoracconto \u2018glocally\u2019 in cui si susseguono le immagini della Festa \u2018condivise\u2019 in contemporanea nella piazza di Specchia e su Facebook, realizzate da <strong>Alessia Rollo<\/strong> che cura anche <strong><em>Lou fai<\/em><\/strong>, una collettiva di fotografia esito del workshop sul tema dell\u2019autorappresentazione. <strong>Attra-verso<\/strong>, invece, \u00e8 un lavoro di scrittura documentaria realizzata a quattro mani da Franco Arminio e Maira Marzioni che, andando a zonzo per i vicoli di Specchia, postano su manifesti e locandine impressioni e scritture paesologiche sulla Cittadella. <strong><em>Dell&#8217;accudire<\/em><\/strong> mette in mostra contenitori di umori stra-ordinari, piccole coppette in cartapesta che accolgono il fare creativo dei laboratori espressivi del Centro per la Cura e la Ricerca sui Disturbi del Comportamento Alimentare (DSM ASL Le).<\/p>\n<p>Come in una sorta di cineclub le stanze del Castello Risolo diventano contenitori di visioni con quattro videoinstallazioni: <strong><em>La follia di Zavattini<\/em><\/strong>, immagini e parole tratte dal film di Ansano Giannarelli; <strong><em>Facce<\/em><\/strong>, opera video a cura di <strong>Paolo Pisanelli<\/strong> e <strong>Francesco Maggiore<\/strong> di Big Sur realizzata con gli studenti del liceo artistico \u201cVincenzo Ciardo\u201d di Lecce; <strong><em>Paradossi italiani<\/em><\/strong>, ovvero l&#8217;Italia che resiste, cinque racconti scritti e interpretati da <strong>Mario Perrotta<\/strong> e sonorizzati da Chiara Idrusa Scrimieri; <strong><em>Terramossa<\/em><\/strong> una guida sentimentale all&#8217;Irpinia, video-frammenti di territorio del paesologo Franco Arminio; <strong><em>SS 275<\/em><\/strong> immagini sui percorsi della strada che cambier\u00e0 il volto di un territorio e la vita degli abitanti del Sud Salento.<strong><em> Attra-verso<\/em><\/strong> \u00e8 un viaggio di parole senza meta nei contorni di Specchia, e dentro le sue pieghe, un corpo a corpo col paese a scovare frammenti di poesia, dettagli insignificanti, gesti sprecati, residui da raccogliere. Ad attraversare e ad essere attraversati da quei luoghi durante i giorni della Festa per dare forma a racconti, frammenti da restituire con \u2018parole diffuse\u2019 saranno gli scrittori Maira Marzioni e Franco Arminio.<\/p>\n<p><strong><br \/>\n<\/strong><\/p>\n<p><strong>Intrecci musicali<\/strong><\/p>\n<p>Anche quest\u2019anno la musica intreccia le visioni durante le quattro serate della Festa di Cinema del reale. Dalla tradizione popolare dei greci <strong>Encardia<\/strong> all\u2019elettronica di <strong>Gabriele Panico<\/strong> che sonorizza dal vivo <strong><em>Isole di fuoco<\/em><\/strong> del maestro <strong>Vittorio De Seta<\/strong>, dai suoni ancestrali provenienti dal frantoio ipogeo dove l\u2019artista <strong>Antonio De Luca<\/strong> far\u00e0 suonare le sue sculture sonore, alla schietta voce e chitarra del cantautore popolare salentino <strong>Mino De Santis<\/strong> narratore di storie del reale come <strong><em>Vanne alla Svizzera<\/em><\/strong> cantata sulle immagini di giovani e vecchi migranti. Il musicista <strong>Donatello Pisanello<\/strong> e lo scrittore <strong>Giuseppe Cristaldi<\/strong> accompagnano le immagini di <em>SS 275<\/em> viaggio sui percorsi della strada che cambier\u00e0 il volto del paesaggio e la storia degli abitanti del Sud Salento. Il documentario musicale <strong><em>When you\u2019re strange<\/em><\/strong><em> <\/em>di <strong>Tom Di Cillo<\/strong> far\u00e0 riecheggiare le note dei Doors per tirare fino a tarda notte e concludere la serata sul terrazzo del Castello con uno speciale Trip Cocktail. E sempre sul terrazzo la performance voce e kalimba della musicista svizzera <strong>IOKOI <\/strong>e l\u2019atteso dj set della Festa finale sulle note di Dj <strong>Popolous<\/strong> che si conclude la domenica mattina con la visione dell\u2019alba.<\/p>\n<p><strong>Extra (eventi in\/Contemporanea)<\/strong><\/p>\n<p>L\u2019alchimia dell\u2019arte contemporanea invade le sale di Palazzo Risolo, prosegue nel convento dei Francescani Neri, conquista gli ambienti dei frantoi ipogei di Specchia, con installazioni e collettive capaci di coniugare il fascino arcaico dei luoghi con i linguaggi pi\u00f9 innovativi dell\u2019arte. Sono eventi <strong><em>Extra<\/em><\/strong>, che anticipano ed animano <strong><em>in\/Contemporanea<\/em><\/strong> la Festa del Cinema del reale, abitando e condividendo lo spirito dei luoghi. \u00c8 il caso di <strong><em>Luminaria Essay<\/em><\/strong>, personale rivisitazione di <strong>Flavio Favelli<\/strong> sul tema delle luminarie declinato nella forma di un site specific negli ambienti di palazzo Risolo e dell\u2019ex convento dei Francescani Neri, promossa dall\u2019associazione Spazio Cactus di Marina Senin Forni. Sempre \u201cin\/Contemporanea\u201d, si svolge <strong><em>Merica e le visioni<\/em><\/strong>, mostra dedicata all\u2019artista fiammingo <strong>Norman Mommens<\/strong> in cui si espongono, a dodici anni dalla sua scomparsa, sculture mai uscite prima d\u2019ora dalla sua casa-museo a Spigolizzi. La mostra, a cura di Ada Martella, \u00e8 allestita sempre presso le sale del maniero cinquecentesco (ingresso da via Umberto I) e comprende anche le incisioni di <strong>Andrea De Simeis<\/strong>.<\/p>\n<p>Due dei numerosi frantoi ipogei disseminati nel sottosuolo di Specchia aprono le porte per accogliere e farsi teatro della ricerca artistica di <strong>Officina Minima<\/strong>, progetto sensibile ai temi della sostenibilit\u00e0 ambientale, economica, culturale che allestisce negli ambienti del frantoio ipogeo Scupola <em>Petravolant<\/em>, collezione di sculture e oggetti luminosi creati in seno ad un laboratorio di riuso delle materie; invece nelle viscere del frantoio Cicca l\u2019artista viennese <strong>Ingrid Simon<\/strong> con i salentini <strong>Antonio De Luca<\/strong> e <strong>Fernando Schiavano<\/strong> sono gli autori di <strong><em>Retrats<\/em><\/strong>, sottotitolo \u201copere minute\u201d, che abbraccia piccole sculture, collage e fotografie in bianco e nero.<\/p>\n<p><strong>CREDITS<\/strong><\/p>\n<p><strong>La Festa di Cinema del reale \u00e8 ideata e organizzata da<\/strong><em> <\/em><\/p>\n<p><em>Big Sur, Associazione Cinema del reale e OfficinaVisioni, con la direzione artistica di Paolo Pisanelli<\/em><strong><\/strong><\/p>\n<p><strong>\u00c8 cofinanziata da<\/strong><em> <\/em><\/p>\n<p><em>Unione Europea (Iniziativa cofinanziata con fondi P.O. FESR Puglia 2007-2013 Asse IV &#8211; Linea d&#8217;intervento 4.3), Regione Puglia (Assessorato al Mediterraneo Settore Attivit\u00e0 Culturali) e Fondazione Apulia Film Commission, <\/em><\/p>\n<p><strong>con il contributo<\/strong><em> <\/em><strong>di<\/strong><em> <\/em><\/p>\n<p><em>Comune di Specchia, Ambasciata Svizzera, Consolato Svizzero a Bari <\/em><\/p>\n<p><strong><em>con il patrocinio di<\/em><\/strong><\/p>\n<p><em>Provincia di Lecce (Assessorato alla Cultura) <\/em><\/p>\n<p><strong>in collaborazione con<\/strong><em> <\/em><\/p>\n<p><em>Archivio Audiovisivo del Movimento Operaio e Democratico, DOC IT \u2013 Associazione Documentaristi Italiani, Festival International de Films de Femmes, Festival dei Popoli, Home Movies &#8211; Archivio nazionale del film di famiglia, Cineteca della Calabria, Cineteca Lucana, Teca del Mediterraneo, Corso di Laurea in Scienze della Comunicazione \u2013 Universit\u00e0 del Salento, Centro Servizi Volontariato Salento, Associazione Culturale In alto a sinistra, Associazione Culturale Damagegood, Pe(n)sa differente, Liceo Artistico V. Ciardo &#8211; Lecce<\/em><\/p>\n<p><strong>Media partner<\/strong><em> <\/em><\/p>\n<p><em>Il Paese nuovo, LeccePrima.it, ildocumentario.it, quiSalento, Olivud, servizi cinematografici e televisivi, RadioU\u00e9b.it \u2013 la radio in pillole, The BoxTV \u2013 Corso di Laurea in Scienze della Comunicazione \u2013 Universit\u00e0 del Salento<\/em><strong> <\/strong><\/p>\n<p><strong>Partner<\/strong><em> <\/em><\/p>\n<p><em>Martinucci srl, Cantine Mer\u00ecca, Societ\u00e0 Agricola Merico Maria Rosa, Biosteria Agriostello Piccapane, Mirod\u00eca Laboratorio di cosmesi naturale artigianale, ArtB edizioni d\u2019arte necessaria, BigSurStore.it<\/em><strong><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>CONTATTI<\/strong><\/p>\n<p><strong>Big Sur<\/strong><\/p>\n<p>tel. 0832.346903<\/p>\n<p>cell: 347.1040009<\/p>\n<p><a href=\"http:\/\/www.cinemadelreale.it\">www.cinemadelreale.it<\/a><\/p>\n<p><a href=\"mailto:produzioni@bigsur.it\">produzioni@bigsur.it<\/a><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Ufficio Stampa Nazionale<\/strong><\/p>\n<p>Gabriele Barcaro<\/p>\n<p>cell: 340.5538425<\/p>\n<p><a href=\"mailto:gabriele.barcaro@gmail.com\">gabriele.barcaro@gmail.com<\/a><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Ufficio Stampa Regionale<\/strong><\/p>\n<p>Valeria Raho<\/p>\n<p>cell: 340.6212127<\/p>\n<p><a href=\"mailto:ufficiostampa.damagegood@gmail.com\">ufficiostampa.damagegood@gmail.com<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>__________________________________________________________________<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/07\/18\/a-specchia-dal-25-al-28-luglio-la-festa-del-cinema-del-reale\/locandina-lou-fai-copia\/\" rel=\"attachment wp-att-2948\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/07\/locandina-Lou-fai-copia-211x300.jpg\" alt=\"\" title=\"locandina Lou fai copia\" width=\"211\" height=\"300\" class=\"alignnone size-medium wp-image-2948\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/07\/locandina-Lou-fai-copia-211x300.jpg 211w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/07\/locandina-Lou-fai-copia-721x1024.jpg 721w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/07\/locandina-Lou-fai-copia.jpg 831w\" sizes=\"(max-width: 211px) 100vw, 211px\" \/><\/a><\/p>\n<div>\n<p><strong>Lou fai<\/strong><\/p>\n<p><strong>workshop teorico-pratico <\/strong><\/p>\n<p><strong>sull\u2019autorappresentazione del territorio<\/strong><\/p>\n<p><strong>a cura di Alessia Rollo<\/strong><\/p>\n<p><strong>\u00a0<\/strong><strong>Specchia. Da mercoled\u00ec 25 a venerd\u00ec 27 luglio, le sale di palazzo Risolo ospitano \u201cLou fai\u201d, un workshop sull\u2019autorappresentazione del territorio a cura della fotografa Alessia Rollo. Il corso teorico-pratico si svolge in contemporanea con la Festa del Cinema del Reale ed \u00e8 promosso dal laboratorio di immagini e visioni Big Sur in collaborazione con l\u2019associazione culturale DamageGood.<\/strong><\/p>\n<p>La rappresentazione del territorio, l\u2019intreccio di memorie collettive ed individuali sono al centro di un acceso dibattito nel panorama della fotografia contemporanea. Per alcuni rappresentano le buone pratiche del futuro, per altri sacche di resistenza in difesa di un immaginario che non pu\u00f2 prescindere da contesti, tempi, identit\u00e0. Su questa linea di ricerca si muove \u201cLou fai\u201d (trascrizione fonetica dell\u2019inglese low-fi, ovvero basso profilo), un corso teorico-pratico a cura della fotografa concettuale Alessia Rollo che si svolge a Specchia, presso palazzo Risolo, nei giorni della Festa del cinema del reale.<\/p>\n<p>Il workshop, promosso da Big Sur e in collaborazione con l\u2019associazione culturale DamageGood, \u00e8 un utile strumento per i partecipanti che possono approfondire le proprie conoscenze su autori, noti su scala nazionale ed internazionale, che lavorano sul concetto di autorappresentazione del territorio, prima di approdare alla sessione pratica in cui le testimonianze degli stessi abitanti della Cittadella del cinema saranno fondamentali per orientare gli scatti e le \u201cvisioni\u201d dei fotografi. In linea con le tematiche della rassegna, \u201cLou fai\u201d \u00e8 un laboratorio che scruta Specchia \u201cdal di dentro\u201d, la attraversa e la ferma sulla pellicola di analogiche usa e getta, senza possibilit\u00e0 di replica.<\/p>\n<p>Obiettivo del corso \u00e8 quello di captare e trasmettere realt\u00e0 altrimenti impercettibili agli occhi, che vanno ben oltre le categorie del \u201cpittoresco\u201d e del \u201cbello\u201d. Per questo motivo, la partecipazione al workshop \u00e8 aperta a tutti coloro che intendono sperimentare un nuovo approccio alla \u201cvisione\u201d e ai nuovi linguaggi fotografici e non solo per chi gi\u00e0 mastica la materia. Inoltre, nel corso delle quattro giornate, la documentazione prodotta dai gruppi di lavoro di \u201cLou fai\u201d entrer\u00e0 a far parte dell\u2019archivio personale del Cinema del reale e di una mostra \u201cmurales\u201d allestita negli ambienti del palazzo nobiliare.<\/p>\n<p><strong>Il workshop \u00e8 gratuito<\/strong> e si svolge a Castello Risolo, a Specchia, da mercoled\u00ec 25 (ore 10,30) a venerd\u00ec 27. Le iscrizioni sono aperte per un numero limitato di posti (massimo 15).<\/p>\n<p>Le adesioni devono pervenire <strong>entro e non oltre luned\u00ec 23 luglio<\/strong>.<\/p>\n<p>Per informazioni sul programma, si consiglia di consultare le pagine di Cinema del reale e dell\u2019associazione DamageGood.<\/p>\n<p><strong>\u00a0<\/strong><strong>DamageGood<\/strong><\/p>\n<\/div>\n<p><strong>cell. 328.8638950<\/strong><\/p>\n<p><strong>www.damagegood.com<\/strong><\/p>\n<p><strong><a href=\"mailto:infodamagegood@gmail.com\">infodamagegood@gmail.com<\/a><\/strong><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2012\/07\/18\/a-specchia-dal-25-al-28-luglio-la-festa-del-cinema-del-reale\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/07\/18\/a-specchia-dal-25-al-28-luglio-la-festa-del-cinema-del-reale\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>\u00a0 La Festa di Cinema del reale FESTIVAL DEL CINEMA DOCUMENTARIO Specchia (Lecce) \u2022 25\/28 luglio 2012 IX edizione www.cinemadelreale.it \u00a0 La Festa di Cinema del reale \u00e8 ideata e organizzata da Big Sur, Associazione Cinema del reale e OfficinaVisioni, con la direzione artistica di Paolo Pisanelli, \u00e8 cofinanziata da Unione Europea (Iniziativa cofinanziata con [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2764,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/2763"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=2763"}],"version-history":[{"count":7,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/2763\/revisions"}],"predecessor-version":[{"id":2952,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/2763\/revisions\/2952"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/2764"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=2763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=2763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=2763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}