{"id":27733,"date":"2014-04-15T20:25:25","date_gmt":"2014-04-15T18:25:25","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=27733"},"modified":"2014-04-15T21:27:29","modified_gmt":"2014-04-15T19:27:29","slug":"grillo-finalmente-uno-che-non-chiede-scusa-quando-ha-ragione","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/15\/grillo-finalmente-uno-che-non-chiede-scusa-quando-ha-ragione\/","title":{"rendered":"GRILLO- FINALMENTE UNO CHE NON CHIEDE SCUSA QUANDO HA RAGIONE"},"content":{"rendered":"<p>In Italia non si era mai visto un personaggio pubblico che attaccato (ingiustamente) dalla comunit\u00e1 ebraica, non chiedesse scusa.<\/p>\n<p>Grillo anche in questo ha dimostrato di essere differente. Accusato di utilizzare i campi di concentramento nazisti per fare campagna elettorale ( proprio da coloro che lo fanno da settant&#8217;anni), ha spiegato invece \u00a0che il riferimento al campo di concentramento al cui ingresso si leggeva &#8220;il lavoro rende liberi&#8221;, \u00e8 stato utilizzato proprio per evidenziare un problema, quello del lavoro, delle politiche sul lavoro, che in Italia e non solo, sta determinando uno sterminio, con imprenditori che si ammazzano, famiglie che finiscono sul lastrico e che sta portando decine di migliaia di giovani ad allontanarsi dal nostro paese.<\/p>\n<p>La conferenza stampa doveva essere impostata sul l&#8217;abolizione di Equitalia, invece i giornalisti (foraggiati dai partiti) hanno costretto i leader dei Cinque Stelle a parlare di altro.<\/p>\n<p>Le accuse di antisemitismo in passato sono spesso servite per attaccare chi non condivideva il pensiero unico, ma con Grillo, gli attacchi a base di fascista, nazista, populista e oggi antisemita, sembrano non funzionare.<\/p>\n<p>Cosa si inventeranno i politici servi del potere bancario e i pennivendoli di regime per cercare di fermare la crescita del Movimento di Beppe Grillo?<\/p>\n<p>Una volta si facevano scoppiare le bombe, quando si voleva stabilizzare il potere, oggi non si pu\u00f2 pi\u00f9 fare, e allora cosa si inventeranno?<\/p>\n<p>V.M.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/15\/grillo-finalmente-uno-che-non-chiede-scusa-quando-ha-ragione\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/15\/grillo-finalmente-uno-che-non-chiede-scusa-quando-ha-ragione\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>In Italia non si era mai visto un personaggio pubblico che attaccato (ingiustamente) dalla comunit\u00e1 ebraica, non chiedesse scusa. Grillo anche in questo ha dimostrato di essere differente. Accusato di utilizzare i campi di concentramento nazisti per fare campagna elettorale ( proprio da coloro che lo fanno da settant&#8217;anni), ha spiegato invece \u00a0che il riferimento [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/27733"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=27733"}],"version-history":[{"count":10,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/27733\/revisions"}],"predecessor-version":[{"id":27741,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/27733\/revisions\/27741"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=27733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=27733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=27733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}