{"id":27781,"date":"2014-04-17T09:49:48","date_gmt":"2014-04-17T07:49:48","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=27781"},"modified":"2014-04-17T09:49:48","modified_gmt":"2014-04-17T07:49:48","slug":"san-cesario-via-lassessore-rollo","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/17\/san-cesario-via-lassessore-rollo\/","title":{"rendered":"SAN CESARIO: VIA L&#8217;ASSESSORE ROLLO"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/via-Rollo1_n.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/via-Rollo1_n-220x300.jpg\" alt=\"\" title=\"via Rollo1_n\" width=\"220\" height=\"300\" class=\"alignleft size-medium wp-image-27782\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/via-Rollo1_n-220x300.jpg 220w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/via-Rollo1_n.jpg 704w\" sizes=\"(max-width: 220px) 100vw, 220px\" \/><\/a><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/via-Rollo_n.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/via-Rollo_n-210x300.jpg\" alt=\"\" title=\"via Rollo_n\" width=\"210\" height=\"300\" class=\"alignleft size-medium wp-image-27783\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/via-Rollo_n-210x300.jpg 210w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/via-Rollo_n.jpg 672w\" sizes=\"(max-width: 210px) 100vw, 210px\" \/><\/a>Se l\u2019assessore crede di avere la delega all\u2019ambiente solo per il suo quartiere, allora \u00e8 il caso di scegliere un altro assessore che si occupi finalmente di tutto il territorio di San Cesario!<\/p>\n<p>&#8211; Arriva sui manifesti in paese lo sdegno dei cittadini al comportamento dell\u2019assessore all\u2019ambiente del PD.<\/p>\n<p>\u00c8 stato troppo sentirsi rispondere -: \u201cSe volete vedere il paese pulito, non guardate San Cesario ma venite nel quartiere Aria Sana, dove abito io!\u201d<\/p>\n<p>\u00c8 un offesa per tutti gli altri cittadini che pagano le tasse!<\/p>\n<p>&nbsp;<\/p>\n<p>Sui muri per il paese si la denuncia dei cittadini :<\/p>\n<p>&nbsp;<\/p>\n<p>-Questa, tra l\u2019altro, \u00e8 solo una delle tante affermazioni, in un susseguirsi di delirio di onnipotenza, fatte luned\u00ec 16aprile dall\u2019assessore all\u2019ambiente di San Cesario Giovanni Rollo che rispondeva (ma sarebbe pi\u00f9 corretto dire \u201cnon rispondeva\u201d) alle domande dei cittadini in un incontro pubblico. Cittadini che giustamente volevano solo sapere quali politiche ambientali siano state adottate in questi 2anni per il paese. Ma niente! Dall\u2019assessore solo un atteggiamento di sufficienza e di superiorit\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<p>E dire che una risposta avrebbe rasserenato gli animi, visto le proteste degli ultimi giorni e visto che, guardando i risultati in giro per il paese, l\u2019impegno dell\u2019assessore -dicono nel manifesto i cittadini &#8211; sembrerebbe sia stato Zero, anzi Zero pi\u00f9 Zero!<\/p>\n<p>-Si continua-:<\/p>\n<p>&nbsp;<\/p>\n<p>Se l\u2019assessore pensa davvero, cos\u00ec come arriva a riferire, che le persone capiscono di essere a San Cesario perch\u00e9 vedono la &#8220;sua&#8221; Aria Sana, forse dovrebbe farsi un bel bagno di umilt\u00e0, scoprirebbe come San Cesario abbia una storia ed una cultura antichissima e che di certo non \u00e8 sulle cartine geografiche perch\u00e9 dista 2km da casa sua\u2026<\/p>\n<p>&nbsp;<\/p>\n<p>Dall&#8217;associazione Sveglia Cittadina, promotrice dell&#8217;iniziativa, il presidente Emanuele Lezzi si dice sconcertato dalle parole dell&#8217;assessore:<\/p>\n<p>\u201cE giustissimo &#8211; afferma &#8211; che il quartiere Aria Sana sia pulito(anche se a guardare nemmeno li l&#8217;assessore a brillato in maniera particolare), com\u2019\u00e8 giusto che lo siano tutti i quartieri del paese che invece sono colmi di cartacce, escrementi di animali ed erba alta, oltre ad avere un pi\u00f9 generale degrado che non dipende purtroppo solo dall\u2019assessore Rollo. Ma da cittadini ci domandiamo: le persone che non hanno &#8220;conoscenze in alto&#8221; ed anche i cittadini dell\u2019Aria Sana, hanno oppure no il diritto di pretendere, da chi gestisce le politiche ambientali, un\u2019uniformit\u00e0 programmatica che non li faccia vergognare di mostrare il loro paese ad altri?<\/p>\n<p>Possono sapere quali sono le politiche attuate fin\u2019ora dall\u2019assessore o debbono per forza rassegnarsi alle solite \u201cmarchette politiche\u201d a spese di tutti e per fini puramente elettorali?<\/p>\n<p>L\u2019azione amministrativa, deve necessariamente essere programmata e ponderata a monte per funzionare in maniera positiva, in altro modo i risultati di un\u2019approssimazione e di un\u2019azione \u201cvotata alla vicinanza\u201d, non possono che essere scadenti.<\/p>\n<p>&nbsp;<\/p>\n<p>Noi ci rivolgiamo al Sindaco, perch\u00e9 vogliamo credere che abbia nel suo schieramento di certo personalit\u00e0 migliori.<\/p>\n<p>E ci rivolgiamo all\u2019opposizione in consiglio comunale, che poi nei numeri elettorali \u00e8 maggioranza nel paese: Per favore, facciamo in modo di lavorare per il bene di tutti, iniziando a mandare a casa alcuni personaggi!\u201d<\/p>\n<p>_________________________________________<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/17\/san-cesario-via-lassessore-rollo\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/17\/san-cesario-via-lassessore-rollo\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Se l\u2019assessore crede di avere la delega all\u2019ambiente solo per il suo quartiere, allora \u00e8 il caso di scegliere un altro assessore che si occupi finalmente di tutto il territorio di San Cesario! &#8211; Arriva sui manifesti in paese lo sdegno dei cittadini al comportamento dell\u2019assessore all\u2019ambiente del PD. \u00c8 stato troppo sentirsi rispondere -: [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":27783,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/27781"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=27781"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/27781\/revisions"}],"predecessor-version":[{"id":27784,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/27781\/revisions\/27784"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/27783"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=27781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=27781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=27781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}