{"id":27859,"date":"2014-04-18T10:56:58","date_gmt":"2014-04-18T08:56:58","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=27859"},"modified":"2014-04-18T10:56:58","modified_gmt":"2014-04-18T08:56:58","slug":"florarte-2014","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/18\/florarte-2014\/","title":{"rendered":"Florarte 2014"},"content":{"rendered":"\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 20%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\t\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-27859 gallery-columns-5 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/18\/florarte-2014\/florarte-mappa-e-programma\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/Florarte-Mappa-e-Programma-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/Florarte-Mappa-e-Programma-150x150.jpg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/Florarte-Mappa-e-Programma-298x300.jpg 298w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/Florarte-Mappa-e-Programma.jpg 824w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/18\/florarte-2014\/florarte-01\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/Florarte-01-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n<p>\u2026 tra forme colori e sensazioni<\/p>\n<p style=\"text-align: left;\" align=\"center\">1\u00b0 CONCORSO INTERNAZIONALE DI ARTE FLOREALE.<br \/>\nC&#8217;\u00e8 grande attesa per \u201cFlorarte 2014\u201d,<strong> il primo concorso internazionale di Arte Floreale, che si terr\u00e0 il 26 e il 27 Aprile a San Pietro in Lama<\/strong>, in provincia di Lecce.\u00a0 A organizzare l&#8217;evento l\u2019International Floral School \u201cL\u2019Altralinfa\u201d di San Don\u00e0 di Piave (Ve), \u201cla Bottega del Fiore\u201d di San Pietro in Lama e l&#8217;architetto Salvatore Coroneo di San Donato di Lecce.<\/p>\n<p>Ancora una volta il Salento viene scelto come palcoscenico di una manifestazione di carattere internazionale che diffonder\u00e0 la bellezza del nostro Barocco Leccese, tema del concorso floreale, nel mondo.<\/p>\n<p>&nbsp;<\/p>\n<p>L&#8217;originale progetto nasce da un&#8217;idea di professionisti con l&#8217;obiettivo comune di realizzare un evento di respiro internazionale, diretto ad arricchire la conoscenza dell&#8217;Arte come autentica espressione di nobile manualit\u00e0, di gusto del bello estetico e del piacere sensoriale.<\/p>\n<p>&nbsp;<\/p>\n<p>L&#8217;invito, esteso a scuole di storica importanza didattica di arte floreale, \u00e8 stato accettato con orgoglio e le presenze ad oggi ricevute lo confermano. <strong>A prendere parte alla kermesse saranno infatti due squadre Norvegesi, due squadre dell\u2019Ucraina, due squadre della Siberia, tre squadre Italiane, un team dalla Finlandia, uno dalla Latvia, uno dalla Russia, ed infine, uno dalla Lituania.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019evento, primo in Italia sul generis, \u00e8 stato creato con la prerogativa che scambi culturali e modi diversi di lavorare possano aumentare il bagaglio culturale di ciascuno, mettendo a confronto i vari artisti.<\/p>\n<p>E come disse\u00a0 San Francesco d&#8217;Assisi: &#8221;Chi lavora con le mani \u00e8 un operaio, chi lavora con le mani e con la testa \u00e8 un artigiano, chi lavora con le mani, la testa e il cuore \u00e8 un artista&#8221;. Affermazione che \u00e8 stata fonte di ispirazione per tutti gli organizzatori dell\u2019evento: l\u2019architetto Salvatore Coroneo di San Donato di Lecce, i docenti della scuola \u201cL&#8217;Altralinfa\u201d, nelle persone dell\u2019ideatore della stessa Ivan Berghella, maestro internazionale di arte floreale, Assunta Bottacin (flower designer), Laura Bottacin (responsabile dello show room e laboratorio), ed infine\u00a0 \u201cla Bottega del Fiore\u201d di San Pietro in Lama nelle persone di Francesco Durante ed Anna Maria Spedicato (flower design e docente della scuola L\u2019Altralinfa).<\/p>\n<p>&nbsp;<\/p>\n<p><strong>La manifestazione si svolger\u00e0\u00a0 il 26 e il 27 Aprile, dalle ore 9:30 alle ore 24:00, per le vie del centro storico di San Pietro in Lama<\/strong>, partendo dal Museo Caroli (Fondazione Memmo) sino alla via Margherita di Savoia,\u00a0 percorrendo nel mezzo la via Roma, via De Carlo e Largo Chiesa (Chiesa Maria SS. Assunta). Le vie, le corti e le Chiese saranno addobbate e decorate da fiori, installazioni artistiche di architetti, vivai e floricoltori, e tante altre opere realizzate da scuole, artisti, designer, associazioni socio-culturali, e da mercati floricoli italiani ed esteri. Agli occhi dei visitatori tutto ci\u00f2 render\u00e0 delle \u201canonime\u201d e \u201cvecchie\u201d vie una vera e propria galleria d\u2019arte all\u2019aperto.<\/p>\n<p>Nel corso delle due giornate verranno organizzate delle visite guidate per le vie di San Pietro in Lama e Domenica 27 alle ore 18:00 in P.za del Popolo, chiuder\u00e0 l\u2019evento internazionale il convegno a cura di Don Michele Giannone sul tema: &#8221;Il Fiore tra Bibbia Liturgia ed Arte&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>L\u2019evento sar\u00e0 allietato da musica live, dj, stand dolciari, gonfiabili per i bambini, \u201cCuore Amico\u201d, e tanto tanto ancora \u2026<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>\u201cFlorarte 2014\u201d \u00e8 stato realizzato in collaborazione con il Comune di San Pietro in Lama e con il patrocinio del Comune di Leverano, dell\u2019Albo degli Architetti della Prov. di Lecce, della Coop. Agricola San Rocco di Leverano, del Comune di Terlizzi, della Regione Puglia &#8221;Forestale&#8221;, della Confartigianato di Lecce, del Gal-Valle della Cupa, della Proloco di San Pietro in Lama e dell\u2019Agenzia Regionale del Turismo \u201cPuglia Promozione\u201d.<\/p>\n<p><span style=\"text-decoration: underline;\">\u00a0<\/span><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/18\/florarte-2014\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/18\/florarte-2014\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>\u2026 tra forme colori e sensazioni 1\u00b0 CONCORSO INTERNAZIONALE DI ARTE FLOREALE. C&#8217;\u00e8 grande attesa per \u201cFlorarte 2014\u201d, il primo concorso internazionale di Arte Floreale, che si terr\u00e0 il 26 e il 27 Aprile a San Pietro in Lama, in provincia di Lecce.\u00a0 A organizzare l&#8217;evento l\u2019International Floral School \u201cL\u2019Altralinfa\u201d di San Don\u00e0 di Piave [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/27859"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=27859"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/27859\/revisions"}],"predecessor-version":[{"id":27862,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/27859\/revisions\/27862"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=27859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=27859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=27859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}