{"id":27920,"date":"2014-04-22T20:45:13","date_gmt":"2014-04-22T18:45:13","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=27920"},"modified":"2014-04-22T20:45:41","modified_gmt":"2014-04-22T18:45:41","slug":"dal-monastero-dei-frati-francescani-conventuali-alla-casa-della-convivialita-don-tonino-bello","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/22\/dal-monastero-dei-frati-francescani-conventuali-alla-casa-della-convivialita-don-tonino-bello\/","title":{"rendered":"DAL \u201cMONASTERO DEI FRATI FRANCESCANI CONVENTUALI\u201d  ALLA   \u201cCASA DELLA CONVIVIALITA&#8217; &#8211; DON TONINO BELLO \u201d"},"content":{"rendered":"\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 20%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\t\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-27920 gallery-columns-5 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/22\/dal-monastero-dei-frati-francescani-conventuali-alla-casa-della-convivialita-don-tonino-bello\/chiesa\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/chiesa-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/22\/dal-monastero-dei-frati-francescani-conventuali-alla-casa-della-convivialita-don-tonino-bello\/chiostro\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/chiostro-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n<p>Fra pochi giorni la comunit\u00e0 di Alessano potr\u00e0 finalmente tornare a fruire di una struttura che per secoli \u00e8 stata quasi sepolta e dimenticata, e che grazie alla tenacia e l&#8217;impegno del parroco di Alessano don Gigi Ciardo, ha ritrovato tutta la sua luce nel segno della semplicit\u00e0 e dell&#8217;essenziale che contraddistinguono strutture antiche come conventi e monasteri: stiamo parlando dell&#8217;ex monastero dei frati Conventuali Francescani, annesso alla chiesa di Sant&#8217;Antonio.<\/p>\n<p>Da ricerche effettuate dallo storico Mauro Ciardo di Gagliano \u00e8 emerso che la prima fondazione di un insediamento conventuale dei frati francescani ad Alessano sarebbe da far risalire tra il 1222 e il 1228, secondo una tradizione consolidata riportata nel 1693 dal padre Luigi Tasselli nel suo libro \u201cAntichit\u00e0 di Leuca\u201d,\u00a0 e la presenza ben strutturata del complesso viene ulteriormente testimoniata nel 1334, quando questa realt\u00e0 viene elencata nel volume del \u201c<em>Provinciale ordinis fratrum minorum vetustissimum<\/em>\u201d di Paolino da Venezia.<\/p>\n<p>Testimonianze pi\u00f9 tarde del convento e dell\u2019annessa chiesa risalgono al 1542, quando sappiamo con certezza che l\u2019edificio sacro era affrescato al suo interno e che contava come frate custode Vincenzo d\u2019Oria (la cui firma \u00e8 incisa su un affresco di Sant\u2019Antonio da Padova collocato nella navata a sinistra).<\/p>\n<p>Una prima rappresentazione dello stabile \u00e8 datata al 12 febbraio 1628, quando il convento viene visitato e descritto dal visitatore apostolico monsignor Andrea Perbenedetti che cita la presenza di cinque frati e una rendita del convento di 250 ducati. Tra le altre cose viene citata ad esempio la presenza di un cancello ligneo che conduce all\u2019altare maggiore e un affresco con dipinta l\u2019immagine di Santa Maria di Costantinopoli. All\u2019epoca la chiesa era costituita da un\u2019unica navata e nel convento ogni frate vive e dorme in singole celle.<\/p>\n<p>Nel corso del secoli non mancarono poi le donazioni a favore del convento, come quella giunta il 23 ottobre 1679, quando il chierico Berardino Alfarano don\u00f2 \u201c<em>inter vivos<\/em>\u201d al convento di S<br \/>\nan Francesco alcuni vigneti con l&#8217;obbligo per i beneficiari di<br \/>\nvenderli per acquistare beni stabili con onere di messe.<\/p>\n<p>Nel 1771 il convento viene sopraelevato visti l\u2019accresciuto numero dei frati e delle sostanze materiali della comunit\u00e0, ma con l\u2019avvento napoleonico anche questa struttura subir\u00e0 l\u2019incameramento prima della trasformazione della chiesa come sede della congrega del Rosario nel 1834.<\/p>\n<p>Nel corso dei primi decenni del XX secolo lo stabile, passato in mano ai privati, viene accresciuto ulteriormente nella parte superiore con l\u2019impianto di un magazzino per la trasformazione del tabacco, mentre nella seconda met\u00e0 ha visto diversi ambienti trasformati in officine per la produzione di conserve alimentari oppure per la riparazione di veicoli.<\/p>\n<p>La struttura nella sua consistenza attuale \u00e8 stata nel tempo acquisita dalla Parrocchia SS. Salvatore: nel 2001\u00a0 Antonio Torsello don\u00f2 alla parrocchia una parte del piano terra (125 mq) ed una parte del primo piano (320 mq); nel 2003 Donato Torsello don\u00f2 altri 200 mq del piano superiore, e negli anni tra il 2005 ed il 2010 sono stati acquistate altre porzioni dell&#8217;immobile.<\/p>\n<p>&nbsp;<\/p>\n<p>In considerazione del fatto che in Alessano \u00e8 molto cresciuta la richiesta di accoglienza e ricezione da parte di fedeli che numerosi accorrono sulla tomba di Don Tonino Bello Vescovo di Molfetta, soprattutto da quando \u00e8 stato avviato il processo di Canonizzazione a Servo di Dio, nasce quasi in maniera consequenziale e naturale l&#8217;idea di realizzare un centro di accoglienza che possa ospitare i pellegrini in un luogo, che per le sue caratteristiche e la sua ubicazione, \u00e8 in perfetta armonia con la spiritualit\u00e0 che i fedeli cercano nel loro pellegrinaggio ad Alessano.<\/p>\n<p>Parte cos\u00ec nel 2009 la prima fase di studio e progettazione dell&#8217;intervento di valorizzazione e riqualificazione di questo complesso conventuale di indiscutibile valore culturale,\u00a0 per il riattamento dello stesso ad una destinazione d&#8217;uso compatibile con le intrinseche caratteristiche architettoniche e tipologiche della struttura.<\/p>\n<p>La modalit\u00e0 di approccio e sviluppo del progetto \u00e8 dettata dalla ferma volont\u00e0 di conservare l&#8217;aspetto e la modalit\u00e0 di fruizione degli spazi esterni ed esterni cos\u00ec come originariamente vissuti, sia pure con i necessari adeguamenti della struttura alle esigenze di tipo igienico e funzionale.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>La struttura \u00e8 completamente in muratura di conci di tufo, sia per le murature perimetrali e di tramezzatura, sia per le coperture che sono del tipo a volta\u00a0 a stella ed a botte.<\/p>\n<p>La distribuzione planimetrica dell\u2019edificio \u00e8 quella tipica di un monastero benedettino con al piano terra un chiostro centrale\u00a0 delimitato su tre lati da un porticato e sul quarto lato dalla navata laterale della chiesa; intorno al porticato sono disposti diversi vani che in origine dovevano essere locali di servizio (stalle, magazzini, depositi) ed anche l\u2019importante refettorio con le annesse cucine e servizi; dall\u2019ala nord-est del porticato si accede all\u2019imponente scala\u00a0 che conduce al primo piano dove\u00a0 due ampi e maestosi corridoi\u00a0 conducono a quelle che erano le celle dei frati , tra cui vi \u00e8 una zona che poteva essere il fuoco comune e l\u2019appartamento del priore; poi vi sono due grandi sale, una coperta con sei volte a stella\u00a0 ed una coperta con una struttura piana\u00a0 che sono di epoca pi\u00f9 recente, come si intuisce dai particolari e dalle tecniche costruttive.<\/p>\n<p>&nbsp;<\/p>\n<p align=\"center\">Vista del chiostro e relativo porticato<\/p>\n<p align=\"center\">\u00a0Scala di accesso al primo piano<\/p>\n<p>La consistenza della struttura in termini di superfici \u00e8 di circa 470 mq al piano terra, oltre al chiostro di 200 mq, ed\u00a0 di circa 900 mq al primo piano.\u00a0 Al piano terra avremo un ingresso che conduce direttamente nel porticato del chiostro, che verr\u00e0 chiuso verso l&#8217;esterno con infissi a vetro, funger\u00e0 da distribuzione ai vari ambienti e precisamente: una zona di prima accoglienza dei pellegrini, i servizi igienici\u00a0 (ai quali si potr\u00e0 accedere anche direttamente dall&#8217;esterno), i servizi per il personale, il salone per il pranzo (il vecchio refettorio del convento), le cucine, la scala e l&#8217;ascensore che conducono al piano superiore.<\/p>\n<p>Al primo piano troviamo l&#8217;antico impianto del convento, con spaziosi corridoi che danno accesso alle 15 camere con bagno (per un totale di 23 posti letto), ed altri vani\u00a0 adibiti a direzione, ambulatorio, deposito per biancheria, lavanderia e stireria, ed una grande sala pluriuso per attivit\u00e0 di intrattenimento.<\/p>\n<p align=\"center\">Particolare volta botte porticato<\/p>\n<p><strong><span style=\"text-decoration: underline;\">\u00a0<\/span><\/strong><\/p>\n<p><span style=\"text-decoration: underline;\">\u00a0DESCRIZIONE DELL\u2019INTERVENTO<\/span><\/p>\n<p>L&#8217;intervento di recupero \u00e8 stato progettato\u00a0 e curato\u00a0 dai tecnici ing. Emanuela Torsello per la parte architettonica e funzionale, dall&#8217;ing. Giorgio Martella per la parte impiantistica, e dall&#8217;ing. Giorgio De Marinis per la parte statica e della sicurezza, ed eseguito con la supervisione della Soprintendenza ai Beni Culturali e Architettonici della provincia di Lecce.<\/p>\n<p>Le opere sono iniziate nel mese di novembre del 2010 e\u00a0 si possono sintetizzare in tre principali categorie:<\/p>\n<p>1)\u00a0\u00a0 Consolidamento statico e ricostruzione dell&#8217;ala crollata:<\/p>\n<p>la prima fase \u00e8 stata il consolidamento in fondazione dello spiccato delle colonne che sostengono il porticato a piano terra realizzato con travi continue in cemento armato (eseguito dalla ditta Ciullo Restauri da Taurisano), ed il consolidamento delle 9 colonne perimetrali del porticato che delimita il chiostro con perforazioni armate\u00a0 (eseguito dalla ditta Pedone Oronzo di Alessano); successivamente \u00e8 stata ricostruita l&#8217;ala nord-est del porticato e delle celle a primo piano (crollate nel mese di novembre 2010) ad opera della ditta Sperti Luigi da Barbarano;\u00a0 a seguire il consolidamento della volta a botte dell&#8217;ala nord-ovest\u00a0 del porticato con l&#8217;inserimento di catene in acciaio, delle volte a spigolo delle 4 celle al piano superiore eseguita all&#8217;estradosso della copertura con la stesura di nastri in fibre d&#8217;acciaio e malta a base di calce fibrorinforzata, delle 6 volte a spigolo del salone a primo piano realizzato sempre con inserimento di catene in acciaio (eseguito dalla ditta Mastrotempo &amp; Partners S.r.l. di Alessano)<span style=\"text-decoration: underline;\">.<\/span><\/p>\n<p>2) Dotazione di impianti tecnologici:<\/p>\n<p>la struttura era completamente sprovvista di qualunque impianto tecnologico, pertanto sono stati realizzati integralmente l&#8217;impianto elettrico sottotraccia, l&#8217;impianto di climatizzazione invernale, l&#8217;impianto idrico e fognante per tutti i servizi, compreso gli allacci alle reti pubbliche di fornitura di acqua, fogna, energia elettrica e\u00a0 gas (sono stati eseguiti rispettivamente dalle ditte Angelo Stefanelli di Specchia e Alfredo Milo di Barbarano);<\/p>\n<p>3)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Recupero delle facciate, pavimenti e rivestimenti:<\/p>\n<p>Il recupero dei paramenti murari delle facciate esterne sono stati eseguiti tramite pulitura e rimozione di muschi ed incrostazioni, stilatura dei giunti, scialbatura con latte di calce e pigmenti naturali di terre colorate, protezione idrorepellente finale, sono stati recuperati tutte le pavimentazioni in battuto di calce e cocciopesto del piano superiore e quelle musive del piano terra, integrando e rifacendo ex novo quelle mancanti con tipologie analoghe a quelle esistenti;<\/p>\n<p>sulle pareti interne sono stati recuperati, dove possibile, i vecchi intonaci, e dove\u00a0 deteriorati\u00a0 e distaccati\u00a0\u00a0 sono stati eseguiti intonaci di grassello di calce con tecniche e materiali che richiamano gli intonaci tradizionali dei luoghi, completando il tutto con velatura di calce rigorosamente bianca (esecuzione da parte della ditta Mastrotempo &amp; Partners S.r.l. di Alessano).<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>4) Dotazione di porte e finestre:<\/p>\n<p>Porte e finestre sono state realizzate in legno di abete, ricalcando una tipologia ed uno stile simili a quelli esistenti, sia pure con inserimento di vetri doppi per garantire un idoneo isolamento termo-acustico (realizzati ed installati dalle ditte De Solda Pasquale di Gagliano e Vozza Fabirzio di Barbarano).<\/p>\n<p>Le 16 arcate del porticato che delimitano il chiostro saranno chiuse con vetrate ad intelaiatura in ferro (eseguite dalla ditta Trifone Amico di Alessano)<\/p>\n<p>5) arredi ed attrezzature:<\/p>\n<p>la struttura \u00e8 stata dotata anche di un ascensore per l&#8217;abbattimento delle barriere architettoniche con struttura autonoma ed autoportante in acciaio e vetro (installato dalla ditta IRMA Ascensori di Taurisano); gli arredi delle camere e degli spazi comuni sono stati eseguiti artigianalmente in legname di abete ispirandosi ad una linea semplice ed essenziale che il luogo richiede (realizzati dalle ditte \u201cFalegnameria Giuseppe Torsello \u201c e \u201cTecnolegno di Francesco Torsello\u201d di Alessano)<\/p>\n<p>&nbsp;<\/p>\n<p><em>Tutto questo \u00e8 stato possibile grazie alla dedizione del nostro parroco don Gigi Ciardo, alla generosit\u00e0 di tutta la comunit\u00e0 parrocchiale, al contributo della CEI e soprattutto alla passione\u00a0 che ha coinvolto tutti coloro che hanno collaborato a vario titolo al recupero della struttura.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Emanuela Torsello<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/22\/dal-monastero-dei-frati-francescani-conventuali-alla-casa-della-convivialita-don-tonino-bello\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/22\/dal-monastero-dei-frati-francescani-conventuali-alla-casa-della-convivialita-don-tonino-bello\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Fra pochi giorni la comunit\u00e0 di Alessano potr\u00e0 finalmente tornare a fruire di una struttura che per secoli \u00e8 stata quasi sepolta e dimenticata, e che grazie alla tenacia e l&#8217;impegno del parroco di Alessano don Gigi Ciardo, ha ritrovato tutta la sua luce nel segno della semplicit\u00e0 e dell&#8217;essenziale che contraddistinguono strutture antiche come [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/27920"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=27920"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/27920\/revisions"}],"predecessor-version":[{"id":27925,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/27920\/revisions\/27925"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=27920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=27920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=27920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}