{"id":27926,"date":"2014-04-22T20:46:54","date_gmt":"2014-04-22T18:46:54","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=27926"},"modified":"2014-04-22T20:46:54","modified_gmt":"2014-04-22T18:46:54","slug":"giornata-mondiale-della-terra-2","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/22\/giornata-mondiale-della-terra-2\/","title":{"rendered":"\u201cGIORNATA MONDIALE DELLA TERRA\u201d"},"content":{"rendered":"<p style=\"text-align: left;\" align=\"center\">Domani, mercoled\u00ec 23 aprile, alle ore 11, nella sala conferenze stampa di Palazzo Adorno a Lecce, si terr\u00e0 la presentazione della Giornata Mondiale della Terra 2014, promossa dalla Provincia di Lecce e dal difensore civico, in collaborazione con il Comune di Nard\u00f2, dove sar\u00e0 celebrata il 28 aprile prossimo.<\/p>\n<p>&nbsp;<\/p>\n<p>Interverranno il presidente della Provincia di Lecce Antonio Gabellone, il difensore civico Giorgio De Giuseppe e il vicesindaco con delega alla Pubblica istruzione del Comune di Nard\u00f2 Carlo Falangone.<\/p>\n<p>&nbsp;<\/p>\n<p>Celebrata in oltre 200 Paesi, in tutto il mondo, la Giornata Mondiale della Terra \u00e8 stata istituita nel 2012 dal Consiglio provinciale di Lecce, su sollecitazione del difensore civico De Giuseppe, diventando un importante appuntamento annuale, in cui amministratori e cittadini sono invitati a riflettere insieme sul futuro del pianeta.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/22\/giornata-mondiale-della-terra-2\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/22\/giornata-mondiale-della-terra-2\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Domani, mercoled\u00ec 23 aprile, alle ore 11, nella sala conferenze stampa di Palazzo Adorno a Lecce, si terr\u00e0 la presentazione della Giornata Mondiale della Terra 2014, promossa dalla Provincia di Lecce e dal difensore civico, in collaborazione con il Comune di Nard\u00f2, dove sar\u00e0 celebrata il 28 aprile prossimo. &nbsp; Interverranno il presidente della Provincia [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/27926"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=27926"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/27926\/revisions"}],"predecessor-version":[{"id":27928,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/27926\/revisions\/27928"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=27926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=27926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=27926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}