{"id":27935,"date":"2014-04-22T20:54:01","date_gmt":"2014-04-22T18:54:01","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=27935"},"modified":"2014-04-22T20:54:01","modified_gmt":"2014-04-22T18:54:01","slug":"ritirate-dai-carabinieri-di-gallipoli-18-patenti-per-guida-in-stato-di-ebbrezza-alcolica","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/22\/ritirate-dai-carabinieri-di-gallipoli-18-patenti-per-guida-in-stato-di-ebbrezza-alcolica\/","title":{"rendered":"RITIRATE DAI CARABINIERI DI GALLIPOLI 18 PATENTI PER GUIDA IN STATO DI EBBREZZA ALCOLICA."},"content":{"rendered":"<p style=\"text-align: left;\" align=\"center\"><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/CARABINIERI4.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/CARABINIERI4-300x200.jpg\" alt=\"\" title=\"CARABINIERI4\" width=\"300\" height=\"200\" class=\"alignleft size-medium wp-image-21285\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/CARABINIERI4-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/CARABINIERI4.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Nel finesettimana lungo di Pasqua e pasquetta i carabinieri della compagnia di Gallipoli, sono stati impegnati su tutto il territorio di loro competenza, con un capillare servizio a largo raggio. In sintesi, sono stati eseguiti controlli, principalmente finalizzati a contrastare il perpetrarsi di reati in genere, nonche\u2019 il fenomeno della guida in stato di ebbrezza, approfittando del fatto che, con le festivita\u2019 molti giovani e meno giovani si siano concessi qualche bicchiere di troppo. All\u2019attivita\u2019 di controllo hanno partecipato pattuglie della dipendente aliquota radiomobile, nonche\u2019 militari della tenenza di copertino e delle stazioni dipendenti, per un totale di n.45 militari e n. 23 automezzi. Il dispositivo e\u2019 stato dispiegato principalmente nelle aree cittadine e periferiche di Gallipoli, Galatina, Nardo\u2019 e Copertino anche con l\u2019impiego di militari in abiti civili che si sono frammischiati ai turisti che hanno gia\u2019 cominciato ad\u00a0 affollare le marine di Gallipoli e Nardo\u2019. Complessivamente, i controlli hanno permesso di ottenere i seguenti risultati:<\/p>\n<p>Quattro soggetti sono stati deferiti in stato di liberta\u2019 per spaccio di sostanze stupefacenti: il primo b.a. 52enne gallipolino e\u2019 stato visto cedere due dosi di marijuana a due diversi soggetti. La successiva perquisizione domiciliare nella casa dell\u2019uomo permetteva di rinvenire materiale per il confezionamento ed il taglio della sostanza. Uno dei due assuntori, t.f. 27enne gallipolino, nonostante l\u2019evidenza dei fatti, ha negato di aver appena acquistato una dose di sostanza stupefacente ed e\u2019 stato quindi deferito in stato di liberta\u2019 per favoreggiamento personale. Z.s. 29enne di Galatone, e\u2019 stato visto cedere una dose di marijuana ad un ragazzo. La perquisizione domiciliare permetteva di rinvenire un bilancino di precisione. Il terzo, un 26enne sempre della citta\u2019 galatea d.a., e\u2019 stato notato cedere una dose di eroina ad un tossicodipendente. La perquisizione domiciliare permetteva di rinvenire dieci dosi di cocaina per un peso complessivo di gr. 3,2 e materiale per il confezionamento. Infine a.a. 20enne di Trepuzzi e\u2019 stata notata dai militari della compagnia cedere una dose di marijuana ad un altro soggetto con lei presente. E.d.d. 20enne gallipolino, invece, e\u2019 stato trovato in possesso di tre dosi di marijuana, per complessivi 5,6 grammi, all\u2019interno degli slip. Per questo e\u2019 stato deferito in stato di liberta\u2019 per detenzione ai fini di spaccio di sostanze stupefacenti. Identica sorte per t.v. 19enne tarantino, trovato in possesso di 5 grammi di marijuana e tre dosi di cocaina nascoste nel vano portaoggetti dell\u2019auto. A copertino i militari dell\u2019arma locale hanno deferito in stato di liberta\u2019 v.a. 32enne di galatina, con l\u2019accusa di tentata estorsione. Il soggetto si e\u2019 presentato all\u2019interno di un esercizio commerciale chiedendo al titolare una somma di denaro minacciandolo, in caso di diniego, di ritorsioni e millantando conoscenze criminali. Il titolare del bar, senza farsi notare, ha chiamato subito i carabinieri che, giunti sul posto, hanno potuto fermare il soggetto e deferirlo in stato di liberta\u2019. I controlli a tappeto in tutto il territorio della compagnia hanno altresi\u2019 permesso di reprimere una serie di reati contro il patrimonio ed assicurare alla giustizia numerosi malviventi che, approfittando delle \u201cgite fuori porta\u201d verso i lidi, mettevano in atto le proprie condotte illecite nei centri dell\u2019entroterra, semideserti. Una donna 22enne di galatina e\u2019 stata denunciata per ricettazione essendo stata trovata in possesso di un cellulare risultato oggetto di furto nel mese di gennaio scorso. Un 50enne di Carmiano, invece, e\u2019 stato deferito in stato di liberta\u2019 per il reato di truffa, avendo simulato la vendita di un cellulare tramite un sito di aste online, ricevendo la somma pattuita ma non inviando mai la merce all\u2019acquirente. Quattro persone, complessivamente, sono state deferite in stato di liberta\u2019 per furto. Due di queste, un galatinese di 60anni e una rumena 30enne, sono stati fermati all\u2019uscita di un supermercato della citta\u2019 galatinese avendo appena sottratto alcuni prodotti cosmetici per un valore di 14,00 euro. Un\u2019altra rumena di 24anni, residente a Martano, e\u2019 stata fermata all\u2019uscita di un altro supermercato di Galatina con addosso derrate alimentari appena rubate per un valore di \u20ac 24,00, mentre un 42enne di Parabita, impiegato presso un supermercato di Gallipoli, e\u2019 stato visto dai colleghi appropriarsi di alcuni giocattoli per un valore di \u20ac 50,00. Chiamata la pattuglia, e\u2019 stato fermato e perquisito e deferito in stato di liberta per furto aggravato. Due soggetti sono stati deferiti per danneggiamento: il primo m.m. 62enne di Aradeo, e\u2019 stato fermato dopo aver rigato, con un punteruolo, quattro autovetture parcheggiate sulla pubblica via: sconosciuto il motivo del gesto. Un 44enne di Alezio, invece, dopo una lite per futili motivi con un amico, ha preso una spranga di ferro ed ha iniziato a sferrare colpi all\u2019autovettura dell\u2019amico, danneggiandola. Immediatamente e\u2019 stato fermato dai carabinieri e denunciato. Il servizio a largo raggio attuato ha altresi\u2019 visto i militari impegnati nel contrasto alla guida in stato di ebbrezza e nei controlli alla circolazione stradale. Per venti automobilisti e\u2019 scattato il deferimento in stato di liberta\u2019 per guida in stato di ebbrezza per l\u2019alto tasso alcolemico presente nel sangue, superiore alla soglia minima di 0,80 g\/l. In un caso si sono raggiunti i 1.97 g\/l quindi quasi quattro volte superiore alla soglia minima. In un caso, oltretutto, ad essere trovato ubriaco al volante e\u2019 stato il conducente di un pullman di ragazzi venuti dal barese per passare la pasquetta sul litorale gallipolino e partecipare ad uno dei concerti organizzati nella citta\u2019 bella. Immediatamente fermato e ritirata la patente, e\u2019 stato necessario far venire un altro autista dalla provincia di Bari per poter permettere al gruppo di malcapitati giovani di far rientro nelle proprie case. Trenta in tutto le patenti ritirate, 80 le contravvenzioni al codice della strada elevate, per violazioni che vanno dalla guida senza cinture di sicurezza all\u2019uso del telefono cellulare alla guida, alla mancanza di copertura assicurativa ed alla mancata revisione del veicolo. Oltre 120 i punti tolti alle patenti dei malcapitati guidatori. Dieci i soggetti trovati alla guida senza aver mai conseguito la patente o privi della stessa perche\u2019 revocata, uno di loro, tra l\u2019altro, trasportava materiali ferrosi raccolti senza la prevista autorizzazione. E\u2019 stato deferito anche per questo motivo. Un soggetto fermato ad un posto di controllo, gia\u2019 noto alle forze di polizia per furto, e\u2019 stato sottoposto a perquisizione dell\u2019autovettura al termine della quale e\u2019 stato deferito in stato di liberta\u2019 per possesso ingiustificato di grimaldelli essendogli stati trovati tre piedi di porco nel bagagliaio dei quali il 21enne di Leverano non ha saputo dare spiegazioni. Quattro i soggetti deferiti in stato di liberta\u2019 per essersi rifiutati di sottoporsi al controllo sulle sostanze stupefacenti. I quattro, fermati e visibilmente in stato di alterazione derivante da assunzione di sostanze stupefacenti, sono stati invitati a sottoporsi al controllo, ma gli stessi si sono rifiutati. Sessanta i segnalati alla prefettura per uso non terapeutico di sostanze stupefacenti. Si tratta perlopiu\u2019 di\u00a0 ragazzi giovani trovati in possesso di sostanze stupefacenti, soprattutto marijuana e cocaina. Uno di questi, un tarantino diciannovenne, e\u2019 stato addirittura fermato trovato nell\u2019atto di assumere una dose di cocaina \u201cposata\u201d sullo schermo del proprio smartphone. Controlli e servizi analoghi continueranno in modo serrato per tutto il prossimo periodo in occasione dei \u201cponti\u201d del 25 aprile e 1\u00b0 maggio, al fine di contribuire a garantire a turisti e salentini vacanze pi\u00f9 sicure.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/22\/ritirate-dai-carabinieri-di-gallipoli-18-patenti-per-guida-in-stato-di-ebbrezza-alcolica\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/22\/ritirate-dai-carabinieri-di-gallipoli-18-patenti-per-guida-in-stato-di-ebbrezza-alcolica\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Nel finesettimana lungo di Pasqua e pasquetta i carabinieri della compagnia di Gallipoli, sono stati impegnati su tutto il territorio di loro competenza, con un capillare servizio a largo raggio. In sintesi, sono stati eseguiti controlli, principalmente finalizzati a contrastare il perpetrarsi di reati in genere, nonche\u2019 il fenomeno della guida in stato di ebbrezza, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":21285,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/27935"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=27935"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/27935\/revisions"}],"predecessor-version":[{"id":27936,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/27935\/revisions\/27936"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/21285"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=27935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=27935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=27935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}