{"id":27985,"date":"2014-04-22T22:14:26","date_gmt":"2014-04-22T20:14:26","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=27985"},"modified":"2014-04-22T22:24:03","modified_gmt":"2014-04-22T20:24:03","slug":"mobilitazione-popolare-in-difesa-dellambiente-vi-raccontiamo-che-cosa-hanno-fatto-e-che-cosa-hanno-detto","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/22\/mobilitazione-popolare-in-difesa-dellambiente-vi-raccontiamo-che-cosa-hanno-fatto-e-che-cosa-hanno-detto\/","title":{"rendered":"MOBILITAZIONE POPOLARE IN DIFESA DELL&#8217;AMBIENTE\/ VI RACCONTIAMO CHE COSA HANNO FATTO E CHE COSA HANNO DETTO"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/amb.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/amb-300x225.jpg\" alt=\"\" title=\"amb\" width=\"300\" height=\"225\" class=\"alignleft size-medium wp-image-27987\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/amb-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/amb.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/sit.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/sit-300x225.jpg\" alt=\"\" title=\"sit\" width=\"300\" height=\"225\" class=\"alignleft size-medium wp-image-27988\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/sit-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/sit.jpg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/10151802_501696039958838_6050552242977422218_n1.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/10151802_501696039958838_6050552242977422218_n1-225x300.jpg\" alt=\"\" title=\"10151802_501696039958838_6050552242977422218_n\" width=\"225\" height=\"300\" class=\"alignleft size-medium wp-image-27986\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/10151802_501696039958838_6050552242977422218_n1-225x300.jpg 225w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/10151802_501696039958838_6050552242977422218_n1.jpg 480w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a>C&#8217;\u00e9 chi dice no<\/p>\n<p>di Tonio Leuci<\/p>\n<p>L\u2019orrendo e vergognoso eccidio di oltre cento ulivi nelle campagne del Salento ha suscitato una vera e propria ondata di indignazione popolare, che si \u00e8 tradotta, oltre che in una petizione sul web, anche in due manifestazioni importanti: la prima venerd\u00ec 18 aprile, la seconda domenica di Pasqua.<\/p>\n<p>&nbsp;<\/p>\n<p>Venerd\u00ec, il maltempo non ha fermato un sit-in sotto la Prefettura a Lecce contro il\u00a0 decreto della Regione Puglia che, sotto la direttiva dell\u2019Unione Europea, ha imposto l\u2019espianto come unica soluzione per combattere un batterio (Xilella Fastidiosa), che porta all\u2019essiccamento degli alberi.<\/p>\n<p>&nbsp;<\/p>\n<p>Il sit- in \u00e8 stato organizzato dalle associazioni ambientaliste salentine: Forum Ambiente e Salute del Grande Salento; Associazione Spazi Popolari; Coordinamento civico apartitico per la tutela del territorio e della salute del cittadino.<\/p>\n<p>Il secondo evento ha visto anche l\u2019adesione di: Arci provinciale Lecce, Associazione DnaDonna, Egerthe!, Gruppo indipendente Intervalla insaniae, Forum Amici del territorio, Sos Coste, Associazione Core De Villani, Movimento Agende Rosse Salento, associazione Sveglia cittadina, Comitato Civico La Scisciula, Soniboni officine culturali, Nuova Messapia, Cosa pubblica Puglia &#8211; Collettivo Arte ambiente Nuovi Selvaggi, Associazione di volontariato Mujmun\u00e8, Associazione \u201cIl nodo fatato\u201d, Associazione \u201cLa valigia parlante\u201dSolet, Liberamente e Apertamente, Comitato intercomunale \u201cNo alla centrale a biomasse a Lequile\u201d, associazione &#8220;Custodi del Salento&#8221;,&#8221;Meticcia&#8221; Aps, Collettivo Tesla, Cooperativa &#8220;Laboratorio Zarchar&#8221; Manfredonia, Laboratorio Omar Moheissi, FucinaAsud, Collettivo C.La.s.s. &#8211; Associazione Nuvole Taurisano.<\/p>\n<p>&nbsp;<\/p>\n<p>Durante il sit in gli ambientalisti hanno gridato le ragioni della protesta:<\/p>\n<p>&nbsp;<\/p>\n<p><em>\u201cEra il 28 di Ottobre 2013 quando, Antonio Guario dirigente capo dell&#8217;osservatorio fitosanitario regionale e Dario Boscia CNR Bari, in assenza di letteratura e senza alcuna base scientifica, attribuivano gli essiccamenti al batterio &#8220;xylella fastidiosa&#8221;. Avevano prospettato uno scenario apocalittico, distruzione di 180 specie di piante, eradicazione di circa 8.000\u00a0 ettari di oliveti, diserbanti e insetticidi\u00a0a tutto spiano, anche per via aerea,\u00a0per uccidere gli insetti vettori (ancora non individuati).\u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Con questo sit-in vogliamo coordinare la mobilitazione civica levatasi al fine di fermare l\u2019eccidio del nostro patrimonio olivicolo. La grave minaccia della sua cancellazione \u00e8 costituita oggi dall\u2019irresponsabile azione regionale nel nome del patogeno da quarantena Xylella Fastidiosa.<\/p>\n<p>&nbsp;<\/p>\n<p>La Regione Puglia ha inaugurato, all\u2019indomani della domenica delle Palme, la mattanza dei primi 104 esemplari di olivi secolari,<em>\u00a0la maggior parte dei quali senza alcun sintomo del malanno.\u00a0<\/em><\/p>\n<p>Non pochi i dubbi che avvolgono l\u2019intera vicenda, sia sotto la procedura utilizzata per comunicare l\u2019 attuazione delle direttive fitosanitarie, sia sotto il profilo della profilassi stessa. Anomalie che si aggiungono alle tantissime accumulatesi nel corso dei mesi intorno alla questione del disseccamento.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019incontro \u00e8 volto a dare voce al territorio rimasto totalmente inascoltato ed a sottolineare<strong><em>\u00a0<\/em><\/strong><em>l\u2019 importanza e l\u2019urgenza di un\u2019indagine sulla vicenda da parte della magistratura e degli organi inquirenti.\u00a0<\/em><\/p>\n<p>Si chiede di fermare gli abbattimenti nonch\u00e9 gli interventi che dovessero prevedere irrorazione di prodotti chimici o di sintesi sempre e comunque nocivi per l\u2019ecosistema e per la salute dei cittadini.<\/p>\n<p>Si auspica che l\u2019eco di questa crescente mobilitazione <em>giunga ai commissari europei<\/em> i quali possano indicare allo Stato membro una via di cura agroecologica dell\u2019intero patrimonio olivicolo del Salento, poich\u00e9 le esperienze pregresse hanno largamente dimostrato che eradicare le piante non serve a debellare il batterio ed inoltre, essendo carenti gli studi in materia, tutti gli istituti di ricerca dovrebbero far luce sulla vicenda. Gli ulivi del Salento sono alberi millenari, patrimonio dell\u2019umanit\u00e0, non permetteremo che vengano sterminati!\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>***<\/p>\n<p>La manifestazione di domenica, nonostante la\u00a0 Pasqua, \u00e8 stata un GRANDE successo, con la partecipazione di una folla di semplici cittadini,\u00a0 ambientalisti e\u00a0 attivisti del Meet up \u201cSalentini Uniti con Beppe Grillo\u201d, i quali si sono dati appuntamento in piazza Sant\u2019Oronzo a Lecce per manifestare e raccogliere le firme per due petizioni: una contro l&#8217;uso degli organismi geneticamente modificati e l\u2019altra in difesa degli ulivi.<\/p>\n<p>E&#8217; stata alta affluenza dei cittadini, coinvolti in questa protesta, in fila per firmare: circa trecento, in due ore.<\/p>\n<p>&nbsp;<\/p>\n<p>In entrambe le manifestazioni, non solo gli ambientalisti e gli attivisti del M5S, ma anche intere famiglie, proprietari agricoli e semplici cittadini, i quali si sono detti esterrefatti, arrabbiati e nauseati da una classe politica che guarda oramai solo alle grandi speculazioni delle multinazionali e agli interessi particolari degli amministratori locali.<\/p>\n<p>&nbsp;<\/p>\n<p>Ognuno con i loro manifesti e striscioni: \u201c<em>NO ALLA STRAGE DEGLI ULIVI!\u201d,<\/em> \u201c<em>MORTE DEL SALENTO = MORTE DEGLI ULIVI\u201d,\u00a0 \u201cNON SI TOCCHI UN SOLO ALBERO!\u201d, \u201cNO SPECULAZIONI!\u201d,\u00a0 \u201cDOVE SI DEVASTA IL PAESAGGIO LI\u2019 C\u2019E\u2019 LA MAFIA!\u201d,\u00a0 \u201cFUORI I CRIMINALI DAL SALENTO!\u201d<\/em> e tanti altri.<\/p>\n<p>&nbsp;<\/p>\n<p>***<\/p>\n<p>Domenica di Pasqua \u00e8\u00a0 intervenuto alla manifestazione anche il cittadino portavoce e capogruppo del M5S al Senato, Maurizio Buccarella il quale, parlando alla cittadinanza, ha espresso i suoi dubbi e sospetti riguardo a questa vicenda, che pu\u00f2 suscitare gli enormi interessi delle multinazionali del settore o di chi ha interesse nelle centrali a biomasse, al fine di reperire una quantit\u00e0 illimitata di legname a basso costo.<\/p>\n<p>A noi di leccecronaca.it ha poi dettagliato quanto ha potuto verificare dal suo osservatorio privilegiato. Sono fatti importanti, quelli che Buccarella ha ricostruito\u00a0 per i nostri lettori, rimasti finora inediti. Li sottoponiamo cos\u00ec all&#8217;attenzione generale. Ecco quanto ci ha dichiarato:<\/p>\n<p>&nbsp;<\/p>\n<p>\u201d<em>Ci sono dei punti che a noi del M5S ci sembrano molto oscuri. Questa storia non convince! Noi, il sospetto lo abbiamo avuto gi\u00e0 nell\u2019estate del 2013, quando \u00e8 esploso il caso e c\u2019erano molti aspetti che rimanevano oscuri. Come strani accadimenti con strani convegni fatti a Bari, sponsorizzati dall\u2019universit\u00e0 americana di Berkeley e altri punti oscuri.\u00a0<\/em><\/p>\n<p><em>\u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/em><\/p>\n<p><em>Il problema Xilella non \u00e8 stato all\u2019ordine del giorno nel dibattito parlamentare, ma subito una cosa \u00e8 balzata agli occhi. Io qui sul telefonino ho ancora le foto di vari emendamenti che nel dicembre 2013, in sede di dibattito e di voto sulla legge di stabilit\u00e0, una legge che spostava diversi miliardi(c\u2019era ancora Letta, doveva arrivare il nuovo \u201ccomunicatore del governo\u201d) e noi notammo in Commissione Bilancio che arrivavano emendamenti fotocopia.\u00a0<\/em><\/p>\n<p><em>Emendamenti tutti uguali a firma di politici di di forze politiche differenti, di dare la loro disponibilit\u00e0 attraverso vari emendamenti al fine di stanziare svariati milioni di euro(5-15 milioni) per finanziare operazioni di quarantena per combattere l\u2019emergenza Xilella Fastidiosa.\u00a0<\/em><\/p>\n<p><em>Emendamenti fotocopia presentati da vari senatori che suscitavano un campanello d\u2019allarme a causa della presenza &#8211; che noi denunciammo durante l\u2019approvazione della legge di stabilit\u00e0 &#8211; di lobbisti, e quindi dell\u2019intervento delle lobby.\u00a0<\/em><\/p>\n<p><em>Persone sconosciute che all\u2019improvviso compaiono fuori le porte delle commissioni bilancio di Camera e Senato, le quali possono anche difendere gli interessi pi\u00f9 nobili oppure interessi oscuri e loschi. Se questi emendamenti fotocopia sono presentati in modo uguale dai parlamentari sia dei partiti della maggioranza, che da quelli dell\u2019opposizione allora o si tratta di un qualcosa di nobile e sacrosanto o di un qualcosa, che riceve l\u2019imput dall\u2019esterno e quindi poco chiaro. Ed \u00e8 appunto quello che noi del M5S cerchiamo di fare ogni volta e cio\u00e8 di vederci chiaro e far vedere cosa succede nelle stanze del Palazzo. Ora, di fronte a questi imput esterni, sta a noi, sta a voi, sta alle associazioni, sta ai cittadini vederci chiaro e vedere alla fine che disegno esce. Se effettivamente c\u2019\u00e8 un \u2018emergenza e per questo bisogna intervenire in maniera cos\u00ec brutale &#8211; come quella che \u00e8 avvenuta con l\u2019eradicazione degli ulivi &#8211; o se dietro c\u2019\u00e8 un qualcos\u2019altro. Il risultato finale \u00e8 la produzione di legname a basso costo, che ben sappiamo quanta gola pu\u00f2 fare a chi ha interesse nelle centrali a biomasse, con una quantit\u00e0 ingente di legname a buon mercato. O &#8211; per la soluzione del problema &#8211; proposte di tipo ogm da istituti americani o trattamenti chimici o fitosanitari da svariate multinazionali del settore, che gi\u00e0 hanno inondato di questi prodotti la nostra terra.\u00a0<\/em><\/p>\n<p><em>Noi del M5S staremo l\u00ec con gli occhi aperti e faremo su questo una battaglia. Io intanto come cittadino portavoce in Parlamento quello che posso fare \u00e8 una interrogazione per chiedere al Ministero o ai ministeri competenti di vederci chiaro.\u00a0<\/em><\/p>\n<p><em>Intanto a livello locale vorrei capire: che fine ha fatto questa legna? Che trattamento ha avuto? Se \u00e8 veramente contaminata che precauzioni sono state prese?\u00a0<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em>*** \u00a0<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Le associazioni ambientaliste, dal canto loro, hanno urlato la loro disapprovazione, la loro ferma protesta e tutto il loro sdegno:<\/p>\n<p><em>\u201cUn\u2019azione irresponsabile, vergognosa, un\u2019esecuzione plateale senza alcun rispetto della pur minima norma di profilassi fitosanitaria, la barbarie compiuta all\u2019indomani della Domenica delle Palme contro oltre 100 vetusti alberi d\u2019olivo, fatti letteralmente a brandelli,\u00a0 da enti pubblici che hanno smarrito ogni ragione, ogni pudore! Un atto blasfemo e palesemente strumentale e terroristico, spettacolarizzato alla merc\u00e9 dei media espressamente invitati a riprendere l\u2019atto dell\u2019esecuzione sommaria, mentre le motoseghe facevano segatura volatilizzata dal vento del legno detto \u201ccontaminato\u201d e \u201ccontaminante\u201d (??), di alberi sanissimi, argentei e carichi di promettenti fiori, e la legna (detta \u201ccontaminata\u201d) veniva caricata sui camion per esser portata ovunque senza protezione, come li stessi media hanno documentato!<\/em><\/p>\n<p><em>I cittadini coesi in difesa dell\u2019agroforesta degli ulivi del Salento, terra consacrata ad Atena nell\u2019antichit\u00e0, e da qui a Maria nel Cristianesimo, in un perfetto sincretismo religioso legato al sacro Ulivo, si danno convegno, per informare, coordinarsi, raccogliere le firme che arriveranno nelle mani dei soggetti preposti.<\/em><\/p>\n<p><em>E\u2019 una mobilitazione civica levatasi al fine di fermare l\u2019eccidio del nostro patrimonio olivicolo. E\u2019 l\u2019incontro di varie realt\u00e0, agricoltori, imprenditori olivicoli, vivaisti, madri e padri, giovani, uomini e donne che amano il territorio nelle sue caratteristiche peculiari ed hanno a cuore la sua preservazione. La grave minaccia della sua cancellazione \u00e8 costituita oggi dall\u2019irresponsabile azione regionale nel nome del mistificato e strumentalizzato patogeno da quarantena \u201cXylella\u201d.<\/em><\/p>\n<p><em>Mai nel mondo, e nella storia dell\u2019umanit\u00e0, neppure per epidemie vere e concrete che colpivano l\u2019uomo, nessun pazzo ha mai proposto la cancellazione di una regione intera, di un\u2019intera foresta, ed oggi invece per un piccolo fito-patogeno sconosciuto all\u2019ulivo fino ad ora nel mondo, patogeno di un albero forte e che sta gi\u00e0 provvedendo a guarire e reagire secondo natura come da sempre ha fatto nei millenni della sua imperitura storia contro tantissimi patogeni con cui ha imparato a convivere, oggi degli agro-nemici della natura propongono, dopo una incerta diagnosi (non confrontata liberamente con tutti gli altri ricercatori della comunit\u00e0 scientifica mondiale \u2013 come la vera Scienza comanda), la terapia folle dell\u2019olocausto finale! Un danno, uno sterminio che mai il patogeno potrebbe compiere negli anni, lo compiono loro con mega incentivi richiesti all\u2019UE (Unione Europea), e chiamano tutto questo \u201ccura\u201d! E con l\u2019ulivo vorrebbero fare scomparire anche la biodiversit\u00e0 salentina selvatica e domestica (ben oltre 150 specie di piante dette \u201ccontaminate\u201d) e la preziosissima entomofauna, la Vita intera insomma, fare il deserto artificiale del Salento, eradicando e avvelenando con prodotti chimici industriali! E questo deformando le norme comunitarie che mai hanno parlato di obbligo all\u2019eradicazione degli ulivi colpiti, ma semmai all\u2019\u201ceradicazione\u201d o addirittura anche solo \u201ccontenimento\u201d del patogeno. Patogeno, poi, s\u00ec ad oggi da quarantena, ma di cui non si vuole verificare neppure se sia giusto lasciarlo in questa graduatoria, dato che non si vuole studiare il decorso dei sintomi su quegli ulivi che han mostrato disseccamenti, e invece si vuole procedere in maniera oltranzista e integralista a ucciderli meccanicamente eradicandoli del tutto \u2026 prima che possano, tanti di essi, guarire naturalmente!<\/em><\/p>\n<p><em>Inoltre entro la fine del mese di aprile \u00a0si vorrebbe decidere dell\u2019assetto del nostro territorio, attraverso la messa \u201cin atto di misure di eradicazione, contenimento e l\u2019istituzione di una zona tampone\u201d per quanto riguarda la vasta area del Gallipolino, come si apprende dal documento recentemente giunto da Bruxelles.<\/em><\/p>\n<p><em>L\u2019incontro di oggi \u00e8 volto a dare voce al territorio rimasto totalmente inascoltato ed a sottolineare l\u2019importanza e l\u2019urgenza di un\u2019indagine sulla vicenda da parte della magistratura e degli organi inquirenti.<\/em><\/p>\n<p><em>Si chiede di fermare in maniera coatta gli abbattimenti, nonch\u00e9 gli interventi che dovessero prevedere irrorazione di prodotti chimici o di sintesi sempre e comunque nocivi per l\u2019ecosistema e per la salute dei cittadini.<\/em><\/p>\n<p><em>L\u2019incontro \u00e8 volto anche alla massima partecipazione dei contadini e dei proprietari olivicoli, che \u00e8 necessario informare massimamente affinch\u00e9 possano reagire, adendo le vie legali qualora nelle prossime ore e giorni, senza preavviso e\/o forzosamente, degli ufficiali preposti dovessero eseguire altre mattanze programmate sui loro terreni.<\/em><\/p>\n<p><em>Oggi \u00e8 un giorno festivo per tutti. Ma entro undici giorni potrebbero cambiare totalmente il nostro DNA culturale, storico, paesaggistico e persino agro-genetico! Dietro ad ogni olivo c\u2019\u00e8 il nostro albero genealogico, un prezioso albero che protegge questa terra dalla desertificazione, dal dissesto idrogeologico e pone vincoli ostativi alle numerose devastanti speculazioni che minacciano come spade di Damocle sospese il nostro patrimonio paesaggistico, tutelato dall\u2019articolo 9 nei principi basilari della nostra Costituzione.<\/em><\/p>\n<p><em>Il Salento reagisce e lo fa proprio nella settimana di Pasqua, quando forse qualcuno\u00a0 sperava che la reazione dei cittadini potesse essere pi\u00f9 blanda e distratta per le concomitanti vacanze! Una sottovalutazione ulteriore dell\u2019Intelligenza e dell\u2019Amore dei cittadini del Salento per la loro terra che aggiunge indignazione ad indignazione!\u201d.<\/em><\/p>\n<p><em>***\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/em><\/p>\n<p>Infine,\u00a0 a Pasquetta (giustamente, l&#8217;emergenza ambientale nel Salento non concedeva ferie) il neo \u2013 costituito comitato \u201cNo villaggi nell&#8217;oasi delle Cesine\u201d\u00a0 ha promosso un sopralluogo in zona.<\/p>\n<p>E&#8217; stato denunciato con dovizia di particolari\u00a0 il fatto che, dopo anni, di alterne vicende, proprio in questi giorni \u00a0 sono stati dati permessi e fondi pubblici ad alcune ditte per la costruzione di strutture ricettive nell&#8217;oasi\u00a0 protetta delle\u00a0 Cesine, gestita (male, a proposito,\u00a0 vista la mancata valorizzazione, e gli scarichi a mare tollerati, ma questa \u00e8 un&#8217;altra storia) dal Wwf e area di interesse comunitario, oltre che, come \u00e8 noto, vero e proprio paradiso biologico salentino. I documenti dicono \u201ca ridosso\u201d dell&#8217;area, ma in realt\u00e0 la struttura alberghiera\u00a0 vi \u00e8 ben dentro. Il tutto, con i soliti permessi degli enti locali, cio\u00e8 degli amministratori politici, fra i quali si distinguono quelli della solita\u00a0 Regione Puglia, della Provincia di Lecce, e, con tanto di\u00a0 esultanza a definizione dell&#8217;iter burocratico, quelli del sindaco di Vernole.<\/p>\n<p>L&#8217;ennesima speculazione senza ritegno.<\/p>\n<p>***\u00a0 \u00a0 \u00a0<em> \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/em><\/p>\n<p>E&#8217; facile prevedere che le proteste non finiranno qui.<\/p>\n<p>Noi di <strong>leccecronaca.it<\/strong> dopo avervi raccontato che cosa succede, con i nostri reportage, commenti e approfondimenti, continueremo a seguire l\u2019evolversi della vicenda, che consideriamo prioritaria, addirittura vitale per tutti noi Salentini, nella speranza che si trovino soluzioni diligenti e responsabili per risolvere questioni che, per come sono state finora gestite e come abbiamo ampiamente fin qui documentato, suscitano molte perplessit\u00e0 e moltissimi dubbi.<\/p>\n<p><strong>Tonio Leuci \u00a0 \u00a0 <\/strong><\/p>\n<p><em>\u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/22\/mobilitazione-popolare-in-difesa-dellambiente-vi-raccontiamo-che-cosa-hanno-fatto-e-che-cosa-hanno-detto\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/22\/mobilitazione-popolare-in-difesa-dellambiente-vi-raccontiamo-che-cosa-hanno-fatto-e-che-cosa-hanno-detto\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>&nbsp; C&#8217;\u00e9 chi dice no di Tonio Leuci L\u2019orrendo e vergognoso eccidio di oltre cento ulivi nelle campagne del Salento ha suscitato una vera e propria ondata di indignazione popolare, che si \u00e8 tradotta, oltre che in una petizione sul web, anche in due manifestazioni importanti: la prima venerd\u00ec 18 aprile, la seconda domenica di [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":27987,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[44],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/27985"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=27985"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/27985\/revisions"}],"predecessor-version":[{"id":27998,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/27985\/revisions\/27998"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/27987"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=27985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=27985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=27985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}