{"id":28316,"date":"2014-04-30T15:54:08","date_gmt":"2014-04-30T13:54:08","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=28316"},"modified":"2014-04-30T15:55:25","modified_gmt":"2014-04-30T13:55:25","slug":"melissano-di-notte","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/30\/melissano-di-notte\/","title":{"rendered":"MELISSANO DI NOTTE"},"content":{"rendered":"<div>\n<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/BodyPart6.jpeg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/BodyPart6.jpeg\" alt=\"\" title=\"BodyPart\" width=\"1000\" height=\"563\" class=\"alignleft size-full wp-image-28317\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/BodyPart6.jpeg 1000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/BodyPart6-300x168.jpg 300w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><em>Riceviamo e volentieri pubblichiamo.<\/em><\/p>\n<p>Questa \u00e8 Melissano di notte. In alcune zone il buio \u00e8 totale. La foto riprende viale Stazione, una delle principali vie di ingresso del paese. Da tre mesi non viene effettuata la normale manutenzione dell&#8217;impianto di pubblica illuminazione. Nonostante i ripetuti appelli di Fratelli d&#8217;Italia &#8211; Alleanza Nazionale, l&#8217;Amministrazione comunale \u00e8 sorda: zero servizi, ma tasse al massimo!<br \/>\nGoverna il paese una maggioranza politica che va dai compagni di Sel (sponsor Dario Stefano) a Forza Italia (amici di Raffaele Fitto).<\/p>\n<div><\/div>\n<\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/30\/melissano-di-notte\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/30\/melissano-di-notte\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo. Questa \u00e8 Melissano di notte. In alcune zone il buio \u00e8 totale. La foto riprende viale Stazione, una delle principali vie di ingresso del paese. Da tre mesi non viene effettuata la normale manutenzione dell&#8217;impianto di pubblica illuminazione. Nonostante i ripetuti appelli di Fratelli d&#8217;Italia &#8211; Alleanza Nazionale, l&#8217;Amministrazione comunale \u00e8 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":28317,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/28316"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=28316"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/28316\/revisions"}],"predecessor-version":[{"id":28319,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/28316\/revisions\/28319"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/28317"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=28316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=28316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=28316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}