{"id":28370,"date":"2014-04-30T17:03:32","date_gmt":"2014-04-30T15:03:32","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=28370"},"modified":"2014-04-30T17:15:20","modified_gmt":"2014-04-30T15:15:20","slug":"premio-letterario-angelo-lippo","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/30\/premio-letterario-angelo-lippo\/","title":{"rendered":"PREMIO LETTERARIO \u201cANGELO LIPPO\u201d"},"content":{"rendered":"<p style=\"text-align: left;\" align=\"center\"><strong><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/Schermata-2014-04-30-a-17.02.44.png\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/Schermata-2014-04-30-a-17.02.44.png\" alt=\"\" title=\"Schermata 2014-04-30 a 17.02.44\" width=\"584\" height=\"449\" class=\"alignleft size-full wp-image-28371\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/Schermata-2014-04-30-a-17.02.44.png 584w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/Schermata-2014-04-30-a-17.02.44-300x230.png 300w\" sizes=\"(max-width: 584px) 100vw, 584px\" \/><\/a>Concorso nazionale di poesia e narrativa ConTesti DiVersi<br \/>\n<\/strong><strong>SCADENZA 30 SETTEMBRE 2014.<br \/>\n<\/strong>Al via il premio letterario dedicato al poeta tarantino <strong>Angelo Lippo<\/strong>. L\u2019associazione culturale e20Cult, in collaborazione con la casa editrice Il Raggio Verde, organizza la prima edizione del <strong>Concorso Nazionale di Poesia e Narrativa contemporanea ConTesti DiVersi &#8211; Premio Letterario \u201cAngelo Lippo\u201d.<\/strong><\/p>\n<p>Il concorso, patrocinato dal <strong>Comune di Taranto<\/strong>, \u00e8 aperto a tutti gli autori italiani e stranieri. Il Premio si articola in due sezioni &#8220;poesia inedita&#8221; e &#8220;racconto inedito&#8221; pi\u00f9 una speciale &#8220;<strong>A scuola conTesti DiVersi<\/strong>&#8221; riservata agli studenti delle ultime classi degli Istituti superiori. L\u2019iscrizione potr\u00e0 avvenire sia tramite e-mail che a mezzo posta. Il termine per le iscrizioni \u00e8 fissato al 30 settembre 2014, a seconda delle modalit\u00e0 adottate far\u00e0 fede il timbro postale o la data di invio telematico. L\u2019indirizzo \u00e8: <strong>\u201cConTestiDiVersi &#8211; Premio Letterario Angelo Lippo\u201d, Casella postale N. 124 &#8211; Lecce Centro &#8211; 73100 Lecce.<\/strong>\u00a0La partecipazione al Premio implica la piena ed incondizionata accettazione del regolamento completo scaricabile nell&#8217;area download del sito: <a href=\"http:\/\/www.premioletterarioangelolippo.it\">www.premioletterarioangelolippo.it<\/a>.<\/p>\n<p>Per ciascuna sezione, la quota di partecipazione \u00e8 di euro 20,00 da inviare tramite vaglia postale intestato all\u2019associazione culturale \u201c<strong>e20Cult \u201cCasella Postale N. 124 &#8211; Lecce Centro &#8211; 73100 Lecce<\/strong>. All\u2019opera vincitrice, per entrambe le sezioni, sar\u00e0 attribuito un premio di 500\u20ac. Inoltre sono previste targhe di riconoscimento e pergamena per i primi tre classificati. La Giuria si riserva inoltre la possibilit\u00e0 di segnalazioni speciali e possibilit\u00e0 di pubblicazione per i lavori in genere ritenuti meritevoli. Il Raggio Verde edizioni si riserva di pubblicare nella collana di narrativa e poesia contemporanea \u201cConTesti Diversi\u201d le opere dei primi dieci autori selezionati per entrambe le sezioni.<\/p>\n<p>La cerimonia di premiazione si terr\u00e0 a <strong>Taranto l\u201911 novembre 2014<\/strong>, nell\u2019anniversario della nascita del poeta. Luogo e orario saranno tempestivamente comunicati dall\u2019organizzazione a tutti i partecipanti via mail e\/o telefonicamente e tramite la consultazione del sito ufficiale del concorso: <strong>premioletterarioangelolippo.it.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Angelo Lippo<\/strong> era nato come amava ripetere, \u201csulle rive dello Ionio\u201d nel giorno di San Martino, classe 1939. Definito da Raffaele Nigro \u201cil maggior poeta dell\u2019ultimo Novecento tarantino\u201d, alternava alla scrittura poetica una densa attivit\u00e0 di saggista, critico d\u2019arte, curatore di eventi d\u2019arte.<\/p>\n<p>Del suo poliedrico campo d\u2019azione ne sono testimonianza i numerosi volumi di poesia, i saggi nonch\u00e9 articoli e fogli sparsi sulle numerosissime riviste e quotidiani territoriali con cui collaborava , tra gli altri, <em>il Corriere del Giorno, Puglia, La Gazzetta del Mezzogiorno, Nuovo<\/em> <em>Quotidiano di Puglia, L\u2019informatore librario, Pietraserena, La Vallisa,<\/em> <em>Quinta generazione<\/em>. Sul fronte delle arti visive ha firmato alcune monografie di artisti italiani contemporanei, scritti in catalogo o recensioni a rassegne d\u2019arte; ha curato alcune importanti rassegne di arte contemporanea: da <em>Proposta \u201970<\/em>, <em>Obiettivo mare<\/em>, fino a <em>Identit\u00e0<\/em> <em>del Contemporaneo <\/em>e <em>Arte in Salento<\/em>.<\/p>\n<p>Sue poesie sono apparse nel tempo su moltissime riviste di letteratura italiana e straniera, tra le pubblicazioni: <em>Quaderno d\u2019amore <\/em>(1963), <em>Tra questo e l\u2019altro <\/em>(1976), <em>La carne stretta <\/em>(1979,prefazione di Marcello Venturoli), <em>Filo Diretto <\/em>(1982), L\u2019ape invisibile (1985, prefazione di Giacinto Spagnoletti), <em>Caprice des Dieux <\/em>(1992), <em>Alfabeto del mare<\/em> (1992), <em>La trama oscura <\/em>(1992), <em>Il castagno di Martino <\/em>(1996), <em>La<\/em> <em>vita si scandisce limpida <\/em>(1996, prefazione di Enzo Santese), <em>Origini<\/em> (1997), <em>La morte felice <\/em>(1999), <em>Le sillabe del vento <\/em>(2001, prefazione di Dante Maffia), <em>Calice <\/em>(2002), <em>Fragile artificio <\/em>(2006), <em>Elogio dell\u2019ebbrezza<\/em> (2009, prefazione di Luigi Scorrano). <em>Se non matura la spig<\/em>a (2011, prefazione di Dante Maffia) edizioni Il Raggio Verde \u00e8 l\u2019ultima sua raccolta.<\/p>\n<p>(approfondimenti: premioletterarioangelolippo.it)<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019associazione culturale e20Cult in<\/p>\n<p>collaborazione con la casa editrice<\/p>\n<p>Il Raggio Verde organizza la prima<\/p>\n<p>edizione del Concorso Nazionale di<\/p>\n<p>Poesia e Narrativa contemporanea<\/p>\n<p>ConTesti DiVersi &#8211; Premio Letterario<\/p>\n<p>\u201cAngelo Lippo\u201d.<\/p>\n<p>Il concorso, patrocinato dal Comune<\/p>\n<p>di Taranto, \u00e8 aperto a tutti gli autori italiani e stranieri. Il Premio si<\/p>\n<p>articola in due sezioni<\/p>\n<p>a) \u201c<strong>Poesia<\/strong>\u201d : la partecipazione \u00e8 aperta a tutti gli autori con testi in<\/p>\n<p>lingua italiana a tema libero. I testi dovranno essere inediti e non<\/p>\n<p>premiati in altri concorsi letterari, pena l\u2019esclusione dal Premio. Ogni<\/p>\n<p>Autore dovr\u00e0 inviare 3 poesie non superiori ai 30 versi, in lingua italiana,<\/p>\n<p>in 6 copie dattiloscritte con il titolo della raccolta di sui solo una<\/p>\n<p>copia &#8211; per ciascuno dei testi dovr\u00e0 recare \u2013 la propria firma, ovvero<\/p>\n<p>nome, cognome, indirizzo, e-mail e numero di telefono.<\/p>\n<p>b) <strong>\u201cRacconto\u201d<\/strong>: Ogni concorrente dovr\u00e0 inviare un racconto inedito<\/p>\n<p>in lingua italiana di 3-5 cartelle (1 cartella = 30 righe di 60 battute)<\/p>\n<p>in 6 copie dattiloscritte con il titolo. Il medesimo titolo sar\u00e0 scritto su<\/p>\n<p>una busta chiusa recante all\u2019interno nome, cognome, data di nascita,<\/p>\n<p>indirizzo, numero telefonico e firma.<\/p>\n<p><strong>art. 1<\/strong>. I partecipanti dovranno inviare alla Segreteria del Premio la<\/p>\n<p>scheda d\u2019adesione e il regolamento, entrambi sottoscritti e compilati<\/p>\n<p>con i dati richiesti.<\/p>\n<p><strong>art. 2<\/strong>. L\u2019iscrizione potr\u00e0 avvenire sia tramite e-mail che a mezzo<\/p>\n<p>posta. Il termine per le iscrizioni \u00e8 fissato al 30 settembre 2014, a<\/p>\n<p>seconda delle modalit\u00e0 adottate far\u00e0 fede il timbro postale o la data<\/p>\n<p>di invio telematico.<\/p>\n<p><strong>art.3 Per l\u2019invio telematico <\/strong>bisogner\u00e0 trasmettere via e-mail, ovvero<\/p>\n<p>all\u2019indirizzo info@premioletterarioangelolippo.it, in tre file, i seguenti<\/p>\n<p>documenti (formati accettati doc, docx ): 1. &#8211; poesie, 2. &#8211; scheda di<\/p>\n<p>adesione compilata, 3. &#8211; copia dell\u2019effettuato pagamento. In caso di<\/p>\n<p>impossibilit\u00e0 a trasmettere via e-mail la scansione del versamento effettuato,<\/p>\n<p>bisogner\u00e0 spedire la ricevuta di pagamento a mezzo posta,<\/p>\n<p>assieme alla \u201cRicevuta di iscrizione telematica\u201d che la Segreteria del<\/p>\n<p>Premio avr\u00e0 provveduto ad inviare via e-mail all\u2019atto della spedizione<\/p>\n<p>telematica. Per l\u2019iscrizione via e-mail far\u00e0 fede la data dell\u2019invio telematico.<\/p>\n<p><strong>Per l\u2019invio postale <\/strong>\u2013\u00e8 consentita anche la modalit\u00e0 di iscrizione<\/p>\n<p>con spedizione di tutti i documenti richiesti (testi, bando, scheda<\/p>\n<p>di adesione, copia pagamento). L\u2019indirizzo postale \u00e8: \u201cConTestiDiVersi<\/p>\n<p>&#8211; Premio Letterario Angelo Lippo\u201d, Casella postale N. 124 &#8211; Lecce<\/p>\n<p>Centro &#8211; 73100 Lecce.<\/p>\n<p><strong>art. 4. <\/strong>Per ciascuna sezione, la quota di partecipazione \u00e8 di euro<\/p>\n<p>20,00 da inviare tramite vaglia postale intestato all\u2019associazione<\/p>\n<p>culturale \u201ce20Cult \u201cCasella Postale N. 124 &#8211; Lecce Centro &#8211; 73100<\/p>\n<p>Lecce. Le quote di partecipazione versate a beneficio dell\u2019Associazione<\/p>\n<p>culturale e20Cult saranno adoperate per la realizzazione<\/p>\n<p>di eventi finalizzati alla promozione della cultura nonch\u00e9 la promozione<\/p>\n<p>delle opere e della figura del Poeta Angelo Lippo. A tutti sar\u00e0<\/p>\n<p>rilasciato l\u2019attestato di partecipazione da ritirarsi personalmente o<\/p>\n<p>tramite delega esclusivamente il giorno della premiazione .<\/p>\n<p><strong>art. 5. \u201cA Scuola ConTesti diVersi\u201d <\/strong>\u00e8 la sezione dedicata agli<\/p>\n<p>studenti delle scuole medie superiori con iscrizione gratuita. Ogni<\/p>\n<p>istituto potr\u00e0 presentare fino a 20 studenti tra i pi\u00f9 meritevoli. Ogni<\/p>\n<p>studente dovr\u00e0 inviare una sola poesia (max 30 versi) in 6 copie,<\/p>\n<p>recante su ciascuna i propri dati, l\u2019istituto d\u2019appartenenza, e la<\/p>\n<p>data di nascita. Saranno premiati i migliori Istituti scolastici e gli<\/p>\n<p>studenti pi\u00f9 meritevole nell\u2019ambito della selezione nazionale.<\/p>\n<p><strong>art. 6<\/strong>. La Comissione giudicatrice selezioner\u00e0 a suo insindacabile<\/p>\n<p>giudizio i primi tre Autori per ciascuna sezione. La composizione<\/p>\n<p>della stessa verr\u00e0 resa nota nella comunicazione finale sui risultati<\/p>\n<p>via e-mail e\/o posta a tutti i partecipanti.<\/p>\n<p><strong>art.7<\/strong>. La partecipazione al Premio implica la piena ed incondizionata<\/p>\n<p>accettazione del regolamento e la divulgazione del proprio<\/p>\n<p>nome, cognome e premio vinto su qualsiasi pubblicazione. Per<\/p>\n<p>l\u2019iscrizione non si accettano pseudonimi, nomi diversi dalla reale<\/p>\n<p>identit\u00e0 dell\u2019autore, previa invalidazione dell\u2019iscrizione senza restituzione<\/p>\n<p>dei lavori inviati e della quota versata. L\u2019organizzazione<\/p>\n<p>attraverso la presente adesione acquisisce implicitamente il diritto<\/p>\n<p>di pubblicare liberamente e gratuitamente tutti i testi ritenuti idonei.,<\/p>\n<p>compresi quelli della sezione \u201c<strong>A scuola ConTesti diVersi.\u201d<\/strong><\/p>\n<p><strong>art.8<\/strong>. All\u2019opera vincitrice, per entrambe le sezioni, sar\u00e0 attribuito<\/p>\n<p>un premio di 500\u20ac. Inoltre sono previste targhe di riconoscimento<\/p>\n<p>e pergamena per i primi tre classificati. La Giuria si riserva inoltre<\/p>\n<p>la possibilit\u00e0 di segnalazioni speciali e possibilit\u00e0 di pubblicazione<\/p>\n<p>per i lavori in genere ritenuti meritevoli.<\/p>\n<p><strong>art.9<\/strong>. Il Raggio Verde edizioni si riserva di pubblicare nella collana<\/p>\n<p>di narrativa e poesia contemporanea \u201cConTesti Diversi\u201d le opere<\/p>\n<p>dei primi dieci autori selezionati per entrambe le sezioni.<\/p>\n<p><strong>art.10. <\/strong>La cerimonia di premiazione (salvo diverse disposizioni) si<\/p>\n<p>terr\u00e0 a Taranto l\u201911 novembre 2014, nell\u2019anniversario della nascita<\/p>\n<p>del poeta. Luogo e orario saranno tempestivamente comunicati<\/p>\n<p>dall\u2019organizzazione a tutti i partecipanti via mail e\/o telefonicamente<\/p>\n<p>e tramite la consultazione del sito ufficiale del concorso:<\/p>\n<p><strong>premioletterarioangelolippo.it.<\/strong><\/p>\n<p><strong>Angelo Lippo <\/strong>era nato come amava ripetere, \u201csulle rive dello Ionio\u201d<\/p>\n<p>nel giorno di San Martino, classe 1939. Definito da Raffaele Nigro \u201cil<\/p>\n<p>maggior poeta dell\u2019ultimo Novecento tarantino\u201d, alternava alla scrittura<\/p>\n<p>poetica una densa attivit\u00e0 di saggista, critico d\u2019arte, curatore di<\/p>\n<p>eventi d\u2019arte.<\/p>\n<p>Del suo poliedrico campo d\u2019azione ne sono testimonianza i numerosi<\/p>\n<p>volumi di poesia, i saggi nonch\u00e9 articoli e fogli sparsi sulle numerosissime<\/p>\n<p>riviste e quotidiani territoriali con cui collaborava , tra gli altri,<\/p>\n<p><em>il Corriere del Giorno, Puglia, La Gazzetta del Mezzogiorno, Nuovo<\/em><\/p>\n<p><em>Quotidiano di Puglia, L\u2019informatore librario, Pietraserena, La Vallisa,<\/em><\/p>\n<p><em>Quinta generazione<\/em>. Sul fronte delle arti visive ha firmato alcune<\/p>\n<p>monografie di artisti italiani contemporanei, scritti in catalogo o<\/p>\n<p>recensioni a rassegne d\u2019arte; ha curato alcune importanti rassegne di<\/p>\n<p>arte contemporanea: da <em>Proposta \u201970<\/em>, <em>Obiettivo mare<\/em>, fino a <em>Identit\u00e0<\/em><\/p>\n<p><em>del Contemporaneo <\/em>e <em>Arte in Salento<\/em>.<\/p>\n<p>Sue poesie sono apparse nel tempo su moltissime riviste di letteratura<\/p>\n<p>italiana e straniera, tra le pubblicazioni: <em>Quaderno d\u2019amore <\/em>(1963),<\/p>\n<p><em>Tra questo e l\u2019altro <\/em>(1976), <em>La carne stretta <\/em>(1979,prefazione di Marcello<\/p>\n<p>Venturoli), <em>Filo Diretto <\/em>(1982), L\u2019ape invisibile (1985, prefazione<\/p>\n<p>di Giacinto Spagnoletti), <em>Caprice des Dieux <\/em>(1992), <em>Alfabeto del mare<\/em><\/p>\n<p>(1992), <em>La trama oscura <\/em>(1992), <em>Il castagno di Martino <\/em>(1996), <em>La<\/em><\/p>\n<p><em>vita si scandisce limpida <\/em>(1996, prefazione di Enzo Santese), <em>Origini<\/em><\/p>\n<p>(1997), <em>La morte felice <\/em>(1999), <em>Le sillabe del vento <\/em>(2001, prefazione<\/p>\n<p>di Dante Maffia), <em>Calice <\/em>(2002), <em>Fragile artificio <\/em>(2006), <em>Elogio dell\u2019ebbrezza<\/em><\/p>\n<p>(2009, prefazione di Luigi Scorrano). <em>Se non matura la spig<\/em>a<\/p>\n<p>(2011, prefazione di Dante Maffia) edizioni Il Raggio Verde \u00e8 l\u2019ultima<\/p>\n<p>sua raccolta di poesie, Angelo Lippo \u00e8 scomparso nella sua amata<\/p>\n<p>Taranto il 27 agosto 2011.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/30\/premio-letterario-angelo-lippo\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/30\/premio-letterario-angelo-lippo\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Concorso nazionale di poesia e narrativa ConTesti DiVersi SCADENZA 30 SETTEMBRE 2014. Al via il premio letterario dedicato al poeta tarantino Angelo Lippo. L\u2019associazione culturale e20Cult, in collaborazione con la casa editrice Il Raggio Verde, organizza la prima edizione del Concorso Nazionale di Poesia e Narrativa contemporanea ConTesti DiVersi &#8211; Premio Letterario \u201cAngelo Lippo\u201d. Il [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":28371,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/28370"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=28370"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/28370\/revisions"}],"predecessor-version":[{"id":28373,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/28370\/revisions\/28373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/28371"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=28370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=28370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=28370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}