{"id":28434,"date":"2014-05-02T09:35:50","date_gmt":"2014-05-02T07:35:50","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=28434"},"modified":"2014-05-02T09:38:18","modified_gmt":"2014-05-02T07:38:18","slug":"corso-per-operatori-sociali-per-le-adozioni","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/05\/02\/corso-per-operatori-sociali-per-le-adozioni\/","title":{"rendered":"CORSO PER OPERATORI SOCIALI PER LE ADOZIONI"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/BIMBI.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/BIMBI.jpg\" alt=\"\" title=\"BIMBI\" width=\"300\" height=\"209\" class=\"alignleft size-full wp-image-28435\" \/><\/a>SONO APERTE LE ISCRIZIONI AL NUOVO CORSO DELLA PROVINCIA \u00a0DEDICATO AGLI OPERATORI SOCIALI\u00a0SUL TEMA DELLE ADOZIONI NAZIONALI ED INTERNAZIONALI.<br \/>\nE\u2019 possibile iscriversi al Corso \u201cI percorsi per le adozioni nazionali e internazionali: il sistema delle relazioni, i rapporti tra i servizi e le famiglie\u201d, esclusivamente on line (www.provincia.le.it\/formazionesociale).<br \/>\nSi tratta della nuova iniziativa formativa promossa dall\u2019assessorato alle Politiche sociali e Pari opportunit\u00e0 della Provincia di Lecce e rivolta a soggetti pubblici e privati che operano nel welfare locale. Il tema \u00e8 quello attuale e delicato delle adozioni, sia nazionali che internazionali, con riferimento alle strade da percorrere e ai nodi da sciogliere.<br \/>\nL\u2019importante opportunit\u00e0 rientra nel Piano formativo \u201cWelfare e qualit\u00e0 sociale del territorio: un percorso continuo di aggiornamento e confronto\u201d, realizzato dalla Provincia di Lecce e cofinanziato dalla Regione Puglia.<br \/>\nIl percorso formativo partir\u00e0 gioved\u00ec 8 maggio, alle ore 9, nella sala conferenze della sede della Provincia in via Botti, a Lecce e si svilupper\u00e0 in cinque giorni, per una durata complessiva di 25 ore.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/05\/02\/corso-per-operatori-sociali-per-le-adozioni\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/05\/02\/corso-per-operatori-sociali-per-le-adozioni\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>SONO APERTE LE ISCRIZIONI AL NUOVO CORSO DELLA PROVINCIA \u00a0DEDICATO AGLI OPERATORI SOCIALI\u00a0SUL TEMA DELLE ADOZIONI NAZIONALI ED INTERNAZIONALI. E\u2019 possibile iscriversi al Corso \u201cI percorsi per le adozioni nazionali e internazionali: il sistema delle relazioni, i rapporti tra i servizi e le famiglie\u201d, esclusivamente on line (www.provincia.le.it\/formazionesociale). Si tratta della nuova iniziativa formativa promossa [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":28435,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/28434"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=28434"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/28434\/revisions"}],"predecessor-version":[{"id":28437,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/28434\/revisions\/28437"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/28435"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=28434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=28434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=28434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}