{"id":28462,"date":"2014-05-03T13:37:14","date_gmt":"2014-05-03T11:37:14","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=28462"},"modified":"2014-05-03T13:37:53","modified_gmt":"2014-05-03T11:37:53","slug":"vuoi-i-soldi-spara-ai-russi","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/05\/03\/vuoi-i-soldi-spara-ai-russi\/","title":{"rendered":"VUOI I SOLDI? SPARA AI RUSSI\u2026!"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/Filorussi-Ucraina.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/Filorussi-Ucraina.jpg\" alt=\"\" title=\"Filorussi-Ucraina\" width=\"600\" height=\"300\" class=\"alignleft size-full wp-image-28463\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/Filorussi-Ucraina.jpg 600w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/Filorussi-Ucraina-300x150.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a>Guarda, guarda&#8230;..,proprio in diretta RadioTiranauno trasmette da Slovlansk\u00a0(o da l\u00ec vicino, come dichiarato).<br \/>\nSottofondo di spari e commento : arrivano l&#8217;esercito e l&#8217;aviazione di Kiev.<\/p>\n<p>Sparano sui civili (armati), uccidono e feriscono. Conquistano 9 posti di blocco e si dirigono con i carrarmati verso il centro della citt\u00e0, presidiato dalla cittadinanza filorussa.<\/p>\n<p>Perdono (almeno) due elicotteri da combattimento, con relativi equipaggi.<\/p>\n<p>La Rai e Skytg24, medaglie d&#8217;oro al valor UEista, come da copione si astengono regolarmente dal censurare l&#8217;uso dell&#8217;esercito contro la popolazione civile. Eh\u2026, mica siamo in Libia e Siria&#8230;quando i cattivoni dittatori mossero il primo blindato gi\u00e0 caterve di corrispondenti di guerra preparavano il terreno alle auspicabili invasioni della Nato. Piuttosto sembra il bis dell&#8217;Egitto.<\/p>\n<p>Mubarak usava l&#8217;esercito contro la &#8220;primavera araba&#8221; ? Diretta da il Cairo\u2026., cos\u00ec come contro Morsi ed i Fratelli musulmani. Ma nessuna condanna audiovideo per il regime militare egiziano e le migliaia di civili ammazzati dai carrarmati o condannati a morte oggi.<\/p>\n<p>Idem a Kiev &#8220;prima&#8221; della rivolta UEista : tutti in piazza (Euro)Maidan contro la polizia (non l&#8217;esercito) di Janukovich per la &#8220;libert\u00e0&#8221; dell&#8217;Ucraina. Oggi in prima linea a sostenere le ragioni del governo (autoproclamatosi) di Kiev contro gli ucraini di lingua russa. Che di passare sotto la dittatura UEista di Bruxelles non ne vogliono assolutamente sapere, sentendosi defraudati di un governo liberamente eletto ed abbattuti dalla troika di Bruxelles e con la supervisione di Obama.<\/p>\n<p>Comune denominatore ?<\/p>\n<p>I soldi : euro, dollari o marenghi d&#8217;oro, nessuna differenza.<\/p>\n<p>Come nel passato, in tutto il mondo, si sono rovesciati governi pi\u00f9 o meno legittimi con la scusa degli interventi &#8220;umanitari&#8221;. Poi si sono creati stati fantoccio al servizio degli interessi economici della finanza mondiale, degli Usa e dell&#8217;UEismo suo servo.<\/p>\n<p>Infine, con il ricatto degli &#8220;aiuti economici&#8221; si sono spinti gli stati &#8220;amici&#8221; a reprimere nel sangue qualunque resistenza ed opposizione al nuovo equilibrio.<\/p>\n<p>Oggi, in Ucraina, ci\u00f2 vuol dire solo una cosa : volete i soldi ? Sparate ai russi !<\/p>\n<p>Vincenzo Mannello<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/05\/03\/vuoi-i-soldi-spara-ai-russi\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/05\/03\/vuoi-i-soldi-spara-ai-russi\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Guarda, guarda&#8230;..,proprio in diretta RadioTiranauno trasmette da Slovlansk\u00a0(o da l\u00ec vicino, come dichiarato). Sottofondo di spari e commento : arrivano l&#8217;esercito e l&#8217;aviazione di Kiev. Sparano sui civili (armati), uccidono e feriscono. Conquistano 9 posti di blocco e si dirigono con i carrarmati verso il centro della citt\u00e0, presidiato dalla cittadinanza filorussa. Perdono (almeno) due [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":28463,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/28462"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=28462"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/28462\/revisions"}],"predecessor-version":[{"id":28465,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/28462\/revisions\/28465"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/28463"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=28462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=28462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=28462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}