{"id":28496,"date":"2014-05-05T18:35:51","date_gmt":"2014-05-05T16:35:51","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=28496"},"modified":"2014-05-05T18:40:28","modified_gmt":"2014-05-05T16:40:28","slug":"aikido-lecce-stage-del-maestro-hiroshi-tada-a-roma","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/05\/05\/aikido-lecce-stage-del-maestro-hiroshi-tada-a-roma\/","title":{"rendered":"AIKIDO LECCE: STAGE DEL MAESTRO HIROSHI TADA A ROMA"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/tada-roma.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/tada-roma.jpg\" alt=\"\" title=\"tada roma\" width=\"1376\" height=\"800\" class=\"alignleft size-full wp-image-28499\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/tada-roma.jpg 1376w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/tada-roma-300x174.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/tada-roma-1024x595.jpg 1024w\" sizes=\"(max-width: 1376px) 100vw, 1376px\" \/><\/a>Si \u00e8 svolto lo stage \u00a0che il Maestro Hiroshi Tada 9 dan Direttore didattico dell&#8217;Aikikai d&#8217;Italia, ormai da tantissimi anni tiene a Roma.<\/p>\n<p>Anche da Lecce alcuni praticanti al seguito del Maestro Valerio Melcore responsabile del Dojo &#8220;Aikido Il Cavaliere&#8221;, hanno partecipato alle tre giorni.<br \/>\nCome sempre le lezioni sono ad un livello elevatissimo, il Maestro Tada, ancora una volta, oltre a mostrare come vanno eseguite correttamente i movimenti e le tecniche di base, si \u00e8 soffermato sul significato di Ki ossia di energia, di come aumentarla e di come correttamente utilizzarla.<br \/>\nEsercizi di concentrazione e di respirazione sono stati eseguiti prima di ogni lezione, poi tecniche a mani nude, con bastone ( jo ) e con la spada di legno ( bokken ) che i praticanti di aikido utilizzano nei loro allenamenti.<br \/>\nQuanti sono interessati a conoscere ed eventualmente a praticare l&#8217;Ai Ki Do, ossia la Via dell&#8217;Armonia dello Spirito, possono farlo recandosi in via Puccini a Lecce presso la Palestra Athlon, il luned\u00ec, mercoled\u00ec, e il \u00a0venerdi alle 19,00 tel. 329 2509093.<\/p>\n<p>La domenica quando il tempo lo permette gli allievi del Dojo&#8221;Aikido Il Cavaliere&#8221; si allenano con le armi nella pineta delle Cesine.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/05\/05\/aikido-lecce-stage-del-maestro-hiroshi-tada-a-roma\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/05\/05\/aikido-lecce-stage-del-maestro-hiroshi-tada-a-roma\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Si \u00e8 svolto lo stage \u00a0che il Maestro Hiroshi Tada 9 dan Direttore didattico dell&#8217;Aikikai d&#8217;Italia, ormai da tantissimi anni tiene a Roma. Anche da Lecce alcuni praticanti al seguito del Maestro Valerio Melcore responsabile del Dojo &#8220;Aikido Il Cavaliere&#8221;, hanno partecipato alle tre giorni. Come sempre le lezioni sono ad un livello elevatissimo, il [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":28499,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/28496"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=28496"}],"version-history":[{"count":6,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/28496\/revisions"}],"predecessor-version":[{"id":28596,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/28496\/revisions\/28596"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/28499"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=28496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=28496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=28496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}