{"id":28556,"date":"2014-05-05T17:20:08","date_gmt":"2014-05-05T15:20:08","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=28556"},"modified":"2014-05-05T17:20:08","modified_gmt":"2014-05-05T15:20:08","slug":"partenope-svicat-24-32","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/05\/05\/partenope-svicat-24-32\/","title":{"rendered":"Partenope-Svicat 24-32"},"content":{"rendered":"<div id=\"mainLayout\" dir=\"ltr\">\n<div id=\"mainPane\" dir=\"ltr\">\n<div id=\"mainContainer\" dir=\"ltr\">\n<div>\n<div id=\"mainContent\" title=\"Desktop\" dir=\"ltr\">\n<div id=\"xandmail_widget_layout_LayoutContainer_0\" dir=\"ltr\">\n<div id=\"xandmail_widget_layout_ContentPane_1\" title=\"\" dir=\"ltr\">\n<div id=\"mailSplitCnt\" dir=\"ltr\">\n<div id=\"mailPreview\" title=\"\" dir=\"ltr\">\n<div id=\"preview12269\">\n<div id=\"preview12269_pane\" dir=\"ltr\">\n<div id=\"xandmail_widget_layout_SplitContainer_12\" dir=\"ltr\">\n<div id=\"xandmail_widget_layout_ContentPane_35\" title=\"\" dir=\"ltr\">\n<div id=\"msgText_preview12269\" dir=\"ltr\"><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/partenope.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/partenope.jpg\" alt=\"\" title=\"partenope\" width=\"1024\" height=\"680\" class=\"alignleft size-full wp-image-28557\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/partenope.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/partenope-300x199.jpg 300w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>La Svicat vince a Napoli e chiude il campionato con 62 punti. Partono bene gli evergreen che, dopo pochi minuti, vanno in meta con capitan Paolo D&#8217;Oria; Spagnoli non sbaglia dalla piazzola e salentini in vantaggio per 7-0. I campani reagiscono e, poco dopo, centrano i tre punti con Reyna. La Svicat si riversa nella met\u00e0 campo biancoblu ma \u00e8 ancora Reyna a trovare i tre punt isu calcio piazzato. Gli ospiti reagiscono e trovano la seconda meta di giornata con Mirko Corbascio; anche questa volta Spagnoli non sbaglia e Svicat avanti per 14-6. Passano cinque minuti e Spagnoli trova i tre punti su punizione. Poco prima della fine del primo tempo, poi, \u00e8 ancora Reyna a trovare i tre punti da calcio piazzato e fischio dell&#8217;arbitro che manda le due squadre al riposo sul 17-9.<\/p>\n<p>La ripresa si apre con la Partenope che trova sei punti da piazzato grazie Reyna: i campani quindi si portano sul 17-15. Il tempo di riprendere il gioco e Micheal Stubbs trova la terza meta di giornata portando i suoi sul 22-15; Spagnoli, implacabile dalla piazzola, porta poigli evergreen sul 24-15. La Partenope accorcia le distanze, ancora su piazzato di Reyna, e si porta sul 24-18. Passano cinque minuti e De Gioia trova la quarta meta di giornata, poi non trasformata da Spagnoli e punteggio quindi fermo sul 29-18. La partenope prova a realizzare la prima meta di giornata ma trova solo sei punti su due piazzati del solito Reyna, mentre la Svicat trova ancora i tre punti con Spagnoli e match che quindi si conclude sul 32-24. La Svicat chiude quindi la sua prima esperienza in Serie B con una vittoria in terra campana.<br \/>\n&#8212;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"qsearchTooltip\" dir=\"ltr\"><\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/05\/05\/partenope-svicat-24-32\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/05\/05\/partenope-svicat-24-32\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>La Svicat vince a Napoli e chiude il campionato con 62 punti. Partono bene gli evergreen che, dopo pochi minuti, vanno in meta con capitan Paolo D&#8217;Oria; Spagnoli non sbaglia dalla piazzola e salentini in vantaggio per 7-0. I campani reagiscono e, poco dopo, centrano i tre punti con Reyna. La Svicat si riversa nella [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":28557,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/28556"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=28556"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/28556\/revisions"}],"predecessor-version":[{"id":28558,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/28556\/revisions\/28558"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/28557"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=28556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=28556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=28556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}