{"id":28798,"date":"2014-05-10T10:22:50","date_gmt":"2014-05-10T08:22:50","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=28798"},"modified":"2014-05-10T10:27:32","modified_gmt":"2014-05-10T08:27:32","slug":"lecce-sparatoria-a-san-ligorio","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/05\/10\/lecce-sparatoria-a-san-ligorio\/","title":{"rendered":"LECCE: SPARATORIA A SAN LIGORIO"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/sparatoria.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/sparatoria.jpg\" alt=\"\" title=\"sparatoria\" width=\"800\" height=\"534\" class=\"alignleft size-full wp-image-28799\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/sparatoria.jpg 800w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/sparatoria-300x200.jpg 300w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>Un cinquantenne leccese, massimo Caroppo \u00e8 stato colpito da tre proiettili di cui uno alla testa.<br \/>\nL&#8217;uomo si \u00e8 trascinato presso un&#8217;abitazione chiedendo aiuto alla donna che gli ha aperto la porta.<br \/>\nE&#8217; stato trasportato immediatamente presso l&#8217;ospedale Vito Fazzi di Lecce, le condizioni in cui versa pare siano gravi.<br \/>\nI medici del reparto al momento si sono astenuti dal fare commenti circa le condizioni del ricoverato.<br \/>\nIl Caroppo, insieme ai suoi fratelli sono noti alle forze dell&#8217;ordine, gi\u00e0 inquisito insieme ad uno dei fratelli poco tempo fa per il reato di usura.<br \/>\nRicordiamo che uno dei fratelli fu ucciso nel periodo in cui nel Salento la Sacra Corona Unita dettava legge.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/05\/10\/lecce-sparatoria-a-san-ligorio\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/05\/10\/lecce-sparatoria-a-san-ligorio\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Un cinquantenne leccese, massimo Caroppo \u00e8 stato colpito da tre proiettili di cui uno alla testa. L&#8217;uomo si \u00e8 trascinato presso un&#8217;abitazione chiedendo aiuto alla donna che gli ha aperto la porta. E&#8217; stato trasportato immediatamente presso l&#8217;ospedale Vito Fazzi di Lecce, le condizioni in cui versa pare siano gravi. I medici del reparto al [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":28799,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/28798"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=28798"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/28798\/revisions"}],"predecessor-version":[{"id":28801,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/28798\/revisions\/28801"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/28799"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=28798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=28798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=28798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}