{"id":2902,"date":"2012-07-17T16:30:05","date_gmt":"2012-07-17T16:30:05","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=2902"},"modified":"2012-07-17T16:30:34","modified_gmt":"2012-07-17T16:30:34","slug":"dal-18-luglio-riparte-il-filobus","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2012\/07\/17\/dal-18-luglio-riparte-il-filobus\/","title":{"rendered":"DAL 18 LUGLIO RIPARTE IL FILOBUS"},"content":{"rendered":"<p style=\"text-align: left;\" align=\"center\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/06\/08\/stop-temporaneo-al-filobus-sostituiti-da-autobus\/filobus-011\/\" rel=\"attachment wp-att-1802\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/06\/Filobus-011-300x199.jpg\" alt=\"\" title=\"Filobus 011\" width=\"300\" height=\"199\" class=\"alignnone size-medium wp-image-1802\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/06\/Filobus-011-300x199.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/06\/Filobus-011.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>L\u2019Ustif (Ufficio speciale trasporti e<em> <\/em>impianti fissi) di Bari ha revocato questa mattina, con il provvedimento n.1668, la sospensione dell\u2019esercizio filoviario disposta lo scorso 7 giugno a causa della prematura scomparsa del direttore d\u2019esercizio Pasquale Borelli,\u00a0 sostituito nei giorni scorsi dall\u2019ingegner Silvano Cavaliere. In conseguenza di ci\u00f2, a <strong>partire da mercoled\u00ec 18 luglio, sar\u00e0 riattivata<\/strong> &#8211; con modalit\u00e0 filoviaria &#8211; <strong>la linea urbana contrassegnata con il n. 29<\/strong> (Stazione ferroviaria-Centro-Porta Napoli).<\/p>\n<p style=\"text-align: left;\">\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2012\/07\/17\/dal-18-luglio-riparte-il-filobus\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/07\/17\/dal-18-luglio-riparte-il-filobus\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>L\u2019Ustif (Ufficio speciale trasporti e impianti fissi) di Bari ha revocato questa mattina, con il provvedimento n.1668, la sospensione dell\u2019esercizio filoviario disposta lo scorso 7 giugno a causa della prematura scomparsa del direttore d\u2019esercizio Pasquale Borelli,\u00a0 sostituito nei giorni scorsi dall\u2019ingegner Silvano Cavaliere. In conseguenza di ci\u00f2, a partire da mercoled\u00ec 18 luglio, sar\u00e0 riattivata [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1802,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/2902"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=2902"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/2902\/revisions"}],"predecessor-version":[{"id":2906,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/2902\/revisions\/2906"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/1802"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=2902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=2902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=2902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}