{"id":29578,"date":"2014-05-22T15:32:17","date_gmt":"2014-05-22T13:32:17","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=29578"},"modified":"2014-05-22T15:32:17","modified_gmt":"2014-05-22T13:32:17","slug":"supersano-scoperta-autocarrozzeria-abusiva","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/05\/22\/supersano-scoperta-autocarrozzeria-abusiva\/","title":{"rendered":"SUPERSANO: SCOPERTA  AUTOCARROZZERIA ABUSIVA"},"content":{"rendered":"<p style=\"text-align: left;\" align=\"center\"><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/Foto-2014_05_22.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/Foto-2014_05_22.jpg\" alt=\"\" title=\"Foto 2014_05_22\" width=\"1000\" height=\"750\" class=\"alignleft size-full wp-image-29579\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/Foto-2014_05_22.jpg 1000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/Foto-2014_05_22-300x225.jpg 300w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a>SENZA NESSUNA AUTORIZZAZIONE IN UN CAPANNONE DI 350 MQ ESERCITAVA ABUSIVAMENTE L\u2019ATTIVITA\u2019 DI CARROZZIERE.<\/p>\n<p style=\"text-align: left;\">\u00a0I Finanzieri di Casarano, hanno scoperto, nella Zona Industriale di Supersano, un\u2019autocarrozzeria in cui veniva esercitata, in forma totalmente abusiva, l\u2019attivit\u00e0 di \u201ccarrozziere\u201d.<br \/>\nNel corso dell\u2019intervento sono state rinvenute all\u2019interno del locale, di circa 350 mq, adibito ad officina con tanto di attrezzatura e cabina\/forno per verniciatura, alcune autovetture in riparazione ed altre in attesa di essere ritirate dai rispettivi proprietari.<\/p>\n<p>\u00a0In assenza delle prescritte autorizzazioni amministrative per l\u2019esercizio dell\u2019attivit\u00e0 di carrozziere da parte del soggetto ispezionato, un uomo di 46 anni del posto, i militari hanno sottoposto a sequestro amministrativo tutta l\u2019attrezzatura utilizzata dallo stesso contestandogli, tra l\u2019altro, specifiche violazioni che prevedono l\u2019irrogazione di una sanzione pecuniaria da Euro 2.582,00 ad Euro 15.493,00.<br \/>\nE\u2019 stata inoltre avviata apposita attivit\u00e0 ispettiva, al fine di individuare i clienti ed i fornitori dell\u2019autoriparatore abusivo per assoggettare ad imposizione fiscale tutti i ricavi dallo stesso conseguiti e non dichiarati nei vari anni.<\/p>\n<p>L\u2019attivit\u00e0 di servizio descritta si inquadra nell\u2019ambito dei servizi di polizia economica e finanziaria e di una serie di controlli a tappeto nell\u2019ambito del territorio di competenza, disposti al fine di contrastare il cosiddetto fenomeno del \u201ccaro-vita\u201d, nonch\u00e9 verificare la regolare emissione di scontrini e ricevute fiscali e il possesso delle prescritte licenze commerciali.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/05\/22\/supersano-scoperta-autocarrozzeria-abusiva\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/05\/22\/supersano-scoperta-autocarrozzeria-abusiva\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>SENZA NESSUNA AUTORIZZAZIONE IN UN CAPANNONE DI 350 MQ ESERCITAVA ABUSIVAMENTE L\u2019ATTIVITA\u2019 DI CARROZZIERE. \u00a0I Finanzieri di Casarano, hanno scoperto, nella Zona Industriale di Supersano, un\u2019autocarrozzeria in cui veniva esercitata, in forma totalmente abusiva, l\u2019attivit\u00e0 di \u201ccarrozziere\u201d. Nel corso dell\u2019intervento sono state rinvenute all\u2019interno del locale, di circa 350 mq, adibito ad officina con tanto [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":29579,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/29578"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=29578"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/29578\/revisions"}],"predecessor-version":[{"id":29580,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/29578\/revisions\/29580"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/29579"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=29578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=29578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=29578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}