{"id":29591,"date":"2014-05-23T10:28:54","date_gmt":"2014-05-23T08:28:54","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=29591"},"modified":"2014-05-23T10:28:54","modified_gmt":"2014-05-23T08:28:54","slug":"un-invito-ad-incontrare-lesbiche-gay-bisessuali-e-transgender","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/05\/23\/un-invito-ad-incontrare-lesbiche-gay-bisessuali-e-transgender\/","title":{"rendered":"Un invito ad incontrare lesbiche, gay, bisessuali, e transgender."},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/gay.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/gay.jpg\" alt=\"\" title=\"gay\" width=\"532\" height=\"335\" class=\"alignleft size-full wp-image-29593\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/gay.jpg 532w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/gay-300x188.jpg 300w\" sizes=\"(max-width: 532px) 100vw, 532px\" \/><\/a>L\u2019associazione di volontariato LeA- Liberamente e Apertamente dal 23 al 25 maggio 2014 presso le Officine Culturali Ergot di Lecce presenta, in collaborazione con il CSV Salento, \u201cLa Gaya Comics\u201d, workshop di fumetto LGBTQ.<\/p>\n<p>L\u2019iniziativa mira a sensibilizzare sui temi inerenti la comunit\u00e0 LGBTQ e in particolare approfondire le relazioni umane attraverso riflessioni e confronti sociali, volti a una maggiore inclusione delle diverse realt\u00e0 e culture, dato che la diversit\u00e0 non \u00e8 sinonimo di pericolo, bens\u00ec di arricchimento.<\/p>\n<p>La partecipazione al workshop \u00e9 completamente gratuita.<\/p>\n<p>Per info e prenotazioni:<\/p>\n<p>Tel.: 324\/0906528<\/p>\n<p>e-mail: lea.lgbtq@libero.it<\/p>\n<p>&nbsp;<\/p>\n<p>Ecco il programma delle tre giornate:<\/p>\n<p>&nbsp;<\/p>\n<p>23 maggio<\/p>\n<p>ore 17.00-19.00<\/p>\n<p>Incontro di riflessione e sensibilizzazione sulla necessit\u00e0 di prevenire e di combattere fenomeni di omofobia -cio\u00e8 stereotipi, pregiudizi, violenza e discriminazione- e di informazione sull\u2019attuale situazione delle persone omosessuali e sui diritti negati. L&#8217;incontro prevede gli interventi dei rappresentanti delle associazioni LeA-Liberamente e Apertamente, Differente Mente e Agedo Lecce.<\/p>\n<p>&nbsp;<\/p>\n<p>24 maggio<\/p>\n<p>ore 9.00-13.00 \/ 14.00-20.00<\/p>\n<p>Workshop con il fumettista ed illustratore Giulio Macaione. Il programma prevede una piccola introduzione sul fumetto come linguaggio del quotidiano, per poi passare all\u2019argomento omosessualit\u00e0 e identit\u00e0 di genere nei fumetti. Si passer\u00e0 poi a realizzare un elaborato, con la guida di Giulio Macaione. I lavori realizzati durante il workshop saranno successivamente esposti presso la libreria Ergot ed utilizzati dall\u2019associazione LeA- Liberamente e Apertamente come materiale divulgativo e di sensibilizzazione.<\/p>\n<p>Giulio Macaione nasce a Catania nel 1983 e cresce a Palermo. Trasferitosi a Bologna e diplomatosi in Pittura, \u00e8 tra i fondatori del collettivo artistico The Dummies. Debutta nel fumetto nel 2005 con il corto &#8220;Mort\u00e9n&#8221; (vincitore del concorso &#8220;Otto tavole per mondo Naif&#8221;) sulla rivista Mondo Naif edita da Kappa Edizioni; sempre con Kappa pubblica i graphic novel &#8220;The Fag Hag&#8221; (2008) e &#8220;Innamorarsi a Milano&#8221; (2010), entrambi su testi di Massimiliano De Giovanni. Con Comma 22 pubblica &#8220;Ofelia&#8221; (2013), graphic novel del quale firma testi e disegni. Ha pubblicato da poco per Renbooks il suo nuovo lavoro \u201cI colori del vicino\u201d, incentrato su due dei personaggi pi\u00f9 amati di &#8220;Ofelia&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>25 maggio &#8211; 18-20<\/p>\n<p>Approfondimento a cura di Simone Rollo (Officine Culturali Ergot) sulla distribuzione di nuovi fumetti.<\/p>\n<p>A conclusione della giornata aperitivo di saluto.<\/p>\n<p>&nbsp;<\/p>\n<p>Partner dell&#8217;iniziativa &#8220;La Gaya Comics&#8221;:<\/p>\n<p>CSV Salento<\/p>\n<p>Officine Culturali Ergot<\/p>\n<p>Agedo Lecce<\/p>\n<p>Associazione Differente Mente<\/p>\n<p>Lecce2019 Capitale della Cultura<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/05\/23\/un-invito-ad-incontrare-lesbiche-gay-bisessuali-e-transgender\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/05\/23\/un-invito-ad-incontrare-lesbiche-gay-bisessuali-e-transgender\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>L\u2019associazione di volontariato LeA- Liberamente e Apertamente dal 23 al 25 maggio 2014 presso le Officine Culturali Ergot di Lecce presenta, in collaborazione con il CSV Salento, \u201cLa Gaya Comics\u201d, workshop di fumetto LGBTQ. L\u2019iniziativa mira a sensibilizzare sui temi inerenti la comunit\u00e0 LGBTQ e in particolare approfondire le relazioni umane attraverso riflessioni e confronti [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":29593,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/29591"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=29591"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/29591\/revisions"}],"predecessor-version":[{"id":29594,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/29591\/revisions\/29594"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/29593"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=29591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=29591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=29591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}