{"id":29653,"date":"2014-05-25T09:59:53","date_gmt":"2014-05-25T07:59:53","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=29653"},"modified":"2014-05-25T09:59:53","modified_gmt":"2014-05-25T07:59:53","slug":"il-rally-del-salento-si-prepara-ad-aprire-i-battenti","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/05\/25\/il-rally-del-salento-si-prepara-ad-aprire-i-battenti\/","title":{"rendered":"IL RALLY DEL SALENTO SI PREPARA AD APRIRE I BATTENTI"},"content":{"rendered":"<p style=\"text-align: left;\" align=\"center\"><strong><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/141.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/141.jpg\" alt=\"\" title=\"14\" width=\"1024\" height=\"682\" class=\"alignleft size-full wp-image-29654\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/141.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/141-300x199.jpg 300w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>PRESENTATA L\u2019EDIZIONE 2014. ANCHE QUEST\u2019ANNO ATTESI MOLTI PILOTI DI PRIMO PIANO. LE ISCRIZIONI PROROGATE FINO A LUNED\u00cc 26 MAGGIO.<\/strong><\/p>\n<p style=\"text-align: left;\">\n<p>\u00c8 stata presentata nella tarda mattinata odierna nella Sala Consiliare del Comune di Maglie la quarantasettesima edizione del Rally del Salento, manifestazione in programma per il prossimo fine settimana lungo le strade della provincia leccese e valida quale terza delle sei prove di cui si compone il nuovo Campionato Italiano WRC. A fare gli onori di casa il Sindaco della Citt\u00e0 di Maglie Antonio Fitto che\u00a0 ha rinnovato la fiducia della Citt\u00e0 verso l\u2019evento sportivo ponendo l\u2019accento sul trade-union tra sport-territorio ed economia: \u201cUna manifestazione che riesce ad attrarre tantissimi sportivi, che\u00a0 tutta la provincia segue con tanto entusiasmo e che d\u00e0 la possibilit\u00e0 di porsi al centro dell\u2019attenzione mediatica nazionale non pu\u00f2 non avere il sostegno che merita -ha esordito il primo cittadino\u2013 mi auguro che intorno a questo evento ci sia il giusto interesse anche da parte di altre istituzioni perch\u00e9 il Rally del Salento pu\u00f2 rappresentare un futuro di grande crescita e di grande prospettiva se lo si guarda dal punto di vista della destagionalizzazione turistica. Allungare la stagione facendola partire a maggio con i flussi che un evento come questo generano d\u00e0 un impulso notevole all\u2019economia della zona. Tutti lo dicono -ha concluso il Sindaco- ma parlare di destagionalizzazione senza poi dare gli strumenti a chi si attiva per allungarla \u00e8 un assurdo controsenso\u201d.<\/p>\n<p>Il Presidente dell\u2019Automobile Club Lecce Aurelio Filippi Filippi si \u00e8\u00a0 soffermato sui motivi che hanno spinto l\u2019ente leccese a riproporre in calendario la manifestazione \u201cNonostante la situazione economica generale non sia delle migliori dobbiamo sempre cercare di essere propositivi dandoci degli obiettivi\u00a0 che contribuiscano a creare dei segnali di ripresa. La scelta di ripresentare il Rally del Salento nasce prima di tutto da qui e poi dalla sinergia \u00a0che abbiamo riscontrato e apprezzato nel proporre la manifestazione all\u2019Amministrazione Comunale di Maglie che ha dato prova di notevole interesse nei confronti di ci\u00f2 che \u00e8 attrattiva e che contribuisce a migliorare la qualit\u00e0 della vita di tutti\u201d.<\/p>\n<p>Pasquale Elia Direttore dell\u2019Automobile Club di Lecce ha invece sottolineato come per l\u2019ente fare sport significa anche impegnarsi sul fronte della Sicurezza Stradale, \u201cStimolare la passione per la corsa e per la velocit\u00e0\u00a0 e parlare di sicurezza stradale sembra apparentemente un controsenso ma in realt\u00e0 non lo \u00e8 perch\u00e9 il messaggio che vogliamo lanciare \u00e8 correre s\u00ec ma in sicurezza. Sulle nostre strade, intese come rally, si corre ma con il rispetto delle regole e con tutto quello che \u00e8 poi alla base di un\u2019 organizzazione di un rally dove la cura minuziosa della sicurezza \u00e8 fondamentale\u201d.<\/p>\n<p>Anche l\u2019Assessore ai Lavori Pubblici e Urbanistica della Citt\u00e0 di Maglie Franca Giannotti ha parlato di una grandissima opportunit\u00e0 di promozione per la citt\u00e0 e per l\u2019intero territorio: \u201cCi sono eventi che oltre a offrire una grande opportunit\u00e0 di fare sport\u00a0 sono un aiuto per il territorio\u201d.<\/p>\n<p>Nel corso del suo intervento invece Leonardo Panico Presidente del Comitato Organizzatore ha riassunto tutto il lavoro che sta a monte con la complessit\u00e0 organizzativa che ne consegue per poter offrire una gara con i migliori standard di sicurezza. Panico ha poi parlato del fascino e delle bellezze del territorio che spinge molti piloti a tornare in provincia di Lecce per trascorrere le vacanze e dell\u2019andamento delle iscrizioni\u00a0 che sta comunque lanciando segnali positivi. A tal proposito la giornata di ieri avrebbe dovuto segnare la chiusura delle iscrizioni ma a seguito della richiesta di proroga giunta con esito positivo sar\u00e0 ancora possibile inviare le domande di adesione entro luned\u00ec prossimo 26 maggio. Nel Salento sono attesi molti dei migliori interpreti del campionato Wrc, un\u2019armata forte e ben assortita che metter\u00e0 a dura prova le forze in campo.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/05\/25\/il-rally-del-salento-si-prepara-ad-aprire-i-battenti\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/05\/25\/il-rally-del-salento-si-prepara-ad-aprire-i-battenti\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>PRESENTATA L\u2019EDIZIONE 2014. ANCHE QUEST\u2019ANNO ATTESI MOLTI PILOTI DI PRIMO PIANO. LE ISCRIZIONI PROROGATE FINO A LUNED\u00cc 26 MAGGIO. \u00c8 stata presentata nella tarda mattinata odierna nella Sala Consiliare del Comune di Maglie la quarantasettesima edizione del Rally del Salento, manifestazione in programma per il prossimo fine settimana lungo le strade della provincia leccese e [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":29654,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/29653"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=29653"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/29653\/revisions"}],"predecessor-version":[{"id":29655,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/29653\/revisions\/29655"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/29654"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=29653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=29653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=29653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}